{"id":981003,"date":"2023-10-21T17:37:56","date_gmt":"2023-10-21T19:37:56","guid":{"rendered":"https:\/\/teknomers.com\/fr\/chez-maxxi-on-assiste-a-un-boom-des-actrices-realisatrices-cortellesi-jecris-des-scenarios-depuis-10-ans-maintenant-je-veux-tout-faire-moi-meme\/"},"modified":"2023-10-21T17:37:59","modified_gmt":"2023-10-21T19:37:59","slug":"chez-maxxi-on-assiste-a-un-boom-des-actrices-realisatrices-cortellesi-jecris-des-scenarios-depuis-10-ans-maintenant-je-veux-tout-faire-moi-meme","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/chez-maxxi-on-assiste-a-un-boom-des-actrices-realisatrices-cortellesi-jecris-des-scenarios-depuis-10-ans-maintenant-je-veux-tout-faire-moi-meme\/","title":{"rendered":"Chez Maxxi, on assiste \u00e0 un boom des actrices-r\u00e9alisatrices.  Cortellesi, j&#8217;\u00e9cris des sc\u00e9narios depuis 10 ans, maintenant je veux tout faire moi-m\u00eame"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>\u00c9coutez la version audio de l&#8217;article<\/button><\/p>\n<p class=\"atext\">Mettez sur sc\u00e8ne six r\u00e9alisatrices &#8211; Paola Cortellesi, Ginevra Elkann, Valeria Golino, Kasja Smutniak, Valeria Brtuni Tedeschi, Jasmine Trinca -, dont cinq sont \u00e9galement des actrices \u00e0 succ\u00e8s, et le d\u00e9bat s&#8217;enflamme.  Pourquoi les acteurs ont toujours \u00e9t\u00e9 aussi r\u00e9alisateurs, mais pour certains, il semble surprenant que des femmes se lancent \u00e9galement derri\u00e8re la cam\u00e9ra.  Les r\u00f4les au cin\u00e9ma ont \u00e9t\u00e9 abord\u00e9s lors du troisi\u00e8me &#8220;Dialogue sur l&#8217;avenir du cin\u00e9ma&#8221;, organis\u00e9 par la Fondazione cinema per Roma avec Anica, anim\u00e9 au Maxxi par Piera Detassis.<\/p>\n<p><h2 id=\"U5010755502597oG\">Trinca : Je voulais exp\u00e9rimenter la libert\u00e9 d&#8217;\u00eatre de l&#8217;autre c\u00f4t\u00e9<\/h2>\n<\/p>\n<p class=\"atext\">\u00abJe voulais exp\u00e9rimenter la libert\u00e9 &#8211; dit-il <b>Jasmin Trinca<\/b>protagoniste de la s\u00e9rie sur <i>Histoire<\/i> d&#8217;Elsa Morante, pr\u00e9sent\u00e9 au Festival de Rome &#8211; pour rester de l&#8217;autre c\u00f4t\u00e9.  Tourner mon regard, avoir mon regard personnel, pas celui des r\u00e9alisateurs avec qui j&#8217;ai travaill\u00e9, parfois avec bonheur, d&#8217;autres fois moins.&#8221;  \u00abDepuis dix ans, j&#8217;\u00e9cris des sc\u00e9narios que je remets ensuite au r\u00e9alisateur.  Je me suis dit : je veux tout faire moi-m\u00eame&#8221;, souligne-t-il <b>Paola Cortellesi<\/b>au Festival du Film de Rome avec <i>Il y a encore demain<\/i>.<\/p>\n<p><h2 id=\"U501075550259IwF\">Smutniak: Mur est un acte militant<\/h2>\n<\/p>\n<p class=\"atext\"><b>Kasja Smutniak<\/b>qu&#8217;il a tir\u00e9 <i>Mur<\/i>, un documentaire sur la fronti\u00e8re entre la Pologne, qui est son pays d&#8217;origine, et la Bi\u00e9lorussie : \u00ab Mur est presque un acte militant.  Mon intention est de raconter des histoires de mon point de vue. \u00bb<\/p>\n<div class=\"aembed\">\n<div class=\"aembed-head\">\n<figure class=\"aimg aentry--full\"><figcaption class=\"acaption aentry--normal\">Smutniak : nous vivons \u00e0 l&#8217;\u00e8re des murs mais la Pologne s&#8217;est r\u00e9veill\u00e9e<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<p><h2 id=\"U5010755502590RC\">Bruni Tedeschi : passer d&#8217;acteur \u00e0 r\u00e9alisateur, c&#8217;est comme grandir comme un enfant<\/h2>\n<\/p>\n<p class=\"atext\">ET <b>V<\/b> <b>Al\u00e9ria Bruni Tedeschi, <\/b>acteur dans le film <b>Gen\u00e8ve Elkann<i\/> <\/b> <i>Je te l&#8217;ai dit<\/i>: \u00abPasser d&#8217;acteur \u00e0 r\u00e9alisateur, c&#8217;est comme devenir adulte \u00e0 partir d&#8217;un enfant.  Il y a d\u2019abord des gens qui prennent soin de vous, puis vous prenez soin des autres. \u00bb<\/p>\n<div class=\"acor acor--mkt\">\n<div class=\"row row--dotted\">\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/www.whatsapp.com\/channel\/0029VaB2FDj5PO11MRejNA3C\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><\/figure>\n<p><\/a><\/div>\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/tariffe.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/10\/Marelli-suspend-indefiniment-la-fermeture-de-lusine-de-Crevalcore.png\" alt=\"En savoir plus\"\/><\/figure>\n<p><\/a><\/div>\n<\/div>\n<\/div>\n<p><h2 id=\"U501075550259zvB\">Cortellesi : Cela m&#8217;\u00e9tonne que si nous devenons r\u00e9alisateurs, nous faisons toujours l&#8217;actualit\u00e9<\/h2>\n<\/p>\n<p class=\"atext\">Le d\u00e9bat a \u00e9galement pris une autre direction. <b>Paola Cortellesi<\/b>: \u00abCe qui m&#8217;\u00e9tonne, c&#8217;est que si on devient r\u00e9alisateur, on fait encore l&#8217;actualit\u00e9\u00bb. <b>Smutniak<\/b>: \u00abJe suis offens\u00e9 par mon \u00e9tonnement devant les r\u00e9alisatrices\u00bb. <b>Bruni Tedeschi :<\/b> \u00abJe ne me sens pas comme une femme qui fait des films.  Ou une actrice qui fait des films.  Si j&#8217;avais su que c&#8217;\u00e9tait le sujet, je ne serais pas venu.&#8221;<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/al-maxxi-e-boom-attrici-registe-cortellesi-10-anni-scrivevo-sceneggiatura-ora-voglio-fare-tutto-io-AFzu3wKB\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9coutez la version audio de l&#8217;article Mettez sur sc\u00e8ne six r\u00e9alisatrices &#8211; Paola Cortellesi, Ginevra Elkann, Valeria Golino, Kasja Smutniak, Valeria Brtuni Tedeschi, Jasmine Trinca -, dont cinq sont \u00e9galement des actrices \u00e0 succ\u00e8s, et le d\u00e9bat s&#8217;enflamme. Pourquoi les acteurs ont toujours \u00e9t\u00e9 aussi r\u00e9alisateurs, mais pour certains, il semble surprenant que des femmes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":981004,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[210428,277,8546,18944,895,156622,377,133,365,109561,617,19418,987,14227,2767,9722],"class_list":["post-981003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-actricesrealisatrices","tag-ans","tag-assiste","tag-boom","tag-chez","tag-cortellesi","tag-depuis","tag-des","tag-faire","tag-jecris","tag-maintenant","tag-maxxi","tag-moimeme","tag-scenarios","tag-tout","tag-veux"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/981003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=981003"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/981003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/981004"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=981003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=981003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=981003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}