{"id":960232,"date":"2023-10-08T03:08:39","date_gmt":"2023-10-08T05:08:39","guid":{"rendered":"https:\/\/teknomers.com\/fr\/le-remede-contre-le-charlatanisme-en-ligne-na-pas-encore-ete-trouve\/"},"modified":"2023-10-08T03:08:43","modified_gmt":"2023-10-08T05:08:43","slug":"le-remede-contre-le-charlatanisme-en-ligne-na-pas-encore-ete-trouve","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/le-remede-contre-le-charlatanisme-en-ligne-na-pas-encore-ete-trouve\/","title":{"rendered":"Le rem\u00e8de contre le charlatanisme en ligne n\u2019a pas encore \u00e9t\u00e9 trouv\u00e9"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>&#8220;Anke ne l&#8217;a ni mang\u00e9e ni bu depuis quatre ans <a rel=\"nofollow noopener\" href=\"https:\/\/www.linda.nl\/nieuws\/anke-ryanne-van-dorst-prana-urnine-het-alternatief\/\" target=\"_blank\">propre urine<\/a>: &#8216;Le soleil est ma source de nourriture&#8217;.<\/p>\n<p>\u00ab Eline, acupunctrice et massoth\u00e9rapeute : \u00ab Je soul\u00e8ve gr\u00e2ce aux ventouses de feu \u00bb <a rel=\"nofollow noopener\" href=\"https:\/\/www.linda.nl\/lifestyle\/gezondheid\/alles-over-cuppen\/\" target=\"_blank\">stagnations et douleurs<\/a> sur&#8217;.&#8221;<\/p>\n<p>Juste deux titres d&#8217;articles sur Linda.nl, le site Internet du magazine du m\u00eame nom.  Pour l&#8217;Association contre le charlatanisme (<a rel=\"nofollow noopener\" href=\"https:\/\/www.kwakzalverij.nl\/\" target=\"_blank\">VtdK<\/a>) des articles comme celui-ci ont motiv\u00e9 la remise ce samedi au magazine du prix annuel Master Kackadoris.<\/p>\n<p>Extrait du rapport du jury : \u00ab Linda de Mol est (\u2026) une ic\u00f4ne cr\u00e9dible pour des millions de femmes.  Cependant, elle n\u00e9glige grossi\u00e8rement sa responsabilit\u00e9 de prot\u00e9ger son public contre des tromperies co\u00fbteuses et inutiles.<\/p>\n<p>L&#8217;association, active depuis 1881, est de moins en moins seule dans sa lutte.  C&#8217;est ainsi que le journaliste scientifique Adriaan ter Braack a connu sa perc\u00e9e d\u00e9finitive l&#8217;ann\u00e9e derni\u00e8re.  Sur Instagram, il a rassembl\u00e9 plus de 46 000 abonn\u00e9s sous le nom de \u00ab Sjamadriaan \u00bb en s&#8217;adressant publiquement aux influenceurs et aux c\u00e9l\u00e9brit\u00e9s qui font de telles all\u00e9gations m\u00e9dicales. <\/p>\n<p>Tous deux y entrent r\u00e9guli\u00e8rement les jambes tendues.  Le VtdK le fait, par exemple, avec un prix destin\u00e9 \u00e0 susciter la honte chez le destinataire.  Et \u00ab Shamadrian \u00bb avec un flot de m\u00e8mes, de disqualifications et de mal\u00e9dictions.  \u00c0 propos du Biohack Project, par exemple, un programme KRO-NCRV dans lequel un groupe de N\u00e9erlandais connus apprennent \u00e0 optimiser les performances du corps et de l&#8217;esprit gr\u00e2ce \u00e0 des devoirs.  La plaisanterie de Ter Braack aux cr\u00e9ateurs a en partie veill\u00e9 \u00e0 ce que le programme comprenne d\u00e9sormais une clause de non-responsabilit\u00e9.  &#8220;C&#8217;est une blessure b\u00e9ante d&#8217;o\u00f9 jaillit continuellement de la d\u00e9sinformation&#8221;, a fulmin\u00e9 Ter Braack dans l&#8217;\u00e9mission t\u00e9l\u00e9vis\u00e9e. <em>Temp\u00eate m\u00e9diatique<\/em>.  Le VVD a d\u00e9clar\u00e9 <a rel=\"nofollow noopener\" href=\"https:\/\/www.openkamer.org\/kamervraag\/2023Z15559\/\" target=\"_blank\">Questions parlementaires<\/a> sur le programme.  \u00ab La d\u00e9sinformation m\u00e9dicale est ainsi normalis\u00e9e \u00e0 la t\u00e9l\u00e9vision nationale.<\/p>\n<p>Mais quel est exactement le pr\u00e9judice caus\u00e9 par des all\u00e9gations m\u00e9dicales non prouv\u00e9es\u00a0?  Le principe \u00ab si \u00e7a n&#8217;aide pas, \u00e7a ne fait pas de mal \u00bb ne s&#8217;applique-t-il pas ici ?  Sur une terrasse \u00e0 Amsterdam-Ouest, Ter Braack est visiblement enthousiasm\u00e9 par cette suggestion.  \u00ab Quand je vois que le taux de vaccination \u00e0 Amsterdam a baiss\u00e9 au cours de l\u2019ann\u00e9e \u00e9coul\u00e9e, je me dis : cela pourrait-il avoir quelque chose \u00e0 voir avec les influenceurs qui font campagne contre cela ?  Et quand je vois que les cancers de la peau se multiplient, alors que les influenceurs mettent massivement en garde contre les cr\u00e8mes solaires, \u00e7a me rend furieux. <\/p>\n<p>De plus, comme il le montre \u00e9galement dans ses blogs, on gagne beaucoup d\u2019argent avec des traitements non \u00e9prouv\u00e9s.  Mais qu\u2019est-ce qui le d\u00e9range le plus ?  \u00ab Les faux espoirs que vous donnez aux gens. \u00bb  Lorsque la maladie de son p\u00e8re est entr\u00e9e en phase terminale, il a \u00e9galement cherch\u00e9 refuge dans des th\u00e9rapies non \u00e9prouv\u00e9es.  &#8220;Alors qu&#8217;\u00e0 un tel moment, quelqu&#8217;un profite bien plus de l&#8217;acceptation.&#8221;<\/p>\n<p>En tant que r\u00e9dacteur en chef d&#8217;un magazine scientifique populaire <em>Qu\u00eate<\/em> il y a eu un conflit entre Ter Braack et son r\u00e9dacteur en chef, qui, \u00e0 son avis, s&#8217;est trop impliqu\u00e9 dans la pseudoscience.  La collision a provoqu\u00e9 une fracture. <\/p>\n<p>Depuis, Ter Braack, aujourd&#8217;hui journaliste ind\u00e9pendant, est un homme charg\u00e9 d&#8217;une mission.  Sur les r\u00e9seaux sociaux, il se pr\u00e9sente comme un \u00ab boulet de d\u00e9molition holistique \u00bb qui d\u00e9fend de toutes ses forces la science contre les \u00ab absurdit\u00e9s \u00bb.  Il se pr\u00e9sente pr\u00e9cis\u00e9ment l\u00e0 o\u00f9 l&#8217;information m\u00e9dicale pullule <a rel=\"nofollow\" href=\"www.sjamadriaan.nl\">un contre-r\u00e9cit<\/a> appartenir.<\/p>\n<p>  &#8220;Tu n&#8217;es pas oblig\u00e9 d&#8217;\u00eatre une garce&#8221;, a-t-il par exemple \u00e9crit cette semaine<a rel=\"nofollow noopener\" href=\"https:\/\/www.instagram.com\/p\/Cx5q_Reodx6\/\" target=\"_blank\"> un message vid\u00e9o<\/a> \u00e0 propos d&#8217;un influenceur qui affirmait qu&#8217;en \u00ab manifestant \u00bb, il n&#8217;\u00e9tait plus n\u00e9cessaire d&#8217;\u00eatre sans enfant et en mauvaise sant\u00e9.  La publication a g\u00e9n\u00e9r\u00e9 plus de 5 000 likes.  <\/p>\n<p>Ne rate-t-il pas son but avec de telles insultes ?  &#8220;Oui, &#8216;connard&#8217;, peut-\u00eatre que je n&#8217;aurais pas d\u00fb dire \u00e7a.  Mais je ne suis absolument pas un connecteur.  Je ne suis pas une bonne personne dans ce r\u00f4le.  Et je veux aussi traiter les gens sur les r\u00e9seaux sociaux comme des adultes.  Vous pouvez \u00e9galement faire d\u2019autres choix que de culpabiliser les gens \u00e0 propos de leur propre sant\u00e9 ou de leur absence d\u2019enfant.<\/p>\n<p>Humour et contenu vont de pair dans toutes ses expressions, dit-il.  Pourtant, il indique qu\u2019il se pose parfois la question de savoir quelle est la strat\u00e9gie la plus efficace.  \u00ab Je re\u00e7ois beaucoup de messages de gens qui me remercient.  Ils disent que mes messages les ont rendus plus critiques.  Mais bien s\u00fbr, vous ne savez pas si mon approche renforcera r\u00e9ellement les convictions des autres.\u00bb  Il voit que lorsque quelqu\u2019un vous traite de charlatan ou de charlatan, cela peut en fait augmenter votre cr\u00e9dibilit\u00e9 aupr\u00e8s de vos abonn\u00e9s.  &#8220;Comme : vous voyez, ce message ne devrait pas \u00eatre rendu public.&#8221;<\/p>\n<picture class=\"lees-ook__image\"><source  type=\"image\/webp\"\/><\/picture>\n<span class=\"lees-ook__content\"><\/p>\n<p>\t\tA lire aussi : <strong>Prix \u200b\u200bdu charlatanisme pour LINDA brillante.<\/strong><br \/>\n<\/span><\/p>\n<h2 class=\"gn4-crosshead\">Les partisans de la ligne dure<\/h2>\n<p>Il existe deux mouvements au sein de l&#8217;Association contre le charlatanisme, explique le rhumatologue et \u00e9pid\u00e9miologiste Alfons den Broeder.  Ce samedi, il sera l&#8217;un des intervenants du colloque o\u00f9 sera d\u00e9cern\u00e9 le Prix Master Kackadoris.  \u00ab Nous avons un groupe, le <em>les extr\u00e9mistes<\/em>, qui estiment qu&#8217;il faut condamner le charlatanisme le plus clairement possible.  J\u2019appartiens moi-m\u00eame au groupe qui adopte une approche plus indulgente.  Je crois que chacun est avant tout libre, m\u00eame de croire \u00e0 des b\u00eatises.  On serait peut-\u00eatre plus favorable \u00e0 l&#8217;Association <em>m\u00e9decine factuelle <\/em>peut \u00eatre.  Car oui, ridiculiser cela peut \u00eatre contre-productif.  Peut-\u00eatre que quelqu&#8217;un comme Freek Vonk (biologiste de la t\u00e9l\u00e9vision, ndlr), qui excite et informe les gens, travaillera mieux.\u00bb<\/p>\n<p>Quelle strat\u00e9gie de communication fonctionne, laquelle ne fonctionne clairement pas et laquelle peut \u00eatre contre-productive\u00a0?  Il n\u2019y a pas de consensus sur ce point, selon une tourn\u00e9e de sp\u00e9cialistes de la communication et du comportement.  Ionica Smeets, professeur de communication scientifique \u00e0 Leiden, montre souvent aux scientifiques dans leurs pr\u00e9sentations que l&#8217;on peut informer un public sceptique avec la science, mais qu&#8217;on ne peut pas les convaincre.  \u00ab Il s\u2019agit de syst\u00e8mes de croyance profond\u00e9ment enracin\u00e9s chez les gens. \u00bb  Ce qui est dr\u00f4le, dit-elle en riant, c\u2019est que \u00ab beaucoup de scientifiques n\u2019arrivent pas \u00e0 croire quand je leur dis \u00e7a \u00bb. <\/p>\n<p>Bastiaan Rutjens m\u00e8ne des recherches en psychologie scientifique avec un groupe de coll\u00e8gues de l&#8217;Universit\u00e9 d&#8217;Amsterdam.  \u00ab Au d\u00e9but de ce si\u00e8cle, tout le monde en parlait <em>d\u00e9ficits d\u2019information. <\/em>\u00c0 l\u2019\u00e9poque, le consensus \u00e9tait que les scientifiques devaient surmonter le manque d\u2019informations et que les gens seraient alors convaincus des faits.  Presque personne n\u2019y croit plus. <\/p>\n<p>Selon lui, c&#8217;est le groupe cible qui d\u00e9termine en fin de compte quelle m\u00e9thode est la meilleure \u00e0 utiliser.  &#8220;Vous ne convaincrez pas votre voisin avec \u00e7a<em> appellation<\/em> et <em>honte<\/em> ou avec <em>discr\u00e9diter<\/em>mais dans le d\u00e9bat public sur le charlatanisme, vous pouvez \u00eatre un peu plus cat\u00e9gorique \u00e0 ce sujet.<\/p>\n<p>Le sp\u00e9cialiste en communication de Nim\u00e8gue, Aart van Stekelenburg, souhaite nuancer l&#8217;image selon laquelle les faits sont sans d\u00e9fense face aux croyances.  M\u00eame si une telle strat\u00e9gie de communication est une affaire \u00e0 long terme.  &#8220;Nos recherches montrent que si vous montrez \u00e0 un public sur une longue p\u00e9riode quel est le consensus scientifique, par exemple sur le climat ou les vaccinations, \u00e0 un moment donn\u00e9, les destinataires de l&#8217;information s&#8217;orienteront effectivement dans la direction de ce consensus.&#8221; <\/p>\n<h2 class=\"gn4-crosshead\">Fabricabilit\u00e9<\/h2>\n<p>\u00abLa gentillesse aide et il faut \u00e9viter d&#8217;\u00eatre arrogant\u00bb, explique Den Broeder, membre du VtdK et m\u00e9decin, qui rencontre r\u00e9guli\u00e8rement dans son cabinet des personnes qui ont entendu parler d&#8217;un diagnostic ou d&#8217;un traitement \u00abquelque part sur Internet\u00bb.  &#8220;La clart\u00e9 aide aussi.&#8221;  Il montre souvent \u00e0 des patients critiques des m\u00e9ta-\u00e9tudes qui apportent un \u00e9clairage diff\u00e9rent sur la question.  &#8220;Parfois \u00e7a aide, parfois non.&#8221; <\/p>\n<p>La science m\u00e9dicale, dit-il \u00e9galement, est souvent un moyen d\u2019occuper un patient pendant que la nature fait son travail.  &#8220;Cela s&#8217;applique aussi bien aux m\u00e9thodes r\u00e9guli\u00e8res qu&#8217;aux m\u00e9thodes alternatives.&#8221; <\/p>\n<p>Il existe \u00e9galement beaucoup d\u2019incertitudes quant \u00e0 l\u2019efficacit\u00e9 des soins r\u00e9guliers.  Les conditions les plus importantes en mati\u00e8re de sant\u00e9 \u2013 assainissement, alimentation propre, vaccination des enfants \u2013 sont remplies depuis longtemps aux Pays-Bas, dit-il.  &#8220;La science m\u00e9dicale ne fait qu&#8217;ajouter une ann\u00e9e et demie suppl\u00e9mentaire \u00e0 la vie.&#8221;<\/p>\n<p>Mais les gens ne l\u2019acceptent plus de nos jours, dit-il.  \u00ab Vous naissez, vous aimez, vous mourez.  C&#8217;est \u00e7a.  Mais en attendant, nous en attendons beaucoup plus.\u00bb  Selon lui, cela cr\u00e9e une demande de charlatanisme.  Mais il faut aussi relativiser cela, dit-il.  \u00ab Au XVIe si\u00e8cle, le m\u00e9decin insufflait simplement de la fum\u00e9e dans l&#8217;anus si l&#8217;on souffrait d&#8217;essoufflement.  Le charlatanisme \u00e9tait encore pire \u00e0 l\u2019\u00e9poque.<\/p>\n<p>\u00ab Sjamadriaan \u00bb ter Braack gagne d\u00e9sormais environ 700 euros par mois gr\u00e2ce \u00e0 la partie payante de son blog et vit \u00e9galement de ses travaux d&#8217;\u00e9criture.  \u00ab Je pourrais gagner beaucoup plus avec mon nombre de followers si, par exemple, j&#8217;acceptais des sponsors.  Mais je pr\u00e9f\u00e8re rester ind\u00e9pendant.  Et bien, insister sur des choses que tout le monde conna\u00eet d\u00e9j\u00e0, comme manger sainement, boire moins et arr\u00eater de fumer, n\u2019est pas un mod\u00e8le de revenus, n\u2019est-ce pas ?<\/p>\n<aside>\n<p><strong>Il y a eu aussi un d\u00e9bat \u00e0 la fin du XVIe si\u00e8cle <\/strong>sur la qualit\u00e9 et l&#8217;ad\u00e9quation de certaines interventions m\u00e9dicales.  Les rh\u00e9teurs de l&#8217;\u00e9poque donnaient r\u00e9guli\u00e8rement des conf\u00e9rences et des pi\u00e8ces de th\u00e9\u00e2tre sur des sujets d&#8217;actualit\u00e9.  Il se moquait de types qui auraient suscit\u00e9 la reconnaissance parmi les contemporains.<\/p>\n<p><strong>Dans <\/strong><strong><em>Un jeu de table de Ma\u00eetre Kackadoris, et une femme sourde avec des yeux<\/em><\/strong>  il critique un m\u00e9decin qui rend visite \u00e0 un groupe d&#8217;agriculteurs avec un stand rempli d&#8217;herbes et de pommades pour les tromper.  Il se vante m\u00eame de sa tricherie.<\/p>\n<p><strong>L&#8217;Association contre le charlatanisme travaille depuis 21 ans<\/strong> d\u00e9cerne chaque ann\u00e9e le prix Master Kackadoris.  Jamais \u00e0 un charlatan lui-m\u00eame, ou \u2013 selon un terme utilis\u00e9 par le m\u00e9decin et membre du VtdK Alfons den Broeder \u2013 \u00e0 un \u00ab charlatan \u00bb, mais \u00e0 une personne ou une institution qui pourrait ou devrait en savoir plus.<\/p>\n<p><strong>Linda, la prochaine gagnante du prix, \u00e9tait cette ann\u00e9e <\/strong>y compris le site Web <em>Kanker.nl <\/em>(en raison des \u00ab \u00e9loges non critiques \u00bb pour le traitement d&#8217;acupuncture) et la diffusion <em>KRONCRV<\/em> (en raison de l&#8217;attribution d&#8217;un prix \u00e0 un institut B12).<\/p>\n<p>Parmi les laur\u00e9ats pr\u00e9c\u00e9dents figurent Halbe Zijlstra et Jacobine Geel. <\/p>\n<\/aside>\n<div class=\"article__published-in\">\n<p>\t\tUne version de cet article est \u00e9galement parue dans le journal du 7 octobre 2023.\n\t<\/p><\/div>\n<\/p><\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.nrc.nl\/nieuws\/2023\/10\/07\/het-medicijn-tegen-online-kwakzalverij-is-nog-niet-gevonden-a4176437\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-33<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Anke ne l&#8217;a ni mang\u00e9e ni bu depuis quatre ans propre urine: &#8216;Le soleil est ma source de nourriture&#8217;. \u00ab Eline, acupunctrice et massoth\u00e9rapeute : \u00ab Je soul\u00e8ve gr\u00e2ce aux ventouses de feu \u00bb stagnations et douleurs sur&#8217;.&#8221; Juste deux titres d&#8217;articles sur Linda.nl, le site Internet du magazine du m\u00eame nom. Pour l&#8217;Association contre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":960233,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[169005,841,844,162,2903,132,4037,1677],"class_list":["post-960232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-charlatanisme","tag-contre","tag-encore","tag-ete","tag-ligne","tag-pas","tag-remede","tag-trouve"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/960232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=960232"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/960232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/960233"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=960232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=960232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=960232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}