{"id":830426,"date":"2023-07-14T13:59:46","date_gmt":"2023-07-14T15:59:46","guid":{"rendered":"https:\/\/teknomers.com\/fr\/ecole-contrat-signe-les-augmentations-pour-les-enseignants-selevent-a-124-euros\/"},"modified":"2023-07-14T13:59:50","modified_gmt":"2023-07-14T15:59:50","slug":"ecole-contrat-signe-les-augmentations-pour-les-enseignants-selevent-a-124-euros","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/ecole-contrat-signe-les-augmentations-pour-les-enseignants-selevent-a-124-euros\/","title":{"rendered":"\u00c9cole, contrat sign\u00e9 : les augmentations pour les enseignants s&#8217;\u00e9l\u00e8vent \u00e0 124 euros"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>\u00c9couter la version audio de l&#8217;article<\/button><\/p>\n<p class=\"atext\">Apr\u00e8s des jours de n\u00e9gociations serr\u00e9es, Aran et les organisations syndicales sont parvenues \u00e0 un accord sur la Convention Collective Nationale de Travail 2019-2021 qui concerne un total de 1 232 248 salari\u00e9s, dont 1 154 993 appartiennent aux secteurs scolaire et AFAM (dont 850 000 enseignants), et 77 255 travailleurs. dans les universit\u00e9s et les instituts de recherche (hors professeurs).  Le contrat vient compl\u00e9ter la s\u00e9quence contractuelle pour les secteurs de l&#8217;Enseignement et de la Recherche entam\u00e9e avec l&#8217;accord \u00e9conomique sign\u00e9 en d\u00e9cembre 2022.<\/p>\n<p><h2 id=\"U5058318756vIB\">Les augmentations <\/h2>\n<\/p>\n<p class=\"atext\">Gr\u00e2ce aux moyens allou\u00e9s par le gouvernement et finalis\u00e9s par Aran, le contrat pr\u00e9voit des augmentations salariales mensuelles moyennes de 124,40 euros pour les enseignants, 96,72 pour le personnel ATA et 197,50 pour les directeurs administratifs (DSGA).  Pour les autres secteurs \u00e9galement, des augmentations importantes ont \u00e9t\u00e9 mises en \u0153uvre.  Une autre nouveaut\u00e9 importante, \u00e9tendue \u00e0 tous les secteurs, est l&#8217;introduction et la r\u00e9glementation du travail intelligent \u00e9galement pour ce secteur.<\/p>\n<p><h2 id=\"U5058318756bkG\">Les autres nouvelles<\/h2>\n<\/p>\n<p class=\"atext\">Au cours des n\u00e9gociations, les dispositions relatives au personnel scolaire, au personnel administratif des universit\u00e9s et des acad\u00e9mies et conservatoires ont \u00e9t\u00e9 revues, tandis qu&#8217;un accord compl\u00e9mentaire est pr\u00e9vu pour le personnel des \u00e9tablissements de recherche. En particulier, pour les \u00e9tablissements de recherche, l&#8217;accord pr\u00e9voit une n\u00e9gociation ult\u00e9rieure pour le d\u00e9finition du syst\u00e8me professionnel et de r\u00e9soudre la question des ressources suppl\u00e9mentaires pour les \u00e9tablissements de recherche non tutelle du minist\u00e8re de l&#8217;Universit\u00e9 et de la Recherche (Mur).<\/p>\n<div class=\"acor acor--mkt\">\n<div class=\"row row--dotted\">\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/consigli24.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><\/figure>\n<p><\/a><\/div>\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/tariffe.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/05\/Les-avions-greve-aujourdhui-pendant-4-heures-Ita-annule-47.png\" alt=\"En savoir plus\"\/><\/figure>\n<p><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/scuola-firmato-contratto-aumenti-i-docenti-salgono-124-euro-AFGXr6D\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9couter la version audio de l&#8217;article Apr\u00e8s des jours de n\u00e9gociations serr\u00e9es, Aran et les organisations syndicales sont parvenues \u00e0 un accord sur la Convention Collective Nationale de Travail 2019-2021 qui concerne un total de 1 232 248 salari\u00e9s, dont 1 154 993 appartiennent aux secteurs scolaire et AFAM (dont 850 000 enseignants), et 77 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":830427,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[6661,873,8847,22516,3334,65,185,5362,872],"class_list":["post-830426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-augmentations","tag-contrat","tag-ecole","tag-enseignants","tag-euros","tag-les","tag-pour","tag-selevent","tag-signe"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/830426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=830426"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/830426\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/830427"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=830426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=830426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=830426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}