{"id":828659,"date":"2023-07-13T12:29:48","date_gmt":"2023-07-13T14:29:48","guid":{"rendered":"https:\/\/teknomers.com\/fr\/beatrice-rana-la-pianiste-italienne-la-plus-connue-au-monde-nous-invite-tous-a-classiche-forme-le-festival-quelle-a-cree-dans-le-salento-et-qui-se-deroule-du-17-au-23-juillet-avec-une-promesse\/"},"modified":"2023-07-13T12:29:51","modified_gmt":"2023-07-13T14:29:51","slug":"beatrice-rana-la-pianiste-italienne-la-plus-connue-au-monde-nous-invite-tous-a-classiche-forme-le-festival-quelle-a-cree-dans-le-salento-et-qui-se-deroule-du-17-au-23-juillet-avec-une-promesse","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/beatrice-rana-la-pianiste-italienne-la-plus-connue-au-monde-nous-invite-tous-a-classiche-forme-le-festival-quelle-a-cree-dans-le-salento-et-qui-se-deroule-du-17-au-23-juillet-avec-une-promesse\/","title":{"rendered":"Beatrice Rana, la pianiste italienne la plus connue au monde, nous invite tous \u00e0 &#8220;Classiche Forme&#8221;, le festival qu&#8217;elle a cr\u00e9\u00e9 dans le Salento et qui se d\u00e9roule du 17 au 23 juillet.  Avec une promesse : \u00ab Vous serez les protagonistes \u00bb"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><strong><span class=\"first-letter\">POUR<\/span> qui est inspir\u00e9 <a rel=\"nofollow noopener\" href=\"https:\/\/www.beatriceranapiano.com\" target=\"_blank\" data-wpel-link=\"external\">B\u00e9atrice Rana<\/a>?<\/strong> \u00ab<a rel=\"nofollow noopener\" href=\"https:\/\/www.anne-sophie-mutter.de\/en\/\" target=\"_blank\" data-wpel-link=\"external\">Anne-Sophie Mutter<\/a>. <a rel=\"nofollow noopener\" href=\"https:\/\/www.ceciliabartoli.com\/projects\/#cecilia-bartoli-music-foundation\" target=\"_blank\" data-wpel-link=\"external\">C\u00e9cile Bartoli<\/a>. <a rel=\"nofollow noopener\" href=\"https:\/\/it.wikipedia.org\/wiki\/Martha_Argerich\" target=\"_blank\" data-wpel-link=\"external\">Marthe Argerich<\/a>.  Car, au-del\u00e0 de l&#8217;incroyable talent, ils ont r\u00e9alis\u00e9 des choses importantes dans le monde musical avec leurs fondations, leurs projets, fa\u00e7onnant la r\u00e9alit\u00e9 culturelle d&#8217;une mani\u00e8re diff\u00e9rente.  En le changeant \u00bb explique le pianiste italien le plus demand\u00e9 \u00e0 l&#8217;\u00e9tranger.  Pas par hasard, <strong>c&#8217;est le but qu&#8217;elle se fixe <a rel=\"nofollow noopener\" href=\"https:\/\/www.classicheforme.com\/2023\/\" target=\"_blank\" data-wpel-link=\"external\">Formes classiques<\/a>le &#8220;Festival international et r\u00e9pandu de musique de chambre dans l&#8217;art et la nature du Salento&#8221;, qu&#8217;il a fond\u00e9 en 2017 et qui s&#8217;ouvre le 17 juillet. <\/strong>Parmi les rendez-vous, des concerts de Stephen Waarts, Mario Brunello, Giovanni Sollima, Marmen String Quartet, Emmanuel Pahud, Tim Crawford, Tim Posner, Rosa Feola.  Encore des hommages \u00e0 Rachmaninov 150 ans apr\u00e8s sa naissance et \u00e0 Francis Poulenc 60 ans apr\u00e8s sa mort.<\/p>\n<h2>Une trentaine d&#8217;action<\/h2>\n<div id=\"attachment_2165429\" data-thumbnail_id=\"2165429\" class=\"wp-caption aligncenter\" style=\"width:693px\"><picture class=\"lozad\"><source  type=\"image\/webp\"><source  type=\"image\/jpeg\"\/><\/source><\/picture>\n<p class=\"wp-caption-text\">B\u00e9atrice Rana (photo Simon Fowler).<\/p>\n<\/div>\n<p>\u00abJe viens de Lecce, une ville merveilleuse mais toujours une p\u00e9riph\u00e9rie culturelle, loin de tout m\u00eame g\u00e9ographiquement.  Je voulais enrichir ma terre \u00bb ajoute-t-il. <strong>N\u00e9e dans une famille de pianistes, B\u00e9atrice commence \u00e0 jouer \u00e0 l&#8217;\u00e2ge de 3 ans, entre au Conservatoire \u00e0 8 ans, donne son premier r\u00e9cital \u00e0 9 ans, s&#8217;impose \u00e0 18 ans en remportant le Concours international de piano de Montr\u00e9al.<\/strong> (et \u00e0 partir de l\u00e0, il est impossible d&#8217;\u00e9num\u00e9rer tous les succ\u00e8s\u00a0: il suffit de mentionner <strong>son 30e anniversaire, en janvier, c\u00e9l\u00e9br\u00e9 en jouant \u00e0 <a rel=\"nofollow noopener\" href=\"https:\/\/www.filarmonica.it\/eventi\/stagione-2023-milano-teatro-alla-scala-dir-shani-23-gennaio\" target=\"_blank\" data-wpel-link=\"external\">Th\u00e9\u00e2tre de la Scala<\/a><\/strong>), c&#8217;est pourtant le contraire de l&#8217;artiste qui vit dans la tour d&#8217;ivoire.<\/p>\n<article class=\"id-vda-article box_ed_hp_02-article eltdf-item-space hentry-pos-i hentry-home_section-i post-iiiii post type-post status-publish format-standard hentry\">\n<\/article>\n<h2>Jouer sans public<\/h2>\n<p><span style=\"font-size: 15px;\">\u00ab L&#8217;image de l&#8217;artiste au loin, sur l&#8217;ermitage, a peut-\u00eatre un peu disparu. <strong>Et, en tout cas, je pense qu&#8217;en tant que musiciens on peut faire beaucoup &#8220;pour&#8221; et &#8220;avec&#8221; le public.  Regarder plus les mod\u00e8les \u00e9trangers que les mod\u00e8les italiens<\/strong>i, j&#8217;ai essay\u00e9 de cr\u00e9er une relation interactive avec les spectateurs : ils ne doivent pas se sentir comme une composante passive de l&#8217;organisation.  Leur r\u00f4le est fondamental et, si ce n&#8217;\u00e9tait pas assez clair, nous l&#8217;avons tr\u00e8s bien compris pendant la pand\u00e9mie.  Pour moi, c&#8217;\u00e9tait tr\u00e8s difficile de jouer sans public\u00bb.<\/span><\/p>\n<h2>La sc\u00e8ne a \u00e9t\u00e9 supprim\u00e9e<\/h2>\n<div id=\"attachment_2165937\" data-thumbnail_id=\"2165937\" class=\"wp-caption aligncenter\" style=\"width:693px\"><picture class=\"lozad\"><source  type=\"image\/webp\"><source  type=\"image\/jpeg\"\/><\/source><\/picture>\n<p class=\"wp-caption-text\">B\u00e9atrice Rana (photo Simon Fowler).<\/p>\n<\/div>\n<p><strong>Comment facilitez-vous cette interrelation, concr\u00e8tement ?<\/strong> \u00ab Avec la suppression de la sc\u00e8ne standard (tout le monde au m\u00eame niveau) et la cr\u00e9ation de situations informelles : en plein air, dans les champs, au milieu des oliviers.  Parfois, il y a une touche d&#8217;arrogance chez les fans du classique, alors quoi <strong>en 2022 je me suis livr\u00e9 \u00e0 une exp\u00e9rience tr\u00e8s communiste<\/strong> <em>(des rires)<\/em>: J&#8217;ai eu un concert dont je n&#8217;ai pas annonc\u00e9 le programme.  Ne sachant pas ce qu&#8217;ils allaient \u00e9couter, aucun expert n&#8217;avait de certitudes absolues sur le moment d&#8217;applaudir, comme les n\u00e9ophytes : comme il y a toujours un peu d&#8217;angoisse de \u00ab performance sociale \u00bb, je mets tout le monde pr\u00e9sent dans la m\u00eame condition \u00bb.<\/p>\n<p>R\u00e9sultat?  &#8220;Ils ont applaudi, guid\u00e9s uniquement par le principe du plaisir, comme il se doit.&#8221; <strong>Et les jeunes, qui trouvent souvent Bach ou Beethoven trop distants, \u00ab moisis \u00bb ?  \u00ab Les jeunes sont toujours sous-estim\u00e9s.<\/strong> La chose que j&#8217;ai apprise dans ces premi\u00e8res ann\u00e9es de vie de concert, c&#8217;est que le public n&#8217;est pas stupide et qu&#8217;il faut lui faire confiance.  Nous n&#8217;avons pas \u00e0 demander, nous devons donner et ensuite nous recevons en retour.  Exiger le silence dans la pi\u00e8ce est une erreur : vous obtenez le silence, vous ne vous y attendez pas.  Malheureusement pas beaucoup sont d&#8217;accord avec moi <em>(Rit \u00e0 haute voix)<\/em>\u00bb.<\/p>\n<h2>Place aux jeunes<\/h2>\n<div id=\"attachment_2166014\" data-thumbnail_id=\"2166014\" class=\"wp-caption aligncenter\" style=\"width:685px\"><picture class=\"lozad\"><source  type=\"image\/webp\"><source  type=\"image\/jpeg\"\/><\/source><\/picture>\n<p class=\"wp-caption-text\">Beatrice Rana applaudie en 2013 apr\u00e8s sa prestation au Van Cliburn International Piano Competition au Texas (Getty Images).<\/p>\n<\/div>\n<p>\u00ab Dans les grands centres il y a beaucoup d&#8217;offre et il y a d\u00e9j\u00e0 un public.  L\u00e0 o\u00f9 il n&#8217;y en a pas, il faut le construire en instaurant une relation de confiance.  Dans le cas des nouvelles g\u00e9n\u00e9rations, d&#8217;autant plus qu&#8217;en Italie il y a un manque d&#8217;\u00e9ducation musicale dans les \u00e9coles : on ne peut pas juger un gar\u00e7on qui n&#8217;a jamais eu acc\u00e8s aux outils de la connaissance, le gronder au moindre faux geste comme les bigots font&#8230; Ce n&#8217;est pas leur faute s&#8217;ils ne savent pas : il s&#8217;agit de les encourager, d&#8217;ouvrir les portes, de leur faire comprendre qu&#8217;il n&#8217;y a pas d&#8217;odeur de naphtaline.  En effet, c&#8217;est un monde dans lequel ils peuvent \u00e9voluer tr\u00e8s facilement. <strong>je suis content de <a rel=\"nofollow noopener\" href=\"https:\/\/www.classicheforme.com\/2023\/\" target=\"_blank\" data-wpel-link=\"external\">Formes classiques <em>(ici le programme en d\u00e9tail)<\/em><\/a>  parce qu&#8217;il attire des publics vari\u00e9s.  Et l&#8217;\u00e2ge moyen des artistes est extr\u00eamement bas<\/strong>, il y a un facteur de reconnaissabilit\u00e9, d&#8217;identification.  Puis nous avons lanc\u00e9 l&#8217;appel \u00e0 volontaires, tous des enfants : ils se sentent partie prenante \u00bb.<\/p>\n<h2>Clara Schumann d&#8217;apr\u00e8s B\u00e9atrice Rana<\/h2>\n<p><strong>Son dernier album (enregistr\u00e9 avec l&#8217;Orchestre de Chambre d&#8217;Europe et le chef Yannick N\u00e9zet-S\u00e9guin) s&#8217;intitule <a rel=\"nofollow noopener\" href=\"https:\/\/www.beatriceranapiano.com\" target=\"_blank\" data-wpel-link=\"external\"><em>Clara et Robert Schumann, Concertos pour piano<\/em><\/a>.<\/strong> Pourquoi ce choix ?  \u00abIl s&#8217;agissait de montrer combien Robert avait pris \u00e0 sa femme, et non l&#8217;inverse.  Les deux sont des concertos en la mineur mais Robert l&#8217;a \u00e9crit 10 ans plus tard.  je ne veux pas faire le <em>passionn\u00e9<\/em> (la musique pour moi est bonne ou mauvaise, elle n&#8217;a pas de genres), cependant <strong><a rel=\"nofollow noopener\" href=\"https:\/\/it.wikipedia.org\/wiki\/Clara_Schumann\" target=\"_blank\" data-wpel-link=\"external\">Claire<\/a> m\u00e9rite un hommage : c&#8217;est un fou, on peut dire qu&#8217;il a \u00ab invent\u00e9 \u00bb mon m\u00e9tier.<\/strong> Elle a \u00e9t\u00e9 la premi\u00e8re femme \u00e0 tourner en tant que concertiste, et malgr\u00e9 ses huit enfants : cela semble absurde en 2023, encore moins au 19\u00e8me si\u00e8cle !  Et lorsqu&#8217;elle est devenue veuve &#8211; \u00e0 un peu plus de 30 ans et de mani\u00e8re traumatisante (son mari s&#8217;est suicid\u00e9) &#8211; elle a poursuivi sa carri\u00e8re, devenant l&#8217;\u00e9g\u00e9rie de Johannes Brahms.  Elle \u00e9tait forte, visionnaire, brillante : elle a \u00e9crit ce concert r\u00e9volutionnaire \u00e0 l&#8217;\u00e2ge de 14 ans, une petite fille.  Elle seule pouvait se limiter, et malheureusement elle l&#8217;a fait : apr\u00e8s son mariage, elle a arr\u00eat\u00e9 de composer\u00bb.<\/p>\n<h2>\u00c9tape d&#8217;\u00e9mancipation<\/h2>\n<div id=\"attachment_2166031\" data-thumbnail_id=\"2166031\" class=\"wp-caption aligncenter\" style=\"width:1034px\"><picture class=\"lozad\"><source  type=\"image\/webp\"><source  type=\"image\/jpeg\"\/><\/source><\/picture>\n<p class=\"wp-caption-text\">B\u00e9atrice Rana (photo Simon Fowler).<\/p>\n<\/div>\n<p><strong>En deux si\u00e8cles, qu&#8217;est-ce qui a chang\u00e9 pour les femmes musiciennes, et pour les femmes pianistes en particulier ?<\/strong> \u00ab La situation s&#8217;est nettement am\u00e9lior\u00e9e : nous ne sommes pas nombreux, mais toujours nombreux.  Il y a eu une \u00e9tape fondamentale pour l&#8217;\u00e9mancipation : d\u00e8s mon plus jeune \u00e2ge j&#8217;ai grandi avec la conviction que je pouvais m&#8217;imaginer dans ce m\u00e9tier.  Pour moi, Argerich \u00e9tait un mod\u00e8le de pianiste en g\u00e9n\u00e9ral (elle sonne comme Dieu !), et de femme pianiste en particulier : il y a maintenant des points de r\u00e9f\u00e9rence.  Dans le cas des compositrices, le chemin \u00e0 parcourir est plus long : il y en a de bons, il y en a beaucoup, mais c&#8217;est un fait que<strong> 95% de la musique classique jou\u00e9e est masculine<\/strong>.  Une discrimination non actuelle, mais le r\u00e9sultat de si\u00e8cles de discrimination culturelle&#8221;.<\/p>\n<p class=\"all-rights-reserved\">iO Femme \u00a9 REPRODUCTION R\u00c9SERV\u00c9E<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iodonna.it\/personaggi\/star-italiane\/2023\/07\/13\/beatrice-rana-venite-al-mio-festival-in-salento-dove-il-pubblico-e-protagonista\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-13<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>POUR qui est inspir\u00e9 B\u00e9atrice Rana? \u00abAnne-Sophie Mutter. C\u00e9cile Bartoli. Marthe Argerich. Car, au-del\u00e0 de l&#8217;incroyable talent, ils ont r\u00e9alis\u00e9 des choses importantes dans le monde musical avec leurs fondations, leurs projets, fa\u00e7onnant la r\u00e9alit\u00e9 culturelle d&#8217;une mani\u00e8re diff\u00e9rente. En le changeant \u00bb explique le pianiste italien le plus demand\u00e9 \u00e0 l&#8217;\u00e9tranger. Pas par hasard, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":828660,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[84,30804,173702,6750,15068,429,5605,1097,3680,6004,3484,203,65,1056,1266,38161,9800,17207,372,364,54055,58581,4690,378,196,188],"class_list":["post-828659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-avec","tag-beatrice","tag-classiche","tag-connue","tag-cree","tag-dans","tag-deroule","tag-festival","tag-forme","tag-invite","tag-italienne","tag-juillet","tag-les","tag-monde","tag-nous","tag-pianiste","tag-promesse","tag-protagonistes","tag-quelle","tag-qui","tag-rana","tag-salento","tag-serez","tag-tous","tag-une","tag-vous"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/828659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=828659"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/828659\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/828660"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=828659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=828659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=828659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}