{"id":787722,"date":"2023-06-17T04:42:53","date_gmt":"2023-06-17T06:42:53","guid":{"rendered":"https:\/\/teknomers.com\/fr\/forza-italia-tajani-vers-la-regence-ligne-directe-entre-marina-et-le-vice-premier-ministre\/"},"modified":"2023-06-17T04:42:56","modified_gmt":"2023-06-17T06:42:56","slug":"forza-italia-tajani-vers-la-regence-ligne-directe-entre-marina-et-le-vice-premier-ministre","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/forza-italia-tajani-vers-la-regence-ligne-directe-entre-marina-et-le-vice-premier-ministre\/","title":{"rendered":"Forza Italia, Tajani vers la r\u00e9gence.  Ligne directe entre Marina et le vice-premier ministre"},"content":{"rendered":"\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>\u00c9couter la version audio de l&#8217;article<\/button><\/p>\n<p class=\"atext\">La nouvelle \u00e8re de Forza Italia sans le chevalier est n\u00e9e.  Et pour prendre le relais, c&#8217;est Antonio Tajani.  Officiellement, le vice-premier ministre est le num\u00e9ro deux du parti.  Mais en attendant le processus pour choisir qui conduira les Azzurri au Congr\u00e8s le 22 juin, il est le trait d&#8217;union avec la famille Cavaliere, c&#8217;est-\u00e0-dire avec ceux qui, plus que tout autre jusqu&#8217;\u00e0 pr\u00e9sent, peuvent garantir l&#8217;existence dans FI vie.  Ce n&#8217;est pas un hasard si Marina Berlusconi appelle Tajani, pour remercier toute la f\u00eate pour l&#8217;affection et la proximit\u00e9 manifest\u00e9es et &#8220;en respectant les r\u00f4les&#8221;.  C&#8217;est lui-m\u00eame qui le raconte, car il est \u00ab autoris\u00e9 \u00bb par la fille a\u00een\u00e9e \u00e0 le dire publiquement, souligne-t-il \u00e0 plusieurs reprises.<\/p>\n<p><h2 id=\"U403263596679mXB\">R\u00f4le isol\u00e9 pour Fascina<\/h2>\n<\/p>\n<p class=\"atext\">En substance, la famille ne quitte pas les amarres de la cr\u00e9ature politique du p\u00e8re &#8211; y compris les dettes financi\u00e8res &#8211; mais chacune dans son propre p\u00e9rim\u00e8tre.  Et dans le politique, pour l&#8217;instant, Tajani d\u00e9cide.  Il n&#8217;y a pas d&#8217;autres meneurs.  Et m\u00eame pas une chanteuse, si quelqu&#8217;un pense \u00e0 la derni\u00e8re compagne de Cav pour un r\u00f4le plus politique.  &#8220;Marta Fascina est d\u00e9put\u00e9e, il n&#8217;y a pas besoin de se tailler des espaces formels&#8221;, le ministre des Affaires \u00e9trang\u00e8res balaie tout doute.<\/p>\n<p><h2 id=\"U403263596679nNE\">Les demandes de Ronzulli<\/h2>\n<\/p>\n<p class=\"atext\">&#8220;Elle n&#8217;avait aucune pr\u00e9tention&#8221;, assure ceux qui ces derni\u00e8res heures ont vu de pr\u00e8s la &#8220;grande douleur&#8221; de la petite amie de trente-trois ans pour la mort du Chevalier.  En tout cas, ceux qui ont v\u00e9cu avec impatience la mont\u00e9e de Fascina ces derniers mois ont \u00e9t\u00e9 rassur\u00e9s par les propos de Tajani.  Et ce m\u00eame front attend maintenant une plus grande reconnaissance, par exemple \u00e0 travers l&#8217;implication dans les territoires, dans les nominations des commissions bicam\u00e9rales, et dans la pouss\u00e9e pour la participation en tant que protagonistes dans les gouvernements.  Ils ne sont pas obligatoires, mais c&#8217;est l&#8217;esprit avec lequel le groupe bleu consid\u00e9r\u00e9 comme le plus proche de Ronzulli est pr\u00eat \u00e0 soutenir le leadership de Tajani.<\/p>\n<p><h2 id=\"U403263596679DeE\">Le nom de Berlusconi dans le symbole<\/h2>\n<\/p>\n<p class=\"atext\">Une autre garantie, a fait remarquer Tajani, r\u00e9side dans le nom du leader, qui restera dans le symbole : &#8220;Ceci est et sera toujours le parti de Silvio Berlusconi&#8221;.  Il parle de la paix sign\u00e9e dans le parti pour Tajani &#8220;presque pr\u00e9sident&#8221;, mettant de c\u00f4t\u00e9 les poisons et les ambitions.<\/p>\n<p><h2 id=\"U403263596679kPF\">Le forfait famille<\/h2>\n<\/p>\n<p class=\"atext\">Le plan familial s&#8217;accompagne d&#8217;un plan d&#8217;action d\u00e9j\u00e0 esquiss\u00e9: Marina Berlusconi et Fedele Confalonieri ont une cha\u00eene directe avec Giorgia Meloni, qui pourrait devenir particuli\u00e8rement chaude si et quand <a rel=\"nofollow noopener\" class=\"classi-link-esterno\" href=\"https:\/\/24plus.ilsole24ore.com\/art\/telecom-e-mediaset-cosi-vivendi-si-trova-centro-doppia-partita-italiana-AEUUQ6hD\" target=\"_blank\">Vivendi devait tenter de se resserrer sur Mfe-Mediaset<\/a>.  Sur le front politique, cependant, le r\u00f4le de Gianni Letta reste crucial, qui a d\u00e9j\u00e0 eu d&#8217;intenses discussions avec le Premier ministre apr\u00e8s la mort de Berlusconi.  L&#8217;objectif commun entre Meloni, Letta et Tajani est de garder les rangs bleus serr\u00e9s.  Apr\u00e8s le rebond positif des sondages ces jours-ci, le consensus sera soigneusement \u00e9valu\u00e9 apr\u00e8s l&#8217;\u00e9t\u00e9.  M\u00eame de la haute direction de FdI.  La tendance pourrait influencer la strat\u00e9gie de Melon.  M\u00eame si entre-temps le PPE a \u00e9cart\u00e9 la possibilit\u00e9 pour les Fr\u00e8res d&#8217;Italie de rejoindre le groupe des Populaires europ\u00e9ens avant les \u00e9lections au Parlement europ\u00e9en pr\u00e9vues dans un an.  Une \u00e9preuve \u00e9lectorale qui, soulign\u00e9e par le Ppe, \u00ab se gagnera au centre, pas en chassant l&#8217;extr\u00e9misme \u00bb<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/forza-italia-tajani-la-reggenza-filo-diretto-marina-e-vicepremier-AEHks1iD\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9couter la version audio de l&#8217;article La nouvelle \u00e8re de Forza Italia sans le chevalier est n\u00e9e. Et pour prendre le relais, c&#8217;est Antonio Tajani. Officiellement, le vice-premier ministre est le num\u00e9ro deux du parti. Mais en attendant le processus pour choisir qui conduira les Azzurri au Congr\u00e8s le 22 juin, il est le trait [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":787723,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[12177,422,18175,14981,2903,13179,944,33411,92972,1218,25652],"class_list":["post-787722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-directe","tag-entre","tag-forza","tag-italia","tag-ligne","tag-marina","tag-ministre","tag-regence","tag-tajani","tag-vers","tag-vicepremier"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/787722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=787722"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/787722\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/787723"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=787722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=787722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=787722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}