{"id":78509,"date":"2022-04-08T11:03:43","date_gmt":"2022-04-08T13:03:43","guid":{"rendered":"https:\/\/teknomers.com\/fr\/laz-se-mefie-du-joueur-interessant-mees-de-wit-nous-regardons-toujours-des-joueurs-comme-lui\/"},"modified":"2022-04-08T11:03:46","modified_gmt":"2022-04-08T13:03:46","slug":"laz-se-mefie-du-joueur-interessant-mees-de-wit-nous-regardons-toujours-des-joueurs-comme-lui","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/laz-se-mefie-du-joueur-interessant-mees-de-wit-nous-regardons-toujours-des-joueurs-comme-lui\/","title":{"rendered":"L&#8217;AZ se m\u00e9fie du &#8220;joueur int\u00e9ressant&#8221; Mees de Wit\u00a0: &#8220;Nous regardons toujours des joueurs comme lui&#8221;"},"content":{"rendered":"\n<div id=\"\">\n<p class=\"article__intro\">\n<p>\t\t\t\t\t\t\t\t\t\tL&#8217;AZ affrontera le PEC Zwolle dimanche et se penchera principalement sur les performances de Mees de Wit.  Chez les Alkmaarders, De Wit est une option importante pour succ\u00e9der \u00e0 Owen Wijndal en tant que nouvel arri\u00e8re gauche du club l&#8217;\u00e9t\u00e9 prochain.  De Wit devra alors rivaliser avec le Hongrois Milos Kerkez, recrut\u00e9 pendant la tr\u00eave hivernale. <\/p>\n<\/p><\/div>\n<div>\n<p>\t\t\t\t\t\t\t\t\t\t<!-- includes\/advertising\/fixed-slot.html --><\/p>\n<p><!-- \/ includes\/advertising\/fixed-slot.html --><\/p>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">De Wit s&#8217;est \u00e9galement fait un nom \u00e0 l&#8217;AZ en marquant deux fois lors du match \u00e0 domicile au nom du PEC Zwolle.  ,,Nous avons \u00e9t\u00e9 avertis sur la base de ce match&#8221;, a d\u00e9clar\u00e9 l&#8217;entra\u00eeneur Pascal Jansen lors de la conf\u00e9rence de presse de vendredi apr\u00e8s-midi.  ,,Il a r\u00e9ussi \u00e0 marquer deux fois de la t\u00eate pendant ce match.  Je ne pense pas qu&#8217;il pensait qu&#8217;il \u00e9tait si bon en t\u00eate.  Mees est maintenant un <i>aile arri\u00e8re <\/i>avec la capacit\u00e9 de marche n\u00e9cessaire.  Cela dit quelque chose sur lui, qu&#8217;il peut faire \u00e7a aussi.<\/p>\n<\/div>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">Jansen pense que De Wit est un &#8220;joueur int\u00e9ressant&#8221; pour son AZ.  ,,Mees se d\u00e9veloppe bien et c&#8217;est aussi un gar\u00e7on qui correspondrait parfaitement \u00e0 notre profil.  C&#8217;est un gar\u00e7on de 23 ans et il est hollandais.  Nous regardons toujours des joueurs comme lui.  Comme lui, il y a plus de joueurs qui sont int\u00e9ressants pour AZ.<\/p>\n<\/div>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">Jansen a vu son concurrent Feyenoord faire match nul 3-3 contre le Slavia Prague en Conference League lors d&#8217;un match ext\u00e9nuant jeudi soir.  La diff\u00e9rence entre AZ et Feyenoord est de trois points, tandis que le FC Twente a \u00e9galement autant de points que AZ.  ,, Il reste \u00e0 voir si ce match de la Conference League a une influence sur Feyenoord en Eredivisie &#8221;, d\u00e9clare Jansen.  ,,Je ne peux pas estimer comment les joueurs de Feyenoord sont maintenant physiquement.  Mais il me semble qu&#8217;on est proches l&#8217;un de l&#8217;autre avec trois clubs et que \u00e7a peut quand m\u00eame \u00eatre excitant.<\/p>\n<\/div>\n<div class=\"article-login-gate fjs-article-login-gate\">\n<p class=\"article-login-gate__title fjs-article-login-gate__title\">\n<p>\t\tAcc\u00e8s gratuit et illimit\u00e9 \u00e0 Showbytes\u00a0?  Qui peut!\n\t<\/p>\n<p>\t<span class=\"article-login-gate__info fjs-article-login-gate__info\"><\/p>\n<p>\t\tConnectez-vous ou cr\u00e9ez un compte et ne manquez rien des \u00e9toiles.<br \/>\n\t<\/span><\/p>\n<p class=\"article-login-gate__buttonholder\">\n<p>\t\t\t<span class=\"button__text fjs-article-login-gate__button\">Oui, je veux un acc\u00e8s gratuit et illimit\u00e9<\/span><\/p>\n<\/div><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.destentor.nl\/nederlands-voetbal\/az-op-zijn-hoede-voor-interessante-speler-mees-de-wit-naar-spelers-als-hij-kijken-we-altijd~a7182149\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-42<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;AZ affrontera le PEC Zwolle dimanche et se penchera principalement sur les performances de Mees de Wit. Chez les Alkmaarders, De Wit est une option importante pour succ\u00e9der \u00e0 Owen Wijndal en tant que nouvel arri\u00e8re gauche du club l&#8217;\u00e9t\u00e9 prochain. De Wit devra alors rivaliser avec le Hongrois Milos Kerkez, recrut\u00e9 pendant la tr\u00eave [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":78510,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1756,133,15028,2554,520,14427,1590,45623,19042,1266,23167,220,45624],"class_list":["post-78509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-comme","tag-des","tag-interessant","tag-joueur","tag-joueurs","tag-laz","tag-lui","tag-mees","tag-mefie","tag-nous","tag-regardons","tag-toujours","tag-wit"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/78509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=78509"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/78509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/78510"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=78509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=78509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=78509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}