{"id":741580,"date":"2023-05-19T05:43:32","date_gmt":"2023-05-19T07:43:32","guid":{"rendered":"https:\/\/teknomers.com\/fr\/blazy-que-les-medias-ne-soient-pas-autorises-a-interroger-rolf-sanchez-sur-une-rupture\/"},"modified":"2023-05-19T05:43:36","modified_gmt":"2023-05-19T07:43:36","slug":"blazy-que-les-medias-ne-soient-pas-autorises-a-interroger-rolf-sanchez-sur-une-rupture","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/blazy-que-les-medias-ne-soient-pas-autorises-a-interroger-rolf-sanchez-sur-une-rupture\/","title":{"rendered":"&#8220;Blazy que les m\u00e9dias ne soient pas autoris\u00e9s \u00e0 interroger Rolf Sanchez sur une rupture&#8221;"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Rolf Sanchez demande la paix aux m\u00e9dias maintenant qu&#8217;Yvonne Coldeweijer a divulgu\u00e9 que sa relation avait pris fin.  Et Guido den Aantrekker pense que c&#8217;est nul : \u00ab Un peu dommage.<\/p>\n<div class=\"entry__thumb\">\n <span class=\"entry__thumb-description\">\u00a9 Instagram<\/span> <\/div>\n<p>Rolf Sanchez, 31 ans, et sa petite amie Sophie Mason se sont s\u00e9par\u00e9s apr\u00e8s quatre ans.  La nouvelle a fuit\u00e9 hier via la cha\u00eene de jus d&#8217;Yvonne Coldeweijer.  Elle a rapport\u00e9 : \u00ab Selon un espion, la relation est termin\u00e9e.  Les choses ne vont pas bien entre Rolf Sanchez et Sophia Mason depuis un moment, mais la relation semble se r\u00e9p\u00e9ter depuis un mois maintenant.<\/p>\n<h2 class=\"wp-block-heading\">Rolf et Sophie se s\u00e9parent<\/h2>\n<p>Rolf \u00e9tait l\u00e0 comme les poulets pour emp\u00eacher toute rumeur : \u00ab Chers tous.  Nous avons encore du mal \u00e0 y mettre des mots, mais tenons \u00e0 vous faire savoir par cette route que nous ne sommes effectivement plus ensemble.  Nous nous sommes s\u00e9par\u00e9s tr\u00e8s affectueusement et esp\u00e9rons que vous respecterez notre vie priv\u00e9e.<\/p>\n<p>Ils ne veulent pas tous les deux parler aux m\u00e9dias de cette rupture.  &#8220;Nous ne commenterons pas davantage \u00e0 ce sujet et esp\u00e9rons que vous nous donnerez le temps de lui donner une place.&#8221;<\/p>\n<h2 class=\"wp-block-heading\">&#8216;Pas de r\u00e9action?  Faible!&#8217;<\/h2>\n<p>Guido den Aantrekker, patron de l&#8217;histoire, pense que c&#8217;est idiot.  &#8220;Je pense toujours que c&#8217;est un peu dommage moi-m\u00eame.  Si vous dites tr\u00e8s longuement quand votre relation commence et que vous \u00eates si heureux, tr\u00e8s amusant, alors c&#8217;est aussi assez amusant pour une fois &#8211; eh bien, amusant n&#8217;est pas le mot &#8211; mais si les choses vont un peu moins, l\u00e0 aussi ouvert pour parler \u00e0 propos de.&#8221;<\/p>\n<p>Il continue au bureau de <a rel=\"nofollow noopener\" href=\"https:\/\/www.kijk.nl\/programmas\/shownieuws-late-editie\/YVknpaWCEkm\" target=\"_blank\">Afficher les actualit\u00e9s<\/a>: &#8220;Mais alors c&#8217;est g\u00e9n\u00e9ralement une publication Instagram et personne d&#8217;autre n&#8217;est autoris\u00e9 \u00e0 demander quoi que ce soit.&#8221;<\/p>\n<h2 class=\"wp-block-heading\">Coup de tonnerre<\/h2>\n<p>Coll\u00e8gue Bart Ettekoven: &#8220;Cela vient comme une sorte de coup de tonnerre, n&#8217;est-ce pas?&#8221;<\/p>\n<p>Guido : &#8220;\u00c9norme.&#8221;<\/p>\n<p>Bart : &#8220;Pourquoi \u00e9crit-il alors : &#8216;Nous sommes <em>en effet<\/em> \u00e0 part.&#8217;  Avec cela, il sugg\u00e8re qu&#8217;il y avait d\u00e9j\u00e0 des rumeurs.<\/p>\n<p>Airen Myl\u00e8ne : \u00ab Oui, \u00e0 travers le <em>canaux de jus<\/em> il y avait d\u00e9j\u00e0 des rumeurs.<\/p>\n<p>euh, les cha\u00eenes de jus\u00a0?  Yvonne Coldeweijer.  C&#8217;est la m\u00eame chose que de crier &#8220;via les programmes TV&#8221; quand quelque chose vient de Shownieuws. <\/p>\n<h2 class=\"wp-block-heading\">Maison achet\u00e9e<\/h2>\n<p>Guido ne donne pas non plus Yvonne \u00e0 aucun moment <em>cr\u00e9dits<\/em>, mais ressasse ce qu&#8217;il y a exactement sur sa cha\u00eene de jus, par exemple \u00e0 propos de la maison que Rolf et Sophia ont achet\u00e9e.  &#8220;Ce qui est ennuyeux, c&#8217;est que l&#8217;ann\u00e9e derni\u00e8re, ils ont achet\u00e9 ensemble une maison \u00e0 Nederhorst den Berg pour 1,4 million d&#8217;euros.&#8221;<\/p>\n<p>Il poursuit : \u00ab Que va-t-il se passer avec \u00e7a ?  Donc, malheureusement, nous ne pouvons pas non plus leur demander cela.  L&#8217;un d&#8217;eux y restera-t-il ou le vendra-t-il ?  Vous le nommez.&#8221;<\/p>\n<h2 class=\"wp-block-heading\">Emm\u00e9nager avec Andr\u00e9 ?<\/h2>\n<p>Il reste \u00e0 voir comment ils vont r\u00e9soudre ce probl\u00e8me, dit Guido.  \u00ab En tout cas, je sais que Rolf est un tr\u00e8s bon ami d&#8217;Andr\u00e9 Hazes et qu&#8217;il vient d&#8217;acqu\u00e9rir une nouvelle maison \u00e0 Wilnis.  Il y a encore quelques pi\u00e8ces vides l\u00e0-bas, alors peut-\u00eatre qu&#8217;il peut y vivre pour le moment.<\/p>\n<p>Une blague d&#8217;Yvonne sur le fait que Sophie \u00e9tait la coach de mouvement de Mia &#038; Dion lors de sa rupture est \u00e9galement \u00e0 peine imit\u00e9e par Guido.  &#8220;Nous avons tous vu que cela n&#8217;avait pas l&#8217;air tr\u00e8s dynamique.&#8221;<\/p>\n<h2 class=\"wp-block-heading\">Jus<\/h2>\n<p>Jus de rupture en trois \u00e9tapes :<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"419193\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/05\/1684482212_750_Blazy-que-les-medias-ne-soient-pas-autorises-a-interroger.jpg\" alt=\"\" class=\"wp-image-419193\"  \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"576\" height=\"1024\" data-id=\"419192\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/05\/1684482212_635_Blazy-que-les-medias-ne-soient-pas-autorises-a-interroger.jpg\" alt=\"\" class=\"wp-image-419192\"  \/><\/figure>\n<\/figure>\n<blockquote class=\"instagram-media\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CsYoBG1tM12\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"\/><\/div>\n<p><script async defer src=\"https:\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.mediacourant.nl\/2023\/05\/flauw-dat-media-rolf-sanchez-niet-mogen-vragen-naar-break-up\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-48<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rolf Sanchez demande la paix aux m\u00e9dias maintenant qu&#8217;Yvonne Coldeweijer a divulgu\u00e9 que sa relation avait pris fin. Et Guido den Aantrekker pense que c&#8217;est nul : \u00ab Un peu dommage. \u00a9 Instagram Rolf Sanchez, 31 ans, et sa petite amie Sophie Mason se sont s\u00e9par\u00e9s apr\u00e8s quatre ans. La nouvelle a fuit\u00e9 hier via [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":741581,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[8717,10925,26,65,4381,132,8961,1176,24009,5118,60,196],"class_list":["post-741580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-autorises","tag-blazy","tag-interroger","tag-les","tag-medias","tag-pas","tag-rolf","tag-rupture","tag-sanchez","tag-soient","tag-sur","tag-une"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/741580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=741580"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/741580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/741581"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=741580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=741580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=741580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}