{"id":731009,"date":"2023-05-12T11:59:44","date_gmt":"2023-05-12T13:59:44","guid":{"rendered":"https:\/\/teknomers.com\/fr\/la-majorite-des-britanniques-craignent-que-lia-nait-des-consequences-devastatrices-pour-lhumanite-et-souhaitent-plus-de-reglementation-selon-un-sondage\/"},"modified":"2023-05-12T11:59:47","modified_gmt":"2023-05-12T13:59:47","slug":"la-majorite-des-britanniques-craignent-que-lia-nait-des-consequences-devastatrices-pour-lhumanite-et-souhaitent-plus-de-reglementation-selon-un-sondage","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/la-majorite-des-britanniques-craignent-que-lia-nait-des-consequences-devastatrices-pour-lhumanite-et-souhaitent-plus-de-reglementation-selon-un-sondage\/","title":{"rendered":"La majorit\u00e9 des Britanniques craignent que l&#8217;IA n&#8217;ait des &#8220;cons\u00e9quences d\u00e9vastatrices pour l&#8217;humanit\u00e9&#8221; et souhaitent plus de r\u00e9glementation, selon un sondage"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>LA majorit\u00e9 des Britanniques ont peur que l&#8217;IA puisse avoir &#8220;des cons\u00e9quences d\u00e9vastatrices pour l&#8217;humanit\u00e9&#8221;.<\/p>\n<p>Selon un sondage, les deux tiers souhaitent davantage de r\u00e9glementation pour garantir un meilleur contr\u00f4le sur la technologie en \u00e9volution rapide.<\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"274\"><a rel=\"nofollow\" href=\"#\"><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">2<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Les deux tiers veulent plus de r\u00e9gulation de l&#8217;intelligence artificielle<\/span><span class=\"article__credit\">Cr\u00e9dit : Getty<\/span><\/figcaption><\/figure>\n<p>Selon Chris Holbrook, l&#8217;am\u00e9lioration rapide de l&#8217;intelligence artificielle (IA) aura &#8220;des cons\u00e9quences d\u00e9sastreuses pour l&#8217;humanit\u00e9 et le bien-\u00eatre mental&#8221; si l&#8217;on ne fait pas plus pour la freiner.<\/p>\n<p>Il a fond\u00e9 la soci\u00e9t\u00e9 de sondage Find Out Now, qui a interrog\u00e9 plus de 2 000 Britanniques.<\/p>\n<p>Plus de 80 % des personnes interrog\u00e9es pensent que les images manipul\u00e9es aggravent les probl\u00e8mes d&#8217;image corporelle, en particulier chez les femmes d&#8217;\u00e2ge moyen.<\/p>\n<p>Cela vient alors que la marque de sport Asics a appel\u00e9 l&#8217;IA pour avoir cr\u00e9\u00e9 une image corporelle irr\u00e9aliste.<\/p>\n<div class=\"read-more-container css-t90arc\">\n<div class=\"css-dr8sr7\">\n<div class=\"css-g9qqck\">\n<div class=\"css-1mpu6y4\">\n<div class=\"css-11k10ko\">\n<div class=\"read-more-vertical-card css-1jl19eb\">\n<div class=\"css-1fz92cy\"><img loading=\"lazy\" decoding=\"async\" class=\"lazyload newskit-replacement-image\" alt=\"J'ai cr\u00e9\u00e9 une IA de moi-m\u00eame avec laquelle vous pouvez sortir pour 1 $ la minute - mais c'est devenu \"voyou\"\" width=\"295\" height=\"188\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/05\/La-majorite-des-Britanniques-craignent-que-lIA-nait-des-consequences.jpg\"\/><\/div>\n<\/div>\n<\/div>\n<div class=\"css-11k10ko\">\n<div class=\"read-more-vertical-card css-1jl19eb\">\n<div class=\"css-1fz92cy\"><img loading=\"lazy\" decoding=\"async\" class=\"lazyload newskit-replacement-image\" alt=\"L'IA \"meilleure et plus rapide\" pour d\u00e9tecter les crises cardiaques que les m\u00e9decins\" width=\"295\" height=\"188\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/05\/1683899983_234_La-majorite-des-Britanniques-craignent-que-lIA-nait-des-consequences.jpg\"\/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>La technologie peut modifier les images afin que les gens n&#8217;aient pas de graisse corporelle, de m\u00e2choires cisel\u00e9e, de muscles ou m\u00eame d&#8217;abdos en pack de 12.<\/p>\n<p>Et les Britanniques ont d\u00e9clar\u00e9 que les photos les faisaient se sentir inaptes, inf\u00e9rieurs, peu attrayants ou peu s\u00fbrs \u2013 certains disant qu&#8217;ils se sentaient moins motiv\u00e9s \u00e0 faire de l&#8217;exercice en cons\u00e9quence.<\/p>\n<p>Quelque 79 % des personnes interrog\u00e9es pensent que l&#8217;industrie de l&#8217;IA doit \u00eatre plus \u00e9troitement r\u00e9glement\u00e9e.<\/p>\n<p>Et les deux tiers disent que les photos et les vid\u00e9os doivent \u00eatre authentifi\u00e9es sur les r\u00e9seaux sociaux &#8211; afin que les utilisateurs sachent s&#8217;ils ont \u00e9t\u00e9 trafiqu\u00e9s.<\/p>\n<p>Le site de m\u00e9dias sociaux Frankli utilise une technologie inviolable pour donner une preuve irr\u00e9vocable que les photographies et les vid\u00e9os sont r\u00e9elles.<\/p>\n<p>Il a command\u00e9 le sondage pour convaincre d&#8217;autres g\u00e9ants de la technologie de s&#8217;assurer que les images et les vid\u00e9os sont r\u00e9elles.<\/p>\n<p>Pendant ce temps, une enqu\u00eate a r\u00e9v\u00e9l\u00e9 que des cybercriminels vendaient du deepfake revenge porn sur le dark web jusqu&#8217;\u00e0 15 800 \u00a3 pour une vid\u00e9o d&#8217;une minute.<\/p>\n<p>Les syst\u00e8mes aliment\u00e9s par l&#8217;IA comme Stable Diffusion ou Midjourney, qui traduisent les invites de texte en images, peuvent \u00eatre utilis\u00e9s pour cr\u00e9er des images \u00e9poustouflantes.<\/p>\n<p>Mais ces g\u00e9n\u00e9rateurs d&#8217;images peuvent aussi cr\u00e9er des images pornographiques hyperr\u00e9alistes.<\/p>\n<p>Et la technologie d&#8217;\u00e9change de visage est capable de manipuler num\u00e9riquement la pornographie, de sorte qu&#8217;il semble que des personnes soient pr\u00e9sentes dans des vid\u00e9os qu&#8217;elles n&#8217;ont jamais film\u00e9es, ce qui expose les Britanniques \u00e0 un risque accru de pornographie vengeresse.<\/p>\n<p>Ces deepfakes pornographiques peuvent \u00eatre vendus entre 240 et 15 870 \u00a3 la minute, selon le g\u00e9ant de la cybers\u00e9curit\u00e9 Kaspersky.<\/p>\n<p>L&#8217;IA est si avanc\u00e9e qu&#8217;elle peut \u00e9galement cr\u00e9er des images d&#8217;humains qui n&#8217;ont jamais exist\u00e9.<\/p>\n<p>Quelque 21% des 18-24 ans ont d\u00e9clar\u00e9 avoir \u00e9t\u00e9 dup\u00e9s par un deepfake.<\/p>\n<p>Et 84 % des Britanniques pensent que les entreprises technologiques devraient ralentir le d\u00e9veloppement de ces syst\u00e8mes.<\/p>\n<p>Le fondateur de Frankli, le Dr Mansoor Ahmed-Rengers, a d\u00e9clar\u00e9 que les entreprises devaient &#8220;agir rapidement&#8221; pour contr\u00f4ler l&#8217;utilisation de la technologie de l&#8217;IA car &#8220;notre avenir est en jeu&#8221;.<\/p>\n<p>Il a ajout\u00e9 : &#8220;Ces r\u00e9sultats de sondage illustrent le niveau de peur du public vis-\u00e0-vis de l&#8217;IA et la rapidit\u00e9 de son d\u00e9veloppement.<\/p>\n<p>&#8220;On voit une nette majorit\u00e9 s&#8217;inqui\u00e9ter des cons\u00e9quences de la technologie avec 66% des r\u00e9pondants appelant \u00e0 l&#8217;authentification des photos et vid\u00e9os sur les r\u00e9seaux sociaux.<\/p>\n<p>&#8220;Huit personnes sur dix pensent que le contenu manipul\u00e9 peut avoir des effets n\u00e9gatifs sur la sant\u00e9 mentale et l&#8217;image corporelle et c&#8217;est pourquoi nous devons agir rapidement. <\/p>\n<p>&#8220;Notre avenir est en jeu ici. Il ne peut pas \u00eatre surestim\u00e9.&#8221;<\/p>\n<div class=\"read-more-container css-t90arc\">\n<div class=\"css-dr8sr7\">\n<div class=\"css-g9qqck\">\n<div class=\"css-1mpu6y4\">\n<div class=\"css-11k10ko\">\n<div class=\"read-more-vertical-card css-1jl19eb\">\n<div class=\"css-1fz92cy\"><img loading=\"lazy\" decoding=\"async\" class=\"lazyload newskit-replacement-image\" alt=\"This Morning's Holly \"aveugl\u00e9 et boulevers\u00e9\" alors que Phil publie une d\u00e9claration\" width=\"295\" height=\"188\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/05\/1683899984_461_La-majorite-des-Britanniques-craignent-que-lIA-nait-des-consequences.jpg\"\/><\/div>\n<\/div>\n<\/div>\n<div class=\"css-11k10ko\">\n<div class=\"read-more-vertical-card css-1jl19eb\">\n<div class=\"css-1fz92cy\"><img loading=\"lazy\" decoding=\"async\" class=\"lazyload newskit-replacement-image\" alt=\"Je suis all\u00e9 en Turquie et j'ai fait faire mes cils et mes ongles - cela ne m'a co\u00fbt\u00e9 que 14 \u00a3 au total\" width=\"295\" height=\"188\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/05\/1683899984_467_La-majorite-des-Britanniques-craignent-que-lIA-nait-des-consequences.jpg\"\/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>La technologie de Frankli, invent\u00e9e par sa soci\u00e9t\u00e9 fa\u00eeti\u00e8re OpenOrigins, permet \u00e0 l&#8217;application de visualiser l&#8217;emplacement exact et l&#8217;heure \u00e0 laquelle les images sont captur\u00e9es. <\/p>\n<p>Au moment o\u00f9 les images sont enregistr\u00e9es, elles sont stock\u00e9es en toute s\u00e9curit\u00e9 sur une base de donn\u00e9es distribu\u00e9e inviolable afin qu&#8217;elles ne puissent pas \u00eatre manipul\u00e9es. <\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"275\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"L'IA est si avanc\u00e9e qu'elle peut cr\u00e9er des images r\u00e9alistes de personnes qui n'ont jamais exist\u00e9\" height=\"960\" width=\"960\" class=\"lazyload\" src=\"https:\/\/www.thesun.co.uk\/wp-content\/uploads\/2023\/02\/RW-INARTICLE-FAKE-PEOPLE-1.jpg\" data-credit=\"thispersondoesnotexist\" data- data-img=\"https:\/\/www.thesun.co.uk\/wp-content\/uploads\/2023\/02\/RW-INARTICLE-FAKE-PEOPLE-1.jpg?strip=all&amp;w=960\"  bad-src=\"data:image\/svg+xml,%3Csvg xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; viewBox=&quot;0 0 1 1&quot;%3E%3C\/svg%3E\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">2<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">L&#8217;IA est si avanc\u00e9e qu&#8217;elle peut cr\u00e9er des images r\u00e9alistes de personnes qui n&#8217;ont jamais exist\u00e9<\/span><span class=\"article__credit\">Cr\u00e9dit\u00a0: cette personne n&#8217;existe pas<\/span><\/figcaption><\/figure>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.thesun.co.uk\/tech\/news-tech\/22338582\/brits-fear-ai-could-have-devastating-consequences\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-58<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA majorit\u00e9 des Britanniques ont peur que l&#8217;IA puisse avoir &#8220;des cons\u00e9quences d\u00e9vastatrices pour l&#8217;humanit\u00e9&#8221;. Selon un sondage, les deux tiers souhaitent davantage de r\u00e9glementation pour garantir un meilleur contr\u00f4le sur la technologie en \u00e9volution rapide. 2 Les deux tiers veulent plus de r\u00e9gulation de l&#8217;intelligence artificielleCr\u00e9dit : Getty Selon Chris Holbrook, l&#8217;am\u00e9lioration rapide de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":731010,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[5463,3202,6786,133,47627,8956,13717,16234,13654,185,12415,2162,5321,25451],"class_list":["post-731009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-britanniques","tag-consequences","tag-craignent","tag-des","tag-devastatrices","tag-lhumanite","tag-lia","tag-majorite","tag-nait","tag-pour","tag-reglementation","tag-selon","tag-sondage","tag-souhaitent"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/731009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=731009"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/731009\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/731010"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=731009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=731009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=731009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}