{"id":731006,"date":"2023-05-12T11:58:41","date_gmt":"2023-05-12T13:58:41","guid":{"rendered":"https:\/\/teknomers.com\/fr\/tim-hofman-pense-que-la-star-de-boulevard-va-trop-loin-retenlikker\/"},"modified":"2023-05-12T11:58:44","modified_gmt":"2023-05-12T13:58:44","slug":"tim-hofman-pense-que-la-star-de-boulevard-va-trop-loin-retenlikker","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/tim-hofman-pense-que-la-star-de-boulevard-va-trop-loin-retenlikker\/","title":{"rendered":"Tim Hofman pense que la star de Boulevard va trop loin : &#8220;Retenlikker !&#8221;"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Tim Hofman pense que Jeroen Snel, le connaisseur de la royaut\u00e9 de RTL Boulevard, va trop loin avec sa critique conservatrice du maillot de bain de la brutale comtesse Eloise.  &#8220;C&#8217;est un l\u00e8che-cul !&#8221;<\/p>\n<div class=\"entry__thumb\">\n <span class=\"entry__thumb-description\">\u00a9RTL<\/span> <\/div>\n<p>La comtesse Elo\u00efse, la ni\u00e8ce du roi, participe \u00e0 une \u00e9mission de divertissement sur RTL 4 : The Perfect Picture.  Le premier \u00e9pisode de mercredi a montr\u00e9 comment elle a pos\u00e9 en maillot de bain sur la plage d&#8217;Afrique du Sud \u00e0 la demande de son coll\u00e8gue candidat Rick Brandsteder.  Une <em>Royal<\/em> en maillot de bain ?  Ce n&#8217;est pas possible, dit Jeroen Snel.<\/p>\n<h2 class=\"wp-block-heading\">l\u00e8che-cul<\/h2>\n<p>Selon Jeroen, il s&#8217;agit d&#8217;un &#8220;cas limite&#8221;.  Quoi?!  Tim Hofman ne comprend pas dans quoi s&#8217;embarque cet ancien bobo d&#8217;EO.  Il parle sur son <em>sociaux<\/em> d&#8217;une &#8220;conversation hallucinatoire&#8221; sur RTL Boulevard. <\/p>\n<p>Il r\u00e9sume : \u00ab Eddy Zo\u00eby dit paternellement que c&#8217;est &#8216;un maillot de bain soign\u00e9&#8217;, Jeroen Snel r\u00e9p\u00e8te \u00e0 trois reprises que c&#8217;est vraiment \u00e0 la limite qu&#8217;Elo\u00efse se montre comme \u00e7a et parle de ses &#8216;bombonellas&#8217;.  Et aussi trois fois que tout cela est inutile.  L\u00e9cher le cul d&#8217;un monarque pendant des ann\u00e9es produit apparemment un joli vocabulaire.<\/p>\n<h2 class=\"wp-block-heading\">Plus de critiques<\/h2>\n<p>Tim n&#8217;est en aucun cas le seul \u00e0 critiquer l&#8217;opinion conservatrice de l&#8217;expert du boulevard.  Par exemple, la star de Telegraaf, Wilson Boldewijn, tweete : &#8220;Oui, parce que si vous \u00eates un &#8216;royal&#8217;, vous devez pr\u00e9tendre que nous sommes en 1796.  Arr\u00eate \u00e7a.&#8221;<\/p>\n<p>Et la c\u00e9l\u00e8bre blogueuse beaut\u00e9 Vera Camilla : \u00ab Je pense a) qu&#8217;en tant qu&#8217;homme, vous devriez toujours garder votre bouche ferm\u00e9e sur ce qu&#8217;une femme fait de son corps, et b) que peu importe si cette femme vient du famille royale.  Votre corps, votre choix.  Indiquer.&#8221;<\/p>\n<h2 class=\"wp-block-heading\">Sexiste<\/h2>\n<p>Gravemade de l&#8217;actrice Nienke trouve la cause de la s\u00e9ance en maillot de bain d&#8217;Eloise discutable.  \u00ab La seule chose dont nous devons nous inqui\u00e9ter est le manque absolu de cr\u00e9ativit\u00e9 de Rick Brandsteder.  Une fille Pamela-Andersson en maillot de bain avec cocktail au milieu de l&#8217;oc\u00e9an.  Soporifique sexiste.<\/p>\n<p>Et l&#8217;habile tweeter TV Victor Hopman : &#8220;Quelle absurdit\u00e9, laissez-la profiter de sa vie et porter ce qu&#8217;elle veut.&#8221;<\/p>\n<h2 class=\"wp-block-heading\">Tweeter<\/h2>\n<p>La critique f\u00e9roce de Tim :<\/p>\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"\/>\n <\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.mediacourant.nl\/2023\/05\/tim-hofman-vindt-dat-boulevard-ster-te-ver-gaat-retenlikker\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-48<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tim Hofman pense que Jeroen Snel, le connaisseur de la royaut\u00e9 de RTL Boulevard, va trop loin avec sa critique conservatrice du maillot de bain de la brutale comtesse Eloise. &#8220;C&#8217;est un l\u00e8che-cul !&#8221; \u00a9RTL La comtesse Elo\u00efse, la ni\u00e8ce du roi, participe \u00e0 une \u00e9mission de divertissement sur RTL 4 : The Perfect Picture. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":731007,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[6689,25033,2616,4076,161970,3564,8845,2103],"class_list":["post-731006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-boulevard","tag-hofman","tag-loin","tag-pense","tag-retenlikker","tag-star","tag-tim","tag-trop"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/731006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=731006"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/731006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/731007"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=731006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=731006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=731006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}