{"id":708476,"date":"2023-04-28T12:44:20","date_gmt":"2023-04-28T14:44:20","guid":{"rendered":"https:\/\/teknomers.com\/fr\/pnrr-la-recette-anti-retard-de-comptabilite-avec-30-davance\/"},"modified":"2023-04-28T12:44:24","modified_gmt":"2023-04-28T14:44:24","slug":"pnrr-la-recette-anti-retard-de-comptabilite-avec-30-davance","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/pnrr-la-recette-anti-retard-de-comptabilite-avec-30-davance\/","title":{"rendered":"Pnrr, la recette anti-retard de Comptabilit\u00e9 avec 30% d&#8217;avance"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>\u00c9couter la version audio de l&#8217;article<\/button><\/p>\n<p class=\"atext\">Les avances de liquidit\u00e9 pour les projets Pnrr peuvent atteindre 30% du co\u00fbt des travaux, pour \u00e9viter le risque d&#8217;une crise de liquidit\u00e9 de la part des ma\u00eetres d&#8217;ouvrage \u00e0 qui les entreprises demandent ces sommes alors que le fonds li\u00e9 \u00e0 la Relance n&#8217;alloue que les 10% .<\/p>\n<p><h2 id=\"U402940463435c0F\">Les demandes des autorit\u00e9s locales <\/h2>\n<\/p>\n<p class=\"atext\">Le Minist\u00e8re de l&#8217;Economie r\u00e9pond aux demandes pressantes \u00e9manant notamment des collectivit\u00e9s locales aux prises avec les difficult\u00e9s de mise en \u0153uvre des investissements du Plan.  Et dans la circulaire 19\/2023 sign\u00e9e le jeudi 27 avril par le comptable g\u00e9n\u00e9ral de l&#8217;\u00c9tat, il resserre \u00e9galement les verrous de Regis, la plateforme t\u00e9l\u00e9matique qui devrait surveiller en temps r\u00e9el tous les mouvements de l&#8217;architecture tr\u00e8s vari\u00e9e de la r\u00e9cup\u00e9ration italienne et qui au contraire selon \u00e0 ce qui a \u00e9t\u00e9 rapport\u00e9 par les maires lors de l&#8217;audition sur la Def n\u00e9glige aujourd&#8217;hui au moins 18 000 projets d\u00e9j\u00e0 lanc\u00e9s par les autorit\u00e9s locales.<\/p>\n<p><h2 id=\"U402940463435yeF\">Minist\u00e8res 15 jours pour saisir tous les projets dans le Regis <\/h2>\n<\/p>\n<p class=\"atext\">La circulaire donne 15 jours aux minist\u00e8res, sujets &#8220;propri\u00e9taires&#8221; des interventions dont les collectivit\u00e9s territoriales sont les &#8220;acteurs&#8221; pour colmater les trous.  D&#8217;ici 15 jours \u00e9galement, les actionneurs, donc les AP centrales et locales impliqu\u00e9es dans l&#8217;une des plus de 150 000 interventions lanc\u00e9es pour le Pnrr, seront habilit\u00e9s \u00e0 fonctionner directement sur la plateforme.<\/p>\n<p class=\"atext\">Alors que l&#8217;Unification du 27 avril a donn\u00e9 le feu vert aux incitations \u00e0 l&#8217;agr\u00e9gation des services publics, autre accomplissement du Pnrr, la Circulaire de la Direction de la Comptabilit\u00e9 rentre au c\u0153ur du chapitre le plus chaud du Plan aujourd&#8217;hui, celui li\u00e9 \u00e0 la difficult\u00e9 de la mise en \u0153uvre des investissements qui place in\u00e9vitablement les collectivit\u00e9s locales sur le devant de la sc\u00e8ne.  Dans son point de presse mercredi devant les Chambres, le ministre Raffaele Fitto a cit\u00e9 les \u00e9coles maternelles comme l&#8217;un des secteurs les plus en difficult\u00e9, attisant le m\u00e9contentement des maires qui attribuent plut\u00f4t les principales causes des retards aux minist\u00e8res.  Parmi les deux points les plus critiques dont se plaignent les maires figurent justement les points d&#8217;achoppement dans la gestion de la liquidit\u00e9 et les trous dans la R\u00e9gis, c&#8217;est-\u00e0-dire les sujets au c\u0153ur de la circulaire.<\/p>\n<div class=\"acor acor--mkt\">\n<div class=\"row row--dotted\">\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/consigli24.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><\/figure>\n<p><\/a><\/div>\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/tariffe.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/01\/Pnrr-accord-entre-syndicats-et-communes-des-embauches-plus.png\" alt=\"En savoir plus\"\/><\/figure>\n<p><\/a><\/div>\n<\/div>\n<\/div>\n<p class=\"atext\">Les deux enjeux sont li\u00e9s, car l&#8217;absence \u00e0 la R\u00e9gis risque de bloquer les avanc\u00e9es.  Sur ce point, la circulaire pr\u00e9cise que &#8220;pour b\u00e9n\u00e9ficier des avances&#8221; destin\u00e9es aux nouveaux projets du Pnrr &#8220;le t\u00e9l\u00e9chargement de tout document justificatif de la d\u00e9pense dans le syst\u00e8me Regis n&#8217;est pas requis&#8221;, et que d\u00e8s lors &#8220;la seule exigence est que le projet est enqu\u00eat\u00e9&#8221; sur la plateforme.  La simplification, sous forme d&#8217;instructions d&#8217;abord pour les minist\u00e8res charg\u00e9s des interventions, est importante, car elle promet d&#8217;acc\u00e9l\u00e9rer le flux des avances indispensables pour d\u00e9marrer les travaux sans gonfler les d\u00e9lais de paiement aux entreprises.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/pnrr-ragioneria-ricetta-anti-ritardi-anticipazioni-30percento-AE22exMD\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9couter la version audio de l&#8217;article Les avances de liquidit\u00e9 pour les projets Pnrr peuvent atteindre 30% du co\u00fbt des travaux, pour \u00e9viter le risque d&#8217;une crise de liquidit\u00e9 de la part des ma\u00eetres d&#8217;ouvrage \u00e0 qui les entreprises demandent ces sommes alors que le fonds li\u00e9 \u00e0 la Relance n&#8217;alloue que les 10% . [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":708477,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[159159,84,56812,17828,11355,11238],"class_list":["post-708476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-antiretard","tag-avec","tag-comptabilite","tag-davance","tag-pnrr","tag-recette"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/708476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=708476"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/708476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/708477"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=708476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=708476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=708476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}