{"id":680587,"date":"2023-04-09T08:27:48","date_gmt":"2023-04-09T10:27:48","guid":{"rendered":"https:\/\/teknomers.com\/fr\/israel-tire-des-roquettes-et-de-lartillerie-sur-la-syrie-en-represailles-aux-attaques-a-la-roquette-sur-les-hauteurs-du-golan\/"},"modified":"2023-04-09T08:27:51","modified_gmt":"2023-04-09T10:27:51","slug":"israel-tire-des-roquettes-et-de-lartillerie-sur-la-syrie-en-represailles-aux-attaques-a-la-roquette-sur-les-hauteurs-du-golan","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/israel-tire-des-roquettes-et-de-lartillerie-sur-la-syrie-en-represailles-aux-attaques-a-la-roquette-sur-les-hauteurs-du-golan\/","title":{"rendered":"Isra\u00ebl tire des roquettes et de l&#8217;artillerie sur la Syrie en repr\u00e9sailles aux attaques \u00e0 la roquette sur les hauteurs du Golan"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Isra\u00ebl a lanc\u00e9 des tirs de roquettes et d&#8217;artillerie contre la Syrie dimanche matin en repr\u00e9sailles \u00e0 une attaque syrienne \u00e0 la roquette samedi soir.  C&#8217;est ce que rapportent les agences de presse internationales.  Pour autant que l&#8217;on sache, le bombardement n&#8217;a co\u00fbt\u00e9 aucune vie.<\/p>\n<p>Vers 22 heures samedi, des responsables militaires isra\u00e9liens ont affirm\u00e9, selon l&#8217;agence de presse AP, que la Syrie avait tir\u00e9 trois roquettes, dont l&#8217;une avait atteint les hauteurs du Golan occup\u00e9es par Isra\u00ebl.  Quelques heures plus tard, trois autres missiles sont arriv\u00e9s, dont l&#8217;un a \u00e9t\u00e9 intercept\u00e9.  AP \u00e9crit sur la base d&#8217;une cha\u00eene de t\u00e9l\u00e9vision libanaise que la Brigade Al-Qods, un groupe palestinien qui soutient le r\u00e9gime du pr\u00e9sident syrien Assad, a revendiqu\u00e9 la responsabilit\u00e9 de l&#8217;attaque.<\/p>\n<p>Aux premi\u00e8res heures du dimanche matin, des avions de combat isra\u00e9liens ont bombard\u00e9 des cibles militaires en Syrie et des soldats ont tir\u00e9 des tirs d&#8217;artillerie en repr\u00e9sailles aux attaques \u00e0 la roquette, a rapport\u00e9 l&#8217;agence de presse Reuters.  Des explosions ont \u00e9t\u00e9 entendues pr\u00e8s de la capitale syrienne Damas. <\/p>\n<p>Les tensions autour de la mosqu\u00e9e Al-Aqsa \u00e0 J\u00e9rusalem seraient \u00e0 l&#8217;origine des attaques \u00e0 la roquette.  Plus t\u00f4t cette semaine, la police isra\u00e9lienne a r\u00e9prim\u00e9 les Palestiniens venus passer la nuit dans le complexe, qui, selon les autorit\u00e9s isra\u00e9liennes, n&#8217;est autoris\u00e9 que pendant les dix derniers jours du Ramadan. <\/p>\n<picture class=\"lees-ook__image\"><source  type=\"image\/webp\"\/><\/picture>\n<span class=\"lees-ook__content\"><\/p>\n<p>\t\tLire aussi <strong>Violents affrontements entre autorit\u00e9s isra\u00e9liennes et Palestiniens sur le mont du Temple<\/strong><br \/>\n<\/span><\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nrc.nl\/nieuws\/2023\/04\/09\/israel-schiet-met-raketten-en-artillerie-op-syrie-als-vergelding-van-raketaanvallen-golanhoogvlakte-a4161662\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-33<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Isra\u00ebl a lanc\u00e9 des tirs de roquettes et d&#8217;artillerie contre la Syrie dimanche matin en repr\u00e9sailles \u00e0 une attaque syrienne \u00e0 la roquette samedi soir. C&#8217;est ce que rapportent les agences de presse internationales. Pour autant que l&#8217;on sache, le bombardement n&#8217;a co\u00fbt\u00e9 aucune vie. Vers 22 heures samedi, des responsables militaires isra\u00e9liens ont affirm\u00e9, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":680588,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[8074,507,133,155511,68564,6012,6720,65,13031,8196,6843,60,26390,3193],"class_list":["post-680587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-attaques","tag-aux","tag-des","tag-golan","tag-hauteurs","tag-israel","tag-lartillerie","tag-les","tag-represailles","tag-roquette","tag-roquettes","tag-sur","tag-syrie","tag-tire"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/680587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=680587"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/680587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/680588"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=680587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=680587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=680587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}