{"id":679029,"date":"2023-04-08T04:55:46","date_gmt":"2023-04-08T06:55:46","guid":{"rendered":"https:\/\/teknomers.com\/fr\/cest-ainsi-que-le-ministre-suisse-de-la-justice-justifie-la-situation-exceptionnelle-entourant-le-rachat-du-credit-suisse-par-ubs\/"},"modified":"2023-04-08T04:55:51","modified_gmt":"2023-04-08T06:55:51","slug":"cest-ainsi-que-le-ministre-suisse-de-la-justice-justifie-la-situation-exceptionnelle-entourant-le-rachat-du-credit-suisse-par-ubs","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/cest-ainsi-que-le-ministre-suisse-de-la-justice-justifie-la-situation-exceptionnelle-entourant-le-rachat-du-credit-suisse-par-ubs\/","title":{"rendered":"C&#8217;est ainsi que le ministre suisse de la Justice justifie la situation exceptionnelle entourant le rachat du Credit Suisse par UBS"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"news-container\">\n<div class=\"dropdown-container-chartflow relative\" style=\"display: none;\">\n<div class=\"row\" style=\"padding:10px;\">\n<p><h3 class=\"box-headline\" style=\"margin:0px;\">partages dans cet article<\/h3>\n<\/p>\n<div class=\"col-xs-2 col-sm-1 pointer\" onclick=\"$('.dropdown-container-chartflow').toggle();\"><\/div>\n<div class=\"col-xs-6 col-sm-3 no-padding-sm-right chart-block relative\">UBS<\/p>\n<p>18,73 euros<br \/>1,08 %<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA\" data-original=\"https:\/\/c.finanzen.net\/cst\/FinanzenDe\/chart.aspx?instruments=4,24476758,4,1&amp;style=mini_mountain_white_135x60&amp;period=OneYear&amp;hash=f34ef9dd401146d38bda805e1aedbaa0\" width=\"135\" height=\"60\" alt=\"Graphique A12DFH\" style=\"height: 60px\"\/><\/div>\n<\/div>\n<\/div>\n<p>\u2022 Le ministre de la Justice Baume-Schneider d\u00e9fend l&#8217;atteinte aux droits des actionnaires <br \/>\n\u2022 Baume-Schneider : &#8220;La meilleure solution&#8221; &#8211; la faillite aurait \u00e9t\u00e9 une &#8220;catastrophe&#8221; <br \/>\n\u2022 R\u00e9\u00e9valuation politique n\u00e9cessaire <\/p>\n<p>Le 19 mars, il a \u00e9t\u00e9 annonc\u00e9 qu&#8217;UBS reprendrait le Credit Suisse en faillite pour un prix d&#8217;achat de trois milliards de francs suisses.  La Banque nationale suisse (BNS) a promis aux deux banques un soutien en liquidit\u00e9s de 100 milliards de francs chacune \u00e0 la suite de la crise.  Alors que de nombreux banquiers et investisseurs internationaux sont soulag\u00e9s par cette \u00e9volution &#8211; apr\u00e8s tout, il aurait peut-\u00eatre \u00e9t\u00e9 possible d&#8217;\u00e9viter des bouleversements encore plus d\u00e9sastreux dans le secteur financier &#8211; certains critiques ont trouv\u00e9 des mots durs pour le manque d&#8217;implication des actionnaires des deux banques dans cette processus d\u00e9cisionnel important.  Selon les lois suisses sur les actionnaires, les reprises de soci\u00e9t\u00e9s doivent \u00eatre convenues avec les actionnaires lors d&#8217;une assembl\u00e9e g\u00e9n\u00e9rale extraordinaire.<br \/>\n<!-- sh_cad_2 --><\/p>\n<h2>Baume-Schneider : &#8220;C&#8217;\u00e9tait la meilleure solution&#8221;<\/h2>\n<p>Cependant, le Conseil f\u00e9d\u00e9ral a appliqu\u00e9 une loi d&#8217;urgence qui permet une intervention dans les droits des actionnaires dans des situations exceptionnelles.  La ministre suisse de la Justice, Elisabeth Baume-Schneider, justifie cette mesure drastique dans l&#8217;\u00e9mission de radio SRF &#8220;Tagessprach&#8221;.  Juridiquement, la d\u00e9cision \u00e9tait irr\u00e9prochable puisque la condition d&#8217;urgence \u00e9tait remplie.  Une faillite du CS d&#8217;importance syst\u00e9mique aurait eu des effets encore pires.  &#8220;S&#8217;il y avait eu faillite, les actionnaires seraient dans une situation encore plus difficile&#8221;, a d\u00e9clar\u00e9 le conseiller f\u00e9d\u00e9ral.  Un effondrement de CS &#8220;aurait \u00e9t\u00e9 une catastrophe dans le pays et \u00e0 l&#8217;\u00e9tranger&#8221;.  De plus, il y a toujours un risque pour les actionnaires avec leurs investissements.  &#8220;C&#8217;\u00e9tait la meilleure solution&#8221;, assure Baume-Schneider.<\/p>\n<p>Le PDG de CS, Ulrich K\u00f6rner, qui a d\u00e9fendu le rachat de CS par UBS dans une lettre \u00e0 ses employ\u00e9s, a une opinion similaire.  Dans le m\u00eame temps, K\u00f6rner a soulign\u00e9 qu&#8217;il restait &#8220;pleinement engag\u00e9&#8221; envers la banque.  &#8220;Je serai \u00e0 vos c\u00f4t\u00e9s pendant que nous travaillons pour faire de la transaction un succ\u00e8s&#8221;, a affirm\u00e9 le g\u00e9rant.<!-- sh_cad_4 --><\/p>\n<h2>Une r\u00e9\u00e9valuation politique n\u00e9cessaire<\/h2>\n<p>Dans la suite de l&#8217;interview, le ministre de la Justice Baume-Schneider a soulign\u00e9 l&#8217;importance du traitement politique de la grave crise du CS.  La fin laide de la grande banque a en fait r\u00e9v\u00e9l\u00e9 des v\u00e9rit\u00e9s inconfortables sur l&#8217;industrie financi\u00e8re suisse.  L&#8217;autorit\u00e9 suisse de surveillance financi\u00e8re FINMA a d\u00e9j\u00e0 ouvert une enqu\u00eate sur CS.  Selon Baume-Schneider, la crise du CS a \u00e9galement montr\u00e9 qu&#8217;un manque de confiance de la part des clients des banques ne pouvait \u00eatre contrecarr\u00e9 par un grand syst\u00e8me de s\u00e9curit\u00e9 juridique.  &#8220;Ensuite, ce sera g\u00e9n\u00e9ralement difficile&#8221;, explique Baume-Schneider.  Le retrait de milliards de fonds de clients CS pouvait difficilement \u00eatre arr\u00eat\u00e9 apr\u00e8s que la r\u00e9putation de la grande banque ait \u00e9t\u00e9 entach\u00e9e par un certain nombre de scandales graves &#8211; des fonds Greensill au scandale Acegos et \u00e0 la filature de l&#8217;ancien top manager Iqbal Khan.  Il faut maintenant discuter de ce que l&#8217;UBS nouvellement cr\u00e9\u00e9e signifie pour le pays en tant que banque encore plus grande.\n<\/p>\n<h2>UBS fait face \u00e0 des t\u00e2ches difficiles<\/h2>\n<p>En fait, UBS fait face \u00e0 d&#8217;\u00e9normes d\u00e9fis.  La plus grande banque suisse s&#8217;est \u00e0 nouveau consid\u00e9rablement d\u00e9velopp\u00e9e et est d\u00e9sormais de loin le num\u00e9ro un du secteur financier suisse.  Dans les mois \u00e0 venir, il s&#8217;agira d&#8217;ancrer la situation financi\u00e8re parfois effrayante de CS dans le profil stable en soi d&#8217;UBS.  Les premiers analystes ont d\u00e9j\u00e0 fait part de leurs inqui\u00e9tudes face \u00e0 cette situation difficile.  Par exemple, la banque canadienne Royal Bank of Canada (RBC) a abaiss\u00e9 sa note UBS de &#8220;Outperform&#8221; \u00e0 &#8220;Sector Perform&#8221; et a abaiss\u00e9 l&#8217;objectif de cours de 24 \u00e0 20 francs.  Reste donc \u00e0 savoir si le prix d&#8217;achat r\u00e9ellement bas de trois milliards de francs pour UBS n&#8217;entra\u00eenera pas des co\u00fbts \u00e9normes.\n<\/p>\n<p>Bureau \u00e9ditorial finanzen.net\n<\/p>\n<div class=\"lvgSearchOuter\"><span class=\"font-bold\">Produits \u00e0 effet de levier s\u00e9lectionn\u00e9s sur Credit Suisse GroupShs Sponsored American Deposit.Receipts Repr. 1 Sh<\/span>Avec les knock-outs, les investisseurs sp\u00e9culatifs peuvent participer de mani\u00e8re disproportionn\u00e9e aux mouvements de prix.  S\u00e9lectionnez simplement l&#8217;effet de levier souhait\u00e9 et nous vous montrerons les produits ouverts appropri\u00e9s sur Credit Suisse GroupShs Sponsored American Deposit.Receipts Repr. 1 Sh<\/p>\n<div class=\"row\">\n<div class=\"col-xs-12\">\n<p>L&#8217;effet de levier doit \u00eatre compris entre 2 et 20<\/p>\n<\/div>\n<\/div>\n<p>Pas de donn\u00e9es<\/p>\n<\/div>\n<p><!--CenterColumn_1--><\/p>\n<div class=\"\">\n<h2 class=\"box-headline\">Plus d&#8217;actualit\u00e9s li\u00e9es \u00e0 Credit Suisse GroupShs Sponsored American Deposit.Receipts Repr. 1 Sh<\/h2>\n<\/div>\n<p>Sources des images : Pincasso \/ Shutterstock.com, Simon Zenger \/ Shutterstock.com<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.finanzen.net\/nachricht\/aktien\/anwendung-des-notrechts-so-rechtfertigt-die-schweizer-justizministerin-die-ausnahmesituation-rund-um-die-uebernahme-der-credit-suisse-durch-ubs-12310759\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-28<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>partages dans cet article UBS 18,73 euros1,08 % \u2022 Le ministre de la Justice Baume-Schneider d\u00e9fend l&#8217;atteinte aux droits des actionnaires \u2022 Baume-Schneider : &#8220;La meilleure solution&#8221; &#8211; la faillite aurait \u00e9t\u00e9 une &#8220;catastrophe&#8221; \u2022 R\u00e9\u00e9valuation politique n\u00e9cessaire Le 19 mars, il a \u00e9t\u00e9 annonc\u00e9 qu&#8217;UBS reprendrait le Credit Suisse en faillite pour un prix [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":679030,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1821,1820,49,29484,15942,460,7813,944,164,4710,650,7173,20413],"class_list":["post-679029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finance","tag-ainsi","tag-cest","tag-credit","tag-entourant","tag-exceptionnelle","tag-justice","tag-justifie","tag-ministre","tag-par","tag-rachat","tag-situation","tag-suisse","tag-ubs"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/679029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=679029"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/679029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/679030"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=679029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=679029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=679029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}