{"id":677485,"date":"2023-04-07T05:18:55","date_gmt":"2023-04-07T07:18:55","guid":{"rendered":"https:\/\/teknomers.com\/fr\/action-de-teck-resources-loffre-de-glencore-sur-teck-risque-de-se-heurter-a-la-resistance-dun-important-actionnaire-japonais\/"},"modified":"2023-04-07T05:18:58","modified_gmt":"2023-04-07T07:18:58","slug":"action-de-teck-resources-loffre-de-glencore-sur-teck-risque-de-se-heurter-a-la-resistance-dun-important-actionnaire-japonais","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/action-de-teck-resources-loffre-de-glencore-sur-teck-risque-de-se-heurter-a-la-resistance-dun-important-actionnaire-japonais\/","title":{"rendered":"Action de Teck Resources\u00a0: l&#8217;offre de Glencore sur Teck risque de se heurter \u00e0 la r\u00e9sistance d&#8217;un important actionnaire japonais"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"news-container\">\n<div class=\"dropdown-container-chartflow relative\" style=\"display: none;\">\n<div class=\"row\" style=\"padding:10px;\">\n<p><h3 class=\"box-headline\" style=\"margin:0px;\">partages dans cet article<\/h3>\n<\/p>\n<div class=\"col-xs-2 col-sm-1 pointer\" onclick=\"$('.dropdown-container-chartflow').toggle();\"><\/div>\n<\/div>\n<\/div>\n<p>Le journal japonais &#8220;Globe and Mail&#8221; a rapport\u00e9 jeudi saint que le japonais Sumitomo Metal Mining avait refus\u00e9 une rencontre avec Glencore pour discuter de l&#8217;OPA.<\/p>\n<p>Avec la famille Keevil, Sumitomo d\u00e9tient les actions A avec droit de vote et donc la majorit\u00e9 de contr\u00f4le de Teck Resources, a ajout\u00e9 le journal.  Sumitomo ne veut m\u00eame pas parler \u00e0 Glencore, a d\u00e9clar\u00e9 un confident de Keevil, selon le journal.  Une prise de contr\u00f4le de Teck ne serait pas possible sans le consentement de la famille Keevil et des Japonais.<!-- sh_cad_2 --><\/p>\n<p>Glencore a lanc\u00e9 lundi une offre publique d&#8217;achat de 23 milliards de dollars sur Teck.  C&#8217;est une prime de 22% par rapport au cours de cl\u00f4ture de la semaine pr\u00e9c\u00e9dente.  La transaction, qui pr\u00e9voit entre autres la scission de l&#8217;activit\u00e9 charbonni\u00e8re combin\u00e9e en une nouvelle soci\u00e9t\u00e9, s&#8217;est heurt\u00e9e \u00e0 la r\u00e9sistance de Teck.<\/p>\n<p>Le conseil d&#8217;administration de Teck a rejet\u00e9 les plans de Glencore dans une d\u00e9claration s\u00e9par\u00e9e.  L&#8217;offre a \u00e9t\u00e9 rejet\u00e9e sans vote dissident et la vente de l&#8217;entreprise n&#8217;\u00e9tait pas une option \u00e0 ce stade.<!-- sh_cad_4 --><\/p>\n<p>Cela \u00e9tait principalement justifi\u00e9 par le fait que les actionnaires de Teck seraient impliqu\u00e9s dans le n\u00e9goce de charbon et de p\u00e9trole, ce qui contredit les obligations ESG et rec\u00e8le des risques juridiques consid\u00e9rables.  Teck souhaite plut\u00f4t se scinder en Teck Metals et Elk Valley Resources et ainsi se concentrer respectivement sur le charbon et les m\u00e9taux de base.<\/p>\n<p>&#8220;Je reste enti\u00e8rement derri\u00e8re les plans propos\u00e9s par Teck pour cr\u00e9er deux soci\u00e9t\u00e9s ind\u00e9pendantes et je soutiens la d\u00e9cision du conseil d&#8217;administration contre l&#8217;offre de Glencore&#8221;, a d\u00e9clar\u00e9 Norman Keevil dans un communiqu\u00e9.<\/p>\n<p>\/jb\/AWP\/il<\/p>\n<p>BAAR (dpa-AFX)<\/p>\n<div class=\"lvgSearchOuter\"><span class=\"font-bold\">S\u00e9lectionnez des produits \u00e0 effet de levier sur Glencore plc<\/span>Avec les knock-outs, les investisseurs sp\u00e9culatifs peuvent participer de mani\u00e8re disproportionn\u00e9e aux mouvements de prix.  S\u00e9lectionnez simplement l&#8217;effet de levier souhait\u00e9 et nous vous montrerons les produits open-end appropri\u00e9s sur Glencore plc<\/p>\n<div class=\"row\">\n<div class=\"col-xs-12\">\n<p>L&#8217;effet de levier doit \u00eatre compris entre 2 et 20<\/p>\n<\/div>\n<\/div>\n<p>Pas de donn\u00e9es<\/p>\n<\/div>\n<p><!--CenterColumn_1--><\/p>\n<div class=\"\">\n<h2 class=\"box-headline\">Plus d&#8217;actualit\u00e9s sur Glencore plc<\/h2>\n<\/div>\n<p>Sources des images : 360b \/ Shutterstock.com, Glencore<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.finanzen.net\/nachricht\/aktien\/abspaltung-von-kohlegeschaeft-teck-resources-aktie-glencore-kaufangebot-fuer-teck-stoesst-wohl-auf-widerstand-von-japanischem-grossaktionaer-12334284\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-28<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>partages dans cet article Le journal japonais &#8220;Globe and Mail&#8221; a rapport\u00e9 jeudi saint que le japonais Sumitomo Metal Mining avait refus\u00e9 une rencontre avec Glencore pour discuter de l&#8217;OPA. Avec la famille Keevil, Sumitomo d\u00e9tient les actions A avec droit de vote et donc la majorit\u00e9 de contr\u00f4le de Teck Resources, a ajout\u00e9 le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":677486,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1063,5007,74,69474,23341,8411,28031,15492,6355,69705,326,60,147371],"class_list":["post-677485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finance","tag-action","tag-actionnaire","tag-dun","tag-glencore","tag-heurter","tag-important","tag-japonais","tag-loffre","tag-resistance","tag-resources","tag-risque","tag-sur","tag-teck"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/677485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=677485"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/677485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/677486"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=677485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=677485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=677485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}