{"id":673799,"date":"2023-04-05T02:56:43","date_gmt":"2023-04-05T04:56:43","guid":{"rendered":"https:\/\/teknomers.com\/fr\/marches-asie-bourses-incoherentes-les-inquietudes-sur-leconomie-augmentent\/"},"modified":"2023-04-05T02:56:46","modified_gmt":"2023-04-05T04:56:46","slug":"marches-asie-bourses-incoherentes-les-inquietudes-sur-leconomie-augmentent","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/marches-asie-bourses-incoherentes-les-inquietudes-sur-leconomie-augmentent\/","title":{"rendered":"MARCH\u00c9S ASIE\/Bourses incoh\u00e9rentes &#8211; Les inqui\u00e9tudes sur l&#8217;\u00e9conomie augmentent"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"news-container\">\n<div class=\"dropdown-container-chartflow relative\" style=\"display: none;\">\n<div class=\"row\" style=\"padding:10px;\">\n<p><h3 class=\"box-headline\" style=\"margin:0px;\">partages dans cet article<\/h3>\n<\/p>\n<div class=\"col-xs-2 col-sm-1 pointer\" onclick=\"$('.dropdown-container-chartflow').toggle();\"><\/div>\n<p><h3 class=\"box-headline\" style=\"margin:0px;\">index dans cet article<\/h3>\n<\/p>\n<\/div>\n<\/div>\n<p>  TOKYO (Dow Jones) \u2013 Alors que les bourses chinoises, y compris celles de Hong Kong, sont ferm\u00e9es pour un jour f\u00e9ri\u00e9, les autres places boursi\u00e8res ne peuvent pas d\u00e9cider d&#8217;une direction claire.  La situation des nouvelles parle plut\u00f4t contre l&#8217;achat d&#8217;actions.  D&#8217;une part, les donn\u00e9es \u00e9conomiques actuelles alimentent les inqui\u00e9tudes \u00e9conomiques aux \u00c9tats-Unis.  Dans le m\u00eame temps, les banques centrales continuent d&#8217;augmenter les taux d&#8217;int\u00e9r\u00eat dans la lutte contre l&#8217;inflation.  La banque centrale n\u00e9o-z\u00e9landaise a relev\u00e9 son taux directeur de 50 points de base, ce qui est un peu plus que pr\u00e9vu.  On dit que la hausse des taux d&#8217;int\u00e9r\u00eat et la m\u00e9diocrit\u00e9 des donn\u00e9es \u00e9conomiques ne vont pas vraiment de pair. <\/p>\n<p>  Cela est particuli\u00e8rement \u00e9vident au Japon, o\u00f9 le Nikkei 225 a chut\u00e9 de 1,6 % \u00e0 27 831 points.  Peu importe que la banque centrale locale ait parl\u00e9 de son ultra-loose <!--#BNL#topicId#225-->politique mon\u00e9taire<!--#ENL--> ne s&#8217;est pas retir\u00e9 jusqu&#8217;\u00e0 pr\u00e9sent.  Le march\u00e9 boursier japonais est accabl\u00e9 par le yen ferme, qui a consid\u00e9rablement augment\u00e9 par rapport au dollar am\u00e9ricain apr\u00e8s les faibles donn\u00e9es am\u00e9ricaines de la veille.  La force du yen au Japon affecte principalement la valeur des exportations, avec Subaru en baisse de 1,9% et Nippon Steel en baisse de 2,2%.  Les actions bancaires perdent \u00e9galement beaucoup, les commer\u00e7ants signalent des taux d&#8217;int\u00e9r\u00eat du march\u00e9 nettement plus bas aux \u00c9tats-Unis. <!-- sh_cad_2 --><\/p>\n<p>  Kospi nettement plus ferme que Nikkei <\/p>\n<p>  En Cor\u00e9e du Sud, en revanche, le Kospi a augment\u00e9 de 0,4 %.  Le march\u00e9 mise sur une reprise \u00e9conomique en Chine et ignore quelque peu la faiblesse des donn\u00e9es am\u00e9ricaines, disent-ils.  Parce que les valeurs d&#8217;exportation de Hyundai Motor et Kia du secteur automobile augmentent respectivement de 1,2 et 1,3 %.  Les deux constructeurs avaient publi\u00e9 de solides chiffres de ventes pour le premier trimestre. <\/p>\n<p>  L&#8217;indice phare australien S&#038;P\/ASX-200 affiche une d\u00e9cote de 0,1 %.  Comme au Japon, les maigres perspectives \u00e9conomiques aux \u00c9tats-Unis sont d\u00e9primantes.  Aussi le plus \u00e9lev\u00e9 de fa\u00e7on inattendue <!--#BNL#topicId#274-->hausse des taux<!--#ENL--> en Nouvelle-Z\u00e9lande, alors que la banque centrale australienne vient de faire une pause dans la hausse des taux d&#8217;int\u00e9r\u00eat, ne d\u00e9clenche aucune impulsion d&#8217;achat.  En g\u00e9n\u00e9ral, le march\u00e9 boursier australien a tendance \u00e0 prendre des b\u00e9n\u00e9fices &#8211; apr\u00e8s une s\u00e9quence de sept victoires cons\u00e9cutives, dit-on.  Pendant ce temps, le dollar n\u00e9o-z\u00e9landais a atteint ses plus hauts niveaux depuis la mi-f\u00e9vrier et les rendements obligataires augmentent \u00e9galement en Nouvelle-Z\u00e9lande. <!-- sh_cad_4 --><\/p>\n<p>=== <\/p>\n<p>Dernier indice (boursier) +\/- % % fin YTD <\/p>\n<p>S&#038;P\/ASX 200 (Sydney) 7 231,60 -0,1 % +2,7 % 08:00 <\/p>\n<p>Nikkei-225 (Tokyo) 27 824,53 -1,6% +8,4% 08:00 <\/p>\n<p>Kospi (S\u00e9oul) 2 493,05 +0,5% +11,5% 08h00 <\/p>\n<p>Shanghai Comp.  Vacances <!-- sh_cad_6 --><\/p>\n<p>Vacances Hang Seng (Hongk.) <\/p>\n<p>Straits-Times (Sing.) 3 327,04 +0,5% +0,9% 11:00 <\/p>\n<p>KLCI (Malaisie) 1 426,52 -0,2% -4,4% 11:00 <!-- sh_cad_7 --><\/p>\n<p>FOREX dernier +\/- % 00:00 Mar, 8:42 % YTD <\/p>\n<p>EUR\/USD 1,0955 -0,0% 1,0955 1,0905 +2,3% <\/p>\n<p>EUR\/JPY 144,29 -0,0% 144,32 144,66 +2,8% <!-- sh_cad_8 --><\/p>\n<p>EUR\/GBP 0,8774 +0,1% 0,8763 0,8777 -0,9% <\/p>\n<p>GBP\/USD 1,2485 -0,1% 1,2502 1,2424 +3,2% <\/p>\n<p>USD\/JPY 131,71 -0,0% 131,74 132,66 +0,5% <!-- sh_cad_9 --><\/p>\n<p>USD\/KRW 1 313,83 +0,1 % 1 312,19 1 314,94 +4,1 % <\/p>\n<p>USD\/CNY 6,8798 +0,0% 6,8798 6,8815 -0,3% <\/p>\n<p>USD\/CNH 6,8716 -0,1% 6,8790 6,8828 -0,8% <!-- sh_cad_10 --><\/p>\n<p>USD\/HKD 7,8498 +0,0% 7,8494 7,8493 +0,5% <\/p>\n<p>AUD\/USD 0,6746 -0,3% 0,6768 0,6769 -1,0% <\/p>\n<p>NZD\/USD 0,6346 +0,6% 0,6312 0,6309 -0,1% <!-- sh_cad_11 --><\/p>\n<p>Bitcoin <\/p>\n<p>BTC\/USD 28 541,48 +1,1% 28 221,98 28 009,13 +71,9% <\/p>\n<p>P\u00c9TROLE BRUT dernier r\u00e8glement VT.  +\/- % +\/- USD % YTD <!-- sh_cad_12 --><\/p>\n<p>WTI\/Nymex 81,00 80,71 +0,4% +0,29 +0,7% <\/p>\n<p>Brent\/ICE 85,29 84,94 +0,4% +0,35 +0,5% <\/p>\n<p>M\u00c9TAUX dernier jour avant +\/- % +\/- USD % YTD <!-- sh_cad_13 --><\/p>\n<p>Or (au comptant) 2 022,68 2 020,41 +0,1 % +2,27 +10,9 % <\/p>\n<p>Argent (au comptant) 25,03 25,03 0 % 0 +4,4 % <\/p>\n<p>Platine (Spot) 1 027,55 1 022,00 +0,5 % +5,55 -3,8 % <!-- sh_cad_14 --><\/p>\n<p>Avenir Cuivre 3,96 3,97 -0,2% -0,01 +3,9% <\/p>\n<p>YTD bas\u00e9 sur le cours de cl\u00f4ture de la veille <\/p>\n<p>=== <\/p>\n<p>  Contactez l&#8217;auteur : maerkte.de@dowjones.com <!-- sh_cad_15 --><\/p>\n<p>  DJG\/DJN\/flf\/ros <\/p>\n<p>  (FIN) Fil de presse Dow Jones<\/p>\n<p>  05 avril 2023 00h49 HE (04h49 \u200b\u200bGMT)<\/p>\n<div class=\"lvgSearchOuter\"><span class=\"font-bold\">Produits \u00e0 effet de levier s\u00e9lectionn\u00e9s sur Hyundai Motor Co Ltd.  (sponsoris\u00e9 par la RDA)<\/span>Avec les knock-outs, les investisseurs sp\u00e9culatifs peuvent participer de mani\u00e8re disproportionn\u00e9e aux mouvements de prix.  S\u00e9lectionnez simplement le levier souhait\u00e9 et nous vous montrerons les produits ouverts adapt\u00e9s sur Hyundai Motor Co Ltd.  (sponsoris\u00e9 par la RDA)<\/p>\n<div class=\"row\">\n<div class=\"col-xs-12\">\n<p>L&#8217;effet de levier doit \u00eatre compris entre 2 et 20<\/p>\n<\/div>\n<\/div>\n<p>Pas de donn\u00e9es<\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.finanzen.net\/nachricht\/aktien\/maerkte-asien-uneinheitliche-boersen-konjunktursorgen-steigen-12327168\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-28<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>partages dans cet article index dans cet article TOKYO (Dow Jones) \u2013 Alors que les bourses chinoises, y compris celles de Hong Kong, sont ferm\u00e9es pour un jour f\u00e9ri\u00e9, les autres places boursi\u00e8res ne peuvent pas d\u00e9cider d&#8217;une direction claire. La situation des nouvelles parle plut\u00f4t contre l&#8217;achat d&#8217;actions. D&#8217;une part, les donn\u00e9es \u00e9conomiques actuelles [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":577397,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[55935,2673,40875,4816,882,65,4417,60],"class_list":["post-673799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finance","tag-asiebourses","tag-augmentent","tag-incoherentes","tag-inquietudes","tag-leconomie","tag-les","tag-marches","tag-sur"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/673799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=673799"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/673799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/577397"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=673799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=673799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=673799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}