{"id":637446,"date":"2023-03-05T04:59:05","date_gmt":"2023-03-05T06:59:05","guid":{"rendered":"https:\/\/teknomers.com\/fr\/lepisode-dautomne-a-ouvert-les-coffres-verbaux-des-telespectateurs-dites-ce-que-vous-dites\/"},"modified":"2023-03-05T04:59:07","modified_gmt":"2023-03-05T06:59:07","slug":"lepisode-dautomne-a-ouvert-les-coffres-verbaux-des-telespectateurs-dites-ce-que-vous-dites","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/lepisode-dautomne-a-ouvert-les-coffres-verbaux-des-telespectateurs-dites-ce-que-vous-dites\/","title":{"rendered":"L&#8217;\u00e9pisode d&#8217;automne a ouvert les coffres verbaux des t\u00e9l\u00e9spectateurs : &#8220;Dites ce que vous dites&#8221;"},"content":{"rendered":"\n<p>Les t\u00e9l\u00e9spectateurs se sont r\u00e9chauff\u00e9s avec les sketchs et les invit\u00e9s de Putous.  La saison des \u00e9liminations a de nouveau progress\u00e9 jusqu&#8217;\u00e0 la fin, lorsque le duo final a surv\u00e9cu dans l&#8217;\u00e9pisode de samedi soir.  Le personnage de K\u00f6pi Kallio, Kari Mutan, et le personnage d&#8217;Aku Sipola, Mainos-Harri, ont \u00e9t\u00e9 \u00e9lus pour la finale.  Le personnage de Joonas K\u00e4\u00e4ri\u00e4inen, Esteri Vakkilainen, a abandonn\u00e9 la course dans les derniers m\u00e8tres.<br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.iltalehti.fi\/tv-ja-leffat\/a\/3617d904-dcdf-4c4e-a083-fe0bd5f61c3b\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-50<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les t\u00e9l\u00e9spectateurs se sont r\u00e9chauff\u00e9s avec les sketchs et les invit\u00e9s de Putous. La saison des \u00e9liminations a de nouveau progress\u00e9 jusqu&#8217;\u00e0 la fin, lorsque le duo final a surv\u00e9cu dans l&#8217;\u00e9pisode de samedi soir. Le personnage de K\u00f6pi Kallio, Kari Mutan, et le personnage d&#8217;Aku Sipola, Mainos-Harri, ont \u00e9t\u00e9 \u00e9lus pour la finale. Le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":637447,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[12884,16424,20848,133,15354,9995,65,3246,886,1824,2980,887,9065,888,98130,188],"class_list":["post-637446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-24-heures","tag-coffres","tag-dautomne","tag-des","tag-dites","tag-lepisode","tag-les","tag-medias-audiovisuels","tag-medias-electriques","tag-ouvert","tag-programmes-de-television-finlandais","tag-programmes-tv","tag-telespectateurs","tag-television-et-films","tag-verbaux","tag-vous"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/637446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=637446"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/637446\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/637447"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=637446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=637446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=637446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}