{"id":630945,"date":"2023-03-01T05:42:39","date_gmt":"2023-03-01T07:42:39","guid":{"rendered":"https:\/\/teknomers.com\/fr\/amendes-de-supporters-et-interdiction-des-tribunes-pour-insulte-raciale-a-vinicius\/"},"modified":"2023-03-01T05:42:41","modified_gmt":"2023-03-01T07:42:41","slug":"amendes-de-supporters-et-interdiction-des-tribunes-pour-insulte-raciale-a-vinicius","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/amendes-de-supporters-et-interdiction-des-tribunes-pour-insulte-raciale-a-vinicius\/","title":{"rendered":"Amendes de supporters et interdiction des tribunes pour insulte raciale \u00e0 Vinicius"},"content":{"rendered":"\n<div id=\"\">&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p>En Espagne, la Commission permanente d&#8217;\u00c9tat sur la violence, le racisme, la x\u00e9nophobie et l&#8217;intol\u00e9rance dans les sports a inflig\u00e9 une amende et interdit un fan qui s&#8217;est av\u00e9r\u00e9 avoir insult\u00e9 racialement le joueur de football du Real Madrid Vinicius Junior lors du match Majorque-Real Madrid.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>La commission affili\u00e9e au Conseil supr\u00eame des sports a annonc\u00e9 sa d\u00e9cision concernant les supporters accus\u00e9s d&#8217;avoir insult\u00e9 racialement le footballeur br\u00e9silien du Real Madrid Vinicius depuis les tribunes lors du match Majorque-Real Madrid disput\u00e9 dans la 1\u00e8re Ligue espagnole de football le 5 f\u00e9vrier.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>La commission a impos\u00e9 une interdiction de toutes les comp\u00e9titions sportives pendant 12 mois avec une amende de 4 000 euros aux supporters qui ont commis un acte raciste.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Concernant le fan en question, la police nationale espagnole a exig\u00e9 une amende de 3 000 euros et une interdiction de comp\u00e9titions sportives de 6 mois.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>En revanche, la commission a d\u00e9clar\u00e9 le match Barcelone-Real Madrid, qui se jouera en championnat le 19 mars, &#8220;\u00e0 haut risque&#8221;.<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n                    &#13;<br \/>\n&#13;\n                <\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.fotomac.com.tr\/realmadrid\/2023\/03\/01\/viniciusa-irkci-hakaret-eden-taraftara-para-ve-tribunlerden-men-cezasi\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-7<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#13; &#13; &#13; En Espagne, la Commission permanente d&#8217;\u00c9tat sur la violence, le racisme, la x\u00e9nophobie et l&#8217;intol\u00e9rance dans les sports a inflig\u00e9 une amende et interdit un fan qui s&#8217;est av\u00e9r\u00e9 avoir insult\u00e9 racialement le joueur de football du Real Madrid Vinicius Junior lors du match Majorque-Real Madrid. &#13; &#13; La commission affili\u00e9e au [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":630946,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2428,1496,110498,133,1363,69930,14048,6555,14544,149023,185,39569,1527,4831,2282,27307,27306],"class_list":["post-630945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-amendes","tag-barcelone","tag-conseil-superieur-du-sport","tag-des","tag-espagne","tag-espagne-1","tag-insulte","tag-interdiction","tag-majorque","tag-police-nationale-espagnole","tag-pour","tag-raciale","tag-real-madrid","tag-supporters","tag-tribunes","tag-vinicius","tag-vinicius-junior"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/630945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=630945"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/630945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/630946"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=630945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=630945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=630945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}