{"id":611249,"date":"2023-02-16T19:33:28","date_gmt":"2023-02-16T21:33:28","guid":{"rendered":"https:\/\/teknomers.com\/fr\/maxi-gagnant-au-superenalotto-90-se-partagent-le-jackpot-de-371-millions\/"},"modified":"2023-02-16T19:33:29","modified_gmt":"2023-02-16T21:33:29","slug":"maxi-gagnant-au-superenalotto-90-se-partagent-le-jackpot-de-371-millions","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/maxi-gagnant-au-superenalotto-90-se-partagent-le-jackpot-de-371-millions\/","title":{"rendered":"Maxi-gagnant au Superenalotto, 90 se partagent le jackpot de 371 millions"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>\u00c9couter la version audio de l&#8217;article<\/button><\/p>\n<p class=\"atext\">6 des records du Superenalotto ont \u00e9t\u00e9 atteints.  A remport\u00e9 371 millions d&#8217;euros &#8211; pour \u00eatre exact 371 133 424,51 euros &#8211; le plus gros jackpot du monde.  Le sextupl\u00e9 gagnant \u00e9tait : 1, 38, 47, 52, 56, 66. Jolly 72 &#8211; SuperStar 23. La victoire a \u00e9t\u00e9 obtenue via le tableau d&#8217;affichage des syst\u00e8mes en distribuant le jackpot sur 90 cartes.  Chaque gagnant remporte environ 4 millions d&#8217;euros, avec un co\u00fbt de 5 euros pour chacun.<\/p>\n<p class=\"atext\">Jeudi soir est la premi\u00e8re victoire de 2023, la plus \u00e9lev\u00e9e de l&#8217;histoire du jeu et, actuellement, \u00e9galement de toutes les loteries du monde.  Avec celui de ce soir il y a 125 victoires avec 6 points pris depuis la naissance de SuperEnalotto, le 3 d\u00e9cembre il y a 25 ans.  Les 6 \u00e9taient port\u00e9s disparus depuis le 22 mai 2021, date \u00e0 laquelle 156 millions d&#8217;euros avaient \u00e9t\u00e9 remport\u00e9s \u00e0 Montappone, un village de la province de Fermo.<\/p>\n<p class=\"atext\">La Campanie \u00e9tait la r\u00e9gion reine du \u00ab 6 \u00bb des records.  Sur 90, il y a 14 gains millionnaires r\u00e9sultant d&#8217;autant d&#8217;actions achet\u00e9es dans la r\u00e9gion.  Agimeg le signale.  Le record national appartient au Bar Paradiso di Stelle, \u00e0 Atripalda, dans la province d&#8217;Avellino, o\u00f9 6 millions d&#8217;actions ont \u00e9t\u00e9 vendues chacune pour plus de 4 millions d&#8217;euros.<\/p>\n<p class=\"atext\">C&#8217;est ainsi que les 90 gains, d&#8217;une valeur chacun de 4 123 704,71 euros, ont \u00e9t\u00e9 r\u00e9partis dans les r\u00e9gions italiennes : Campanie 14, Frioul-V\u00e9n\u00e9tie Julienne 9, Sicile 9, Calabre 9, Marche 7, Latium 7, selon l&#8217;agence Lombardie 7, Pouilles 7, Ligurie 4, Pi\u00e9mont 4, \u00c9milie-Romagne 4, Toscane 3, V\u00e9n\u00e9tie 2, Abruzzes 2, Trentin Haut-Adige 1, Ombrie 1. Sans gains Vall\u00e9e d&#8217;Aoste, Molise, Basilicate et Sardaigne.<\/p>\n<div class=\"acor acor--mkt\">\n<div class=\"\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--isq\" href=\"https:\/\/consigli24.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><\/figure>\n<p><\/a><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/maxi-vincita-superenalotto-90-si-dividono-jackpot-371-milioni-AEI3PYoC\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9couter la version audio de l&#8217;article 6 des records du Superenalotto ont \u00e9t\u00e9 atteints. A remport\u00e9 371 millions d&#8217;euros &#8211; pour \u00eatre exact 371 133 424,51 euros &#8211; le plus gros jackpot du monde. Le sextupl\u00e9 gagnant \u00e9tait : 1, 38, 47, 52, 56, 66. Jolly 72 &#8211; SuperStar 23. La victoire a \u00e9t\u00e9 obtenue [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":611250,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[31816,146384,1610,5937,69869],"class_list":["post-611249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-jackpot","tag-maxigagnant","tag-millions","tag-partagent","tag-superenalotto"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/611249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=611249"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/611249\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/611250"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=611249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=611249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=611249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}