{"id":594721,"date":"2023-02-06T19:25:27","date_gmt":"2023-02-06T21:25:27","guid":{"rendered":"https:\/\/teknomers.com\/fr\/un-appel-a-laide-des-joueurs-de-besiktas-pour-les-victimes-du-tremblement-de-terre\/"},"modified":"2023-02-06T19:25:29","modified_gmt":"2023-02-06T21:25:29","slug":"un-appel-a-laide-des-joueurs-de-besiktas-pour-les-victimes-du-tremblement-de-terre","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/un-appel-a-laide-des-joueurs-de-besiktas-pour-les-victimes-du-tremblement-de-terre\/","title":{"rendered":"Un appel \u00e0 l&#8217;aide des joueurs de Be\u015fikta\u015f pour les victimes du tremblement de terre !"},"content":{"rendered":"\n<div id=\"\">Alors que le douloureux bilan continue de faire peur dans les tremblements de terre ressentis dans de nombreuses provinces, dont l&#8217;\u00e9picentre est Kahramanmara\u015f et surtout \u00e0 Hatay, Gaziantep, Adana, Osmaniye, Diyarbak\u0131r, Malatya et \u015eanl\u0131urfa ;  Les appels \u00e0 l&#8217;aide de la communaut\u00e9 sportive continuent d&#8217;affluer. <\/p>\n<p>Les footballeurs de Be\u015fikta\u015f Cenk Tosun, Josef de Souza, Necip Uysal et Atiba Hutchinson ont appel\u00e9 au soutien des fans de Be\u015fikta\u015f avec les vid\u00e9os qu&#8217;ils ont tourn\u00e9es.<\/p>\n<p>Exprimant qu&#8217;il attend le soutien de tout le monde, Cenk Tosun a d\u00e9clar\u00e9 : \u00ab Condol\u00e9ances \u00e0 tout notre pays. Nous souffrons tous beaucoup, nous sommes vraiment d\u00e9sol\u00e9s. Je souhaite la mis\u00e9ricorde de Dieu sur le d\u00e9funt et mes condol\u00e9ances \u00e0 leurs familles. a lanc\u00e9 une campagne. En collaboration avec l&#8217;AFAD, &#8220;Nous enverrons notre soutien avec nos amis, nous enverrons des fournitures. Vous apportez les fournitures n\u00e9cessaires \u00e0 Vodafone Park, et elles atteindront leur destination. J&#8217;attends votre soutien. Je vous aime beaucoup ,&#8221; il a dit. <\/p>\n<p><strong>JOSEF DE SOUZA : LE PEUPLE TURC EST FORT, PEUT SURMONTER DES SITUATIONS TELLEMENT DIFFICILES<\/strong><\/p>\n<p>Exprimant qu&#8217;il \u00e9tait tr\u00e8s boulevers\u00e9 \u00e0 cause du tremblement de terre, Josef de Souza a d\u00e9clar\u00e9: &#8220;Bonjour les fans de Be\u015fikta\u015f. Je veux partager ma tristesse \u00e0 propos du tremblement de terre qui a eu lieu aujourd&#8217;hui. Tout d&#8217;abord, je fais partie de ce pays et il y avait un trag\u00e9die dont je suis vraiment d\u00e9sol\u00e9. J&#8217;offre mes condol\u00e9ances aux familles de ceux qui ont perdu la vie dans le tremblement de terre. Le peuple turc est fort. , peut surmonter des situations aussi difficiles. Nous aiderons tous ensemble pour des jours meilleurs. Nous devons aider les gens l\u00e0-bas pour cette grande tristesse. Notre club a publi\u00e9 une liste et il y a des fournitures d&#8217;urgence sur cette liste. Vous pouvez donner autant que vous le pouvez. Je le ferai pour moi car l\u00e0-bas &#8220;Les gens ont subi de grandes pertes. Au moins nous peut aider autant que possible \u00e0 compenser ces pertes. Mes pri\u00e8res vont au peuple turc, mes condol\u00e9ances \u00e0 tous \u00bb, a-t-il d\u00e9clar\u00e9. <\/p>\n<p><strong>NECIP UYSAL : NOUS SOMMES TR\u00c8S TRISTES<\/strong><\/p>\n<p>D\u00e9clarant qu&#8217;ils attendent de l&#8217;aide des fans de Be\u015fikta\u015f, Necip Uysal a d\u00e9clar\u00e9: &#8220;Tout d&#8217;abord, mes condol\u00e9ances \u00e0 toute notre nation. Nous sommes tr\u00e8s tristes. En tant que communaut\u00e9 de Be\u015fikta\u015f, nous attendons toute votre aide \u00e0 Vodafone Park avec l&#8217;AFAD.&#8221;<\/p>\n<p><strong>ATIBA HUTCHINSON : SOUTENONS CEUX DANS LE BESOIN EN CES MOMENTS DIFFICILES O\u00d9 LE PAYS EST ENVOY\u00c9<\/strong><\/p>\n<p>Atiba Hutchinson, qui a lanc\u00e9 un appel pour soutenir les personnes dans le besoin dans les moments difficiles, a d\u00e9clar\u00e9 : &#8220;Bonjour \u00e0 tous, comme vous le savez, il y a des gens qui ont \u00e9t\u00e9 tr\u00e8s touch\u00e9s par le tremblement de terre qui a eu lieu hier en Turquie. Je pr\u00e9sente mes condol\u00e9ances aux familles de ceux qui ont perdu la vie. En tant que Be\u015fikta\u015f, nous envoyons nos pri\u00e8res \u00e0 toutes les personnes touch\u00e9es par le tremblement de terre. Nous voulons que tout le monde aide autant que possible. &#8220;Nous voulons qu&#8217;ils soutiennent Vodafone Park. Aidons ceux qui en ont besoin en ces temps difficiles en le pays en faisant don de mat\u00e9riaux \u00e0 Vodafone Park autant que possible. Mes pri\u00e8res accompagnent toutes les personnes touch\u00e9es par le tremblement de terre \u00bb, a-t-il d\u00e9clar\u00e9. <\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n                    &#13;<br \/>\n                        &#13;<br \/>\n&#13;\n                <\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.fotomac.com.tr\/besiktas\/2023\/02\/06\/besiktasli-futbolculardan-depremzedeler-icin-yardim-cagrisi\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-7<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que le douloureux bilan continue de faire peur dans les tremblements de terre ressentis dans de nombreuses provinces, dont l&#8217;\u00e9picentre est Kahramanmara\u015f et surtout \u00e0 Hatay, Gaziantep, Adana, Osmaniye, Diyarbak\u0131r, Malatya et \u015eanl\u0131urfa ; Les appels \u00e0 l&#8217;aide de la communaut\u00e9 sportive continuent d&#8217;affluer. Les footballeurs de Be\u015fikta\u015f Cenk Tosun, Josef de Souza, Necip [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":594722,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[6865,451,71860,299,20836,133,104283,135777,3028,5707,8671,520,143895,1151,65,32066,82028,143896,20613,185,61642,10358,17000,144060,1884],"class_list":["post-594721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-adana","tag-appel","tag-atiba-hutchinson","tag-besiktas","tag-cenk-tosun","tag-des","tag-diyarbakir","tag-famille-besiktas","tag-gaziantep","tag-hatay","tag-joseph-de-souza","tag-joueurs","tag-kahramanmaras","tag-laide","tag-les","tag-malatya","tag-necip-uysal","tag-osmaniye","tag-parc-vodafone","tag-pour","tag-sanliurfa","tag-terre","tag-tremblement","tag-une-mode","tag-victimes"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/594721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=594721"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/594721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/594722"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=594721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=594721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=594721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}