{"id":592813,"date":"2023-02-05T14:20:25","date_gmt":"2023-02-05T16:20:25","guid":{"rendered":"https:\/\/teknomers.com\/fr\/un-tueur-en-serie-met-la-vie-de-lolita-en-danger\/"},"modified":"2023-02-05T14:20:26","modified_gmt":"2023-02-05T16:20:26","slug":"un-tueur-en-serie-met-la-vie-de-lolita-en-danger","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/un-tueur-en-serie-met-la-vie-de-lolita-en-danger\/","title":{"rendered":"Un tueur en s\u00e9rie met la vie de Lolita en danger"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><span class=\"first-letter\">P<\/span>dernier rendez-vous avec <strong><em>Les enqu\u00eates de Lolita Lobosco 2<\/em><\/strong>  (ce soir le <a rel=\"nofollow noopener\" href=\"https:\/\/www.raiplay.it\/dirette\/rai1\" target=\"_blank\" data-wpel-link=\"external\">Rai 1 \u00e0 21h25<\/a>).  Le sous-commissaire de Bari devra faire face \u00e0 un <strong>tueurs en s\u00e9rie<\/strong> tuant de jeunes femmes aux cheveux roux. <strong>Et il sera aussi sur le point de nous laisser des stylos<\/strong>.  Heureusement, quelqu&#8217;un l&#8217;assiste de l\u00e0-haut et cela <strong>Anthony Fort<\/strong>son bras droit, a un nez presque aussi bon que celui de son coll\u00e8gue.<\/p>\n<p>Et il y a aussi les <strong>questions sentimentales<\/strong> ouvrir. <strong>Daniel<\/strong> <strong>il revient vivant<\/strong>mais ne revient \u00e0 Bari que pour achever son d\u00e9m\u00e9nagement en Su\u00e8de. <strong>Entre les deux on dirait qu&#8217;il n&#8217;y a plus rien \u00e0 faire<\/strong>.  En attendant, Angelo convainc <strong>Lolita<\/strong> faire un tour en bateau.<\/p>\n<article class=\"id-vda-article box_ed_hp_02-article eltdf-item-space hentry-pos-i hentry-home_section-i post-iiiii post type-post status-publish format-standard hentry\"\/>\n<h2><em>Les enqu\u00eates de Lolita Lobosco 2<\/em>: les extraits du cinqui\u00e8me \u00e9pisode<\/h2>\n<p>Est intitul\u00e9 <strong><em>Chasse aux monstres<\/em><\/strong>  l&#8217;avant-dernier \u00e9pisode de la fiction avec <strong>Luisa Ranieri<\/strong>dans le r\u00f4le de <strong>Lolita Lobosco<\/strong>le sous-commissaire en jupe invent\u00e9e par l&#8217;\u00e9crivain <strong>Gabriella Gen\u00e8se. <\/strong> Le monstre en question est un <strong>tueur en s\u00e9rie qui tue des jeunes femmes<\/strong> et les cheveux roux. <strong>Une fille de 25 ans<\/strong> d&#8217;origine russe, elle a \u00e9t\u00e9 retrouv\u00e9e sans vie dans la province de Bari, apr\u00e8s avoir \u00e9t\u00e9 tortur\u00e9e.  Elle \u00e9tait danseuse \u00e0 la discoth\u00e8que Bon Ton.<\/p>\n<p>L&#8217;affaire est li\u00e9e \u00e0 une autre datant de <strong>quinze ans plus t\u00f4t,<\/strong> sur lequel il avait travaill\u00e9 comme PM a <strong>Mariette d\u00e9butante<\/strong>.  Personne n&#8217;avait trouv\u00e9 le coupable de ce meurtre.  Cette fois, les pistes m\u00e8nent \u00e0 un certain <strong>Carlo<\/strong>, un homme amoureux de la femme assassin\u00e9e qui est imm\u00e9diatement arr\u00eat\u00e9.  Mais une autre fille est kidnapp\u00e9e.  Le tueur en s\u00e9rie n&#8217;est pas Carlo. <strong>Lolita \u00e0 ce stade met sa vie en danger <\/strong>faire semblant (avec une perruque rouge) une femme qui fr\u00e9quente le Bon Ton.<\/p>\n<div class=\"player_single_video_component\">\n<div id=\"divVideoPlayer\" class=\"video-sticky-box privacyAccettata\">\n<div class=\"video-sticky-box-inner\">\n<div class=\"video-sticky-box-frame-cont\">\n<div class=\"player player_video_rcs player_shortcode custom-video-sticky\" data-config=\"&quot;newspaper&quot;:&quot;rcs&quot;,&quot;uuid&quot;:&quot;iodonna-0002049883&quot;,&quot;muted&quot;:true,&quot;blockAdv&quot;:false,&quot;ovlLogo&quot;:false,&quot;autoplay&quot;:true,&quot;watermark&quot;:false,&quot;sticky&quot;:&quot;targetClass&quot;:&quot;sticky-video&quot;,&quot;times&quot;:1,&quot;viewport&quot;:50,&quot;relocation&quot;:true,&quot;endlessSticky&quot;:true,&quot;initStickyNoAutoplay&quot;:true,&quot;tipo_video&quot;:&quot;pagina_video&quot;\">\n<div class=\"player_preview\">\n                                    <img decoding=\"async\" class=\"\" alt=\"\"Lolita Lobosco\" est de retour et c'est un succ\u00e8s imm\u00e9diat.  Luisa Ranieri: \u00abLes gens aiment \u00e7a parce que c'est imparfait\u00bb\" title=\"\"Lolita Lobosco\" est de retour et c'est un succ\u00e8s imm\u00e9diat.  Luisa Ranieri: \u00abLes gens aiment \u00e7a parce que c'est imparfait\u00bb\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/01\/Danilo-demenage-en-Suede-pour-le-travail-tandis-quAngelo-retourne.webp.webp\"\/>                                    <span class=\"player_button play\"\/>\n                                <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<h2>L&#8217;histoire entre Lolita et Danilo est au bout du fil<\/h2>\n<p>En traitant avec un tueur en s\u00e9rie <strong>Lolita doit mettre de l&#8217;ordre dans sa vie amoureuse<\/strong>.  Comme le dit l&#8217;ami et coll\u00e8gue de toujours <strong>Anthony Fort<\/strong>: \u00ab La vie boite, puis s&#8217;ajuste et recommence \u00e0 marcher \u00bb. <strong>La femme manque \u00e0 Danilo<\/strong>, mais les deux ont du mal \u00e0 trouver des points de contact.  Alors mieux vaut l\u00e2cher prise.<\/p>\n<div id=\"attachment_2061395\" data-thumbnail_id=\"2061395\" class=\"wp-caption aligncenter\" style=\"width:1000px\"><picture class=\"lozad\"><source  type=\"image\/webp\"><source  type=\"image\/jpeg\"\/><\/source><\/picture>\n<p class=\"wp-caption-text\">Filippo Scicchitano et Luisa Ranieri.  (Photo Duccio Giordano)<\/p>\n<\/div>\n<p>Entre-temps <strong>Ange<\/strong> <strong>essaie de se rapprocher de Lolita : <\/strong>il l&#8217;invite pour une promenade en bateau et elle est de plus en plus convaincue qu&#8217;Angelo <strong>il n&#8217;est pas si narcissique et vaniteux<\/strong> comme il l&#8217;a toujours cru.  Les souvenirs du pass\u00e9 envahissent son c\u0153ur.<\/p>\n<h2>L&#8217;affaire Petresine est au point mort<\/h2>\n<p>L&#8217;affaire du d\u00e9c\u00e8s du p\u00e8re de <strong>Lolita s&#8217;arr\u00eate<\/strong>.  Rocco Santopadre, l&#8217;homme qu&#8217;elle avait rencontr\u00e9 <strong>P\u00e9tresina<\/strong> peu avant d&#8217;\u00eatre \u00e9cras\u00e9, il est retrouv\u00e9 sans vie par<strong> Lolita et Antonio<\/strong> dans une maison de la province de Lecce. <strong>Quelqu&#8217;un veut cacher la v\u00e9rit\u00e9<\/strong> \u00e0 propos de sa mort.  Lolita pourra-t-elle trouver une autre piste \u00e0 suivre ?\n<\/p>\n<div class=\"runa-integration-newsletter-box\">\n    <a rel=\"nofollow noopener\" href=\"https:\/\/www.iodonna.it\/accedi\/?intcmp=nlbeauty_banner_articolo_sitoiodonna_boxInt_271021_iodonna_ss_nd\" class=\"ris-full-link\" data-wpel-link=\"internal\" target=\"_blank\"><\/p>\n<p>\n        <span style=\"left: -60px;\">Recevez des nouvelles et des mises \u00e0 jour<\/span><br \/>\n        <span style=\"left: -160px;\">sur les derniers<\/span><br \/>\n        <span style=\"left: -40px;\">tendances beaut\u00e9<\/span><br \/>\n        <span style=\"left: 10px;\">directement \u00e0 votre courrier<\/span>\n    <\/p>\n<\/div>\n<p>L\u00e0 <strong>La m\u00e8re de Lello<\/strong> attend juste une invitation dans la nouvelle maison de son fils et de sa fille <strong>Catherine<\/strong>.  Un soir, il est \u00e0 d\u00eener avec les deux <strong>jeunes mari\u00e9s<\/strong> et avec un gourou indien.  Comment cela finira-t-il ?<\/p>\n<p class=\"all-rights-reserved\">iO Femme \u00a9 REPRODUCTION R\u00c9SERV\u00c9E<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iodonna.it\/spettacoli\/tv\/2023\/02\/05\/lolita-lobosco-2-la-quinta-puntata-lolita-finisce-nelle-mani-di-un-serial-killer\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-13<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pdernier rendez-vous avec Les enqu\u00eates de Lolita Lobosco 2 (ce soir le Rai 1 \u00e0 21h25). Le sous-commissaire de Bari devra faire face \u00e0 un tueurs en s\u00e9rie tuant de jeunes femmes aux cheveux roux. Et il sera aussi sur le point de nous laisser des stylos. Heureusement, quelqu&#8217;un l&#8217;assiste de l\u00e0-haut et cela Anthony [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":592814,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[1572,32050,4955,198,3998,180],"class_list":["post-592813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-danger","tag-lolita","tag-met","tag-serie","tag-tueur","tag-vie"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/592813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=592813"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/592813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/592814"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=592813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=592813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=592813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}