{"id":57424,"date":"2022-03-27T21:07:44","date_gmt":"2022-03-27T23:07:44","guid":{"rendered":"https:\/\/teknomers.com\/fr\/perez-supporte-la-malchance-avec-sang-froid\/"},"modified":"2022-03-27T21:07:48","modified_gmt":"2022-03-27T23:07:48","slug":"perez-supporte-la-malchance-avec-sang-froid","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/perez-supporte-la-malchance-avec-sang-froid\/","title":{"rendered":"P\u00e9rez supporte la malchance avec sang-froid"},"content":{"rendered":"\n<div>\n<p>Sergio P\u00e9rez menait le Grand Prix d&#8217;Arabie Saoudite 2022 \u00e0 Djeddah de la pole position jusqu&#8217;au 14e tour, mais sa soir\u00e9e en Formule 1 a pris un tournant soudain : juste au moment o\u00f9 P\u00e9rez avait termin\u00e9 son arr\u00eat au stand, le pilote Williams Nicholas Latifi et la voiture de s\u00e9curit\u00e9 sont sortis.  Les poursuivants de P\u00e9rez b\u00e9n\u00e9ficient d&#8217;un arr\u00eat &#8220;gratuit&#8221; et le Mexicain perd la t\u00eate.<\/p>\n<p>Le Mexicain supporte son destin avec sang-froid et d\u00e9clare dans une premi\u00e8re r\u00e9action \u00e0 \u00ab Sky \u00bb : \u00ab C&#8217;est juste de la course. Surtout ici \u00e0 Djeddah, vous savez qu&#8217;une telle situation peut se produire. le mur au mauvais moment pour moi.&#8221;<\/p>\n<p>P\u00e9rez se r\u00e9p\u00e8te: &#8220;C&#8217;est la course. Et le vent tourne \u00e0 nouveau.&#8221;  En tout cas, il n&#8217;a rien \u00e0 se reprocher : \u00ab Aujourd&#8217;hui, nous avons tout fait pour gagner cette course depuis la pole position.<\/p>\n<h2>P\u00e9rez: Non seulement perdu la victoire, mais aussi un podium<\/h2>\n<p>En fait, Perez contr\u00f4lait ce qui se passait de face, gardant le pilote Ferrari Charles Leclerc, son plus proche poursuivant, \u00e0 une distance de plus de deux secondes.  Ce n&#8217;est qu&#8217;apr\u00e8s la phase de voiture de s\u00e9curit\u00e9 que sa course a \u00e9t\u00e9 annul\u00e9e.<\/p>\n<p>&#8220;La voiture de s\u00e9curit\u00e9 n&#8217;est pas arriv\u00e9e au meilleur moment pour nous&#8221;, a d\u00e9clar\u00e9 le directeur sportif de Red Bull, Helmut Marko, sur &#8220;Sky&#8221;.  &#8220;Je pense que cela a co\u00fbt\u00e9 un podium \u00e0 P\u00e9rez.&#8221;<\/p>\n<p>Car apr\u00e8s la phase de voiture de s\u00e9curit\u00e9, Perez ne s&#8217;est retrouv\u00e9 qu&#8217;\u00e0 la quatri\u00e8me place.  &#8220;C&#8217;est comme \u00e7a : la voiture de s\u00e9curit\u00e9 a des gagnants et des perdants&#8221;, d\u00e9clare Marko, ajoutant : &#8220;Latifi nous a apport\u00e9 la victoire \u00e0 Abu Dhabi, o\u00f9 Perez a au moins perdu un podium.&#8221;<\/p>\n<h2>Pas une course id\u00e9ale de P\u00e9rez, m\u00eame devant la voiture de s\u00e9curit\u00e9<\/h2>\n<p>Cependant, la course de P\u00e9rez n&#8217;a pas \u00e9t\u00e9 aussi facile qu&#8217;il n&#8217;y para\u00eet de l&#8217;ext\u00e9rieur, poursuit Marko.  Parce que l&#8217;arr\u00eat au stand pr\u00e9coce du pilote Red Bull n&#8217;\u00e9tait pas pr\u00e9vu : &#8220;Il avait une usure plus importante des pneus, nous avons donc d\u00fb le faire entrer un tour plus t\u00f4t.&#8221;<\/p>\n<p>P\u00e9rez a ensuite tent\u00e9 de regagner au moins une position, mais a termin\u00e9 quatri\u00e8me derri\u00e8re Max Verstappen, Leclerc et Carlos Sainz.  Apr\u00e8s tout : contrairement \u00e0 l&#8217;ouverture de la Formule 1, lorsque les deux voitures Red Bull avaient \u00e9chou\u00e9, les deux voitures ont maintenant vu l&#8217;arriv\u00e9e.  \u00ab Et c&#8217;est tr\u00e8s positif pour l&#8217;\u00e9quipe \u00bb, d\u00e9clare P\u00e9rez : \u00ab Je suis aussi tr\u00e8s content pour Max. Il a fait une course fantastique. Apr\u00e8s le week-end \u00e0 Bahre\u00efn, c&#8217;est super d&#8217;avoir un Red Bull l\u00e0-haut. Qualifications et devant dans la course, donc \u00e7a va \u00eatre.&#8221;<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne4858972\/formel-1-red-bull-pilot-perez-traegt-pech-mit-fassung-das-ist-einfach-racing\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-8<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sergio P\u00e9rez menait le Grand Prix d&#8217;Arabie Saoudite 2022 \u00e0 Djeddah de la pole position jusqu&#8217;au 14e tour, mais sa soir\u00e9e en Formule 1 a pris un tournant soudain : juste au moment o\u00f9 P\u00e9rez avait termin\u00e9 son arr\u00eat au stand, le pilote Williams Nicholas Latifi et la voiture de s\u00e9curit\u00e9 sont sortis. Les poursuivants [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":57425,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[84,4183,127,33106,3887,23459,7460,4470,815,31767],"class_list":["post-57424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-avec","tag-course-de-taureaux-rouges","tag-formule-1","tag-grand-prix-darabie-saoudite","tag-malchance","tag-perez","tag-sangfroid","tag-sergio-perez","tag-sports-mecaniques","tag-supporte"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/57424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=57424"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/57424\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/57425"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=57424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=57424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=57424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}