{"id":57319,"date":"2022-03-27T19:28:49","date_gmt":"2022-03-27T21:28:49","guid":{"rendered":"https:\/\/teknomers.com\/fr\/geste-en-or-de-keylor-navas-30-refugies-ukrainiens-accueillis-chez-eux\/"},"modified":"2022-03-27T19:29:02","modified_gmt":"2022-03-27T21:29:02","slug":"geste-en-or-de-keylor-navas-30-refugies-ukrainiens-accueillis-chez-eux","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/geste-en-or-de-keylor-navas-30-refugies-ukrainiens-accueillis-chez-eux\/","title":{"rendered":"Geste en or de Keylor Navas : 30 r\u00e9fugi\u00e9s ukrainiens accueillis chez eux"},"content":{"rendered":"\n<p><h2 class=\"is-subtitle\">Selon RMC Sport, le d\u00e9fenseur extr\u00eame de PGS a accueilli chez lui 30 r\u00e9fugi\u00e9s fuyant la guerre en Ukraine<\/h2>\n<\/p>\n<div>\n<p>Keylor Navas prend le terrain en faveur des r\u00e9fugi\u00e9s ukrainiens.  Comme le rapporte RMC Sport, le gardien du PSG a achet\u00e9 et am\u00e9nag\u00e9 30 lits chez lui, destin\u00e9s \u00e0 autant de r\u00e9fugi\u00e9s fuyant la guerre en Ukraine.<\/p>\n<\/div>\n<div>\n<p>Navas a accueilli les r\u00e9fugi\u00e9s dans sa maison, avec sa femme qui s&#8217;occupe de la pr\u00e9paration de la nourriture, des v\u00eatements et des fonctions religieuses, avec le couple li\u00e9 aux rites de l&#8217;\u00c9glise \u00e9vang\u00e9lique.<\/p>\n<\/div>\n<div>\n<div class=\"bck-copyright\">\n<p class=\"is-above-copyright\">\n<p>            27 mars 2022 (changement 27 mars 2022 | 20:55)\n          <\/p>\n<p class=\"is-copyright\">\u00a9 REPRODUCTION R\u00c9SERV\u00c9E<\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.golssip.it\/news\/guerra-in-ucraina-gesto-doro-di-keylor-navas-accolti-in-casa-30-profughi-ucraini\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-4<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon RMC Sport, le d\u00e9fenseur extr\u00eame de PGS a accueilli chez lui 30 r\u00e9fugi\u00e9s fuyant la guerre en Ukraine Keylor Navas prend le terrain en faveur des r\u00e9fugi\u00e9s ukrainiens. Comme le rapporte RMC Sport, le gardien du PSG a achet\u00e9 et am\u00e9nag\u00e9 30 lits chez lui, destin\u00e9s \u00e0 autant de r\u00e9fugi\u00e9s fuyant la guerre en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":57320,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[20585,895,5155,29835,37590,37591,254,354],"class_list":["post-57319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-accueillis","tag-chez","tag-eux","tag-geste","tag-keylor","tag-navas","tag-refugies","tag-ukrainiens"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/57319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=57319"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/57319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/57320"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=57319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=57319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=57319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}