{"id":57070,"date":"2022-03-27T15:59:56","date_gmt":"2022-03-27T17:59:56","guid":{"rendered":"https:\/\/teknomers.com\/fr\/perspective-vladimir-poutine-organise-plus-de-medailles-de-ski-pour-la-finlande\/"},"modified":"2022-03-27T16:00:02","modified_gmt":"2022-03-27T18:00:02","slug":"perspective-vladimir-poutine-organise-plus-de-medailles-de-ski-pour-la-finlande","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/perspective-vladimir-poutine-organise-plus-de-medailles-de-ski-pour-la-finlande\/","title":{"rendered":"Perspective : Vladimir Poutine organise plus de m\u00e9dailles de ski pour la Finlande"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div class=\"article-description-pov-text\">\n<div class=\"author-image-container\"><\/div>\n<p>L&#8217;absence d&#8217;athl\u00e8tes russes se voit tr\u00e8s concr\u00e8tement dans le ski de fond, \u00e9crit Santtu Silvennoinen.<\/p><\/div>\n<\/div>\n<div role=\"button\">\n<div class=\"article-image-container\" style=\"height:;padding-bottom:66.69291338582677%\"><img decoding=\"async\" class=\"image image-show image-preview\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2022\/03\/1648403996_471_Perspective-Vladimir-Poutine-organise-plus-de-medailles-de-ski.jpg\" alt=\"Le contrecoup des hostilit\u00e9s arbitraires de Vladimir Poutine dans les sports de haut niveau est que les athl\u00e8tes russes ont \u00e9t\u00e9 gel\u00e9s dans presque tous les sports.\" \/><img decoding=\"async\" class=\"image image-show\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2022\/03\/1648403996_130_Perspective-Vladimir-Poutine-organise-plus-de-medailles-de-ski.jpg\" alt=\"Le contrecoup des hostilit\u00e9s arbitraires de Vladimir Poutine dans les sports de haut niveau est que les athl\u00e8tes russes ont \u00e9t\u00e9 gel\u00e9s dans presque tous les sports.\" \/><\/div>\n<p><span class=\"caption-text\">Le contrecoup des hostilit\u00e9s arbitraires de Vladimir Poutine dans les sports de haut niveau est que les athl\u00e8tes russes ont \u00e9t\u00e9 gel\u00e9s dans presque tous les sports.<!-- --> <\/span><span class=\"media-source\">AOP<\/span><\/p>\n<\/div>\n<div>\n<p class=\"paragraph\"><strong>\u00abCette merde pour le ski masculin, ce sont ces Jeux olympiques.  Cod prend tout, les coups de poing d&#8217;Iivo pour les d\u00e9placements normaux et quelques co\u00efncidences pour les autres dans le sprint \u00bb.<\/strong><\/p>\n<p class=\"paragraph\">Le message agac\u00e9 envoy\u00e9 par l&#8217;entra\u00eeneur de ski finlandais le 12 mars est arriv\u00e9.  Falun \u00e9tait le dernier d\u00e9part personnel de la Coupe du monde \u00e0 cette \u00e9poque, avec les hommes 15 kilom\u00e8tres libres, et les Norv\u00e9giens ont pris les 1\u00e8re, 3\u00e8me, 4\u00e8me, 5\u00e8me et 6\u00e8me place.<\/p>\n<p class=\"paragraph\">Une semaine plus t\u00f4t, lors du voyage royal de 50 kilom\u00e8tres du Kollen, les Norv\u00e9giens avaient remport\u00e9 une triple victoire et obtenu sept hommes en onze amendes, bien que Johannes Kl\u00e4bo, entre autres, \u00e9tait absent du corona.<\/p>\n<p class=\"paragraph\">La guerre d&#8217;agression d\u00e9clench\u00e9e fin f\u00e9vrier par l&#8217;autoritaire pr\u00e9sident russe Vladimir Poutine a mis fin \u00e0 une p\u00e9riode d&#8217;environ 30 ans de sport de haut niveau. <strong>Les derni\u00e8res d\u00e9cennies du dernier mill\u00e9naire sont marqu\u00e9es par des boycotts et diverses fermetures collectives en raison de la politique mondiale, mais au 21e si\u00e8cle, des pays ont \u00e9t\u00e9 expuls\u00e9s des \u00e9v\u00e9nements sportifs &#8220;uniquement&#8221; pour des d\u00e9lits de dopage.<\/strong><\/p>\n<div class=\"article-image gallery center\" role=\"button\">\n<p><span class=\"caption-text\">Les m\u00e9dailles de ski seront redistribu\u00e9es lorsque les Russes ne seront pas impliqu\u00e9s.<!-- --> <\/span><span class=\"media-source\">AOP<\/span><\/p>\n<\/div>\n<p class=\"paragraph\">La mise \u00e0 l&#8217;\u00e9cart des Russes de toutes les activit\u00e9s sportives se voit tr\u00e8s concr\u00e8tement dans le ski de fond, alors que les listes de r\u00e9sultats sont tr\u00e8s diff\u00e9rentes de, disons, les Jeux olympiques d&#8217;hiver de P\u00e9kin en f\u00e9vrier.<\/p>\n<p class=\"paragraph\">L&#8217;\u00e9quipe du Comit\u00e9 olympique russe a \u00e9t\u00e9 la premi\u00e8re \u00e9quipe de ski de fond \u00e0 l&#8217;\u00e9preuve chinoise des cinq anneaux avec onze m\u00e9dailles : quatre d&#8217;or, quatre d&#8217;argent et trois de bronze.  La Norv\u00e8ge a re\u00e7u huit (5\u20131\u20132) m\u00e9dailles, la Finlande six (1\u20132\u20133) et la Su\u00e8de quatre (1\u20132\u20131) m\u00e9dailles.<\/p>\n<p class=\"paragraph\"><strong>&#8211; Il y aura une grande diff\u00e9rence dans les comp\u00e9titions, car la contribution des hommes russes en particulier a \u00e9t\u00e9 tr\u00e8s importante.  Il est ind\u00e9niable que l&#8217;absence des Russes serait une perte comp\u00e9titive significative pour le ski de fond, d\u00e9clare Reijo Jylh\u00e4, l&#8217;expert en ski d&#8217;Iltalehti.<\/strong><\/p>\n<div class=\"article-image gallery center\" role=\"button\">\n<p><span class=\"caption-text\">Les chances de succ\u00e8s de la Finlande et de nombreux autres pays sont plus grandes lorsque les Russes ne sont pas impliqu\u00e9s.<!-- --> <\/span><span class=\"media-source\">Kimmo Brandt \/ EPA \/ AOP<\/span><\/p>\n<\/div>\n<p class=\"paragraph\">M\u00eame si Poutine met fin \u00e0 sa guerre en Ukraine dans les prochaines semaines, le froid pour les athl\u00e8tes russes pourrait bien durer encore longtemps. <strong>Entre autres choses, la F\u00e9d\u00e9ration internationale d&#8217;athl\u00e9tisme a d\u00e9j\u00e0 annonc\u00e9 que les Russes auront dans tous les cas une interdiction des Championnats du monde d&#8217;Eugene en juillet et des Championnats d&#8217;Europe \u00e0 Munich en ao\u00fbt.<\/strong><\/p>\n<p class=\"paragraph\">Des discours individuels des d\u00e9cideurs du Comit\u00e9 international olympique ont soulign\u00e9 le maintien de l&#8217;interdiction de comp\u00e9tition jusqu&#8217;aux Jeux d&#8217;\u00e9t\u00e9 de 2024 et aux Jeux d&#8217;hiver de 2026.<\/p>\n<p class=\"paragraph\">Plus Poutine poursuit son attaque d\u00e9lirante, plus les Russes sont susceptibles d&#8217;\u00eatre absents de la saison de ski de fond 2022-23.<\/p>\n<p class=\"paragraph\"><strong>Il est tr\u00e8s possible que les Russes ne soient r\u00e9introduits dans le sport international qu&#8217;apr\u00e8s l&#8217;\u00e9viction de Poutine.<\/strong><\/p>\n<div class=\"article-image gallery center\" role=\"button\">\n<p><span class=\"caption-text\">La carri\u00e8re de Therese Johaug s&#8217;est termin\u00e9e cette saison.<!-- --> <\/span><span class=\"media-source\">FLAMME PASSI<\/span><\/p>\n<\/div>\n<p class=\"paragraph\">Si P\u00e9kin avait \u00e9t\u00e9 battu sans les Russes, Iivo Niskanen aurait remport\u00e9 le combin\u00e9 de 30 kilom\u00e8tres et Kerttu Niskanen, quatri\u00e8me, aurait remport\u00e9 quatre m\u00e9dailles de bronze au lieu d&#8217;une : un combin\u00e9 de 15 kilom\u00e8tres, un double message et un 4&#215;5. message kilom\u00e9trique.<\/p>\n<p class=\"paragraph\"><strong>Quand Th\u00e9r\u00e8se Johaug a mis fin \u00e0 sa carri\u00e8re et que les Russes risquent d&#8217;\u00eatre sur la touche l&#8217;an prochain, il y a de la place au sommet du ski f\u00e9minin.  Si le succ\u00e8s motive Krista P\u00e4rm\u00e4koski, qui est encore cingl\u00e9e, il ne faut pas mettre les skis dans le sac apr\u00e8s cette saison.<\/strong><\/p>\n<div class=\"iltv-embed\">\n<p><span class=\"caption-text\">La saison de ski n&#8217;est pas termin\u00e9e !  En Finlande, les grands matchs sont encore devant<!-- --> <\/span><span class=\"media-source\" \/><\/p>\n<\/div>\n<div class=\"article-image-external-container\"><img decoding=\"async\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2022\/03\/Le-heros-olympique-a-mis-ses-skis-dans-le-sac.gif\" alt=\"\u00c9missions de t\u00e9l\u00e9vision aujourd'hui, guide TV\" \/><\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iltalehti.fi\/talviurheilu\/a\/622e8f3d-5894-4788-944b-ebc198bfe42f\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-49<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;absence d&#8217;athl\u00e8tes russes se voit tr\u00e8s concr\u00e8tement dans le ski de fond, \u00e9crit Santtu Silvennoinen. Le contrecoup des hostilit\u00e9s arbitraires de Vladimir Poutine dans les sports de haut niveau est que les athl\u00e8tes russes ont \u00e9t\u00e9 gel\u00e9s dans presque tous les sports. AOP \u00abCette merde pour le ski masculin, ce sont ces Jeux olympiques. Cod [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":57071,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[153,3354,2549,17917,7038,8327,185,452,4181,9927,3937,107,8468,13],"class_list":["post-57070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-24h","tag-exercice-et-sport","tag-finlande","tag-medailles","tag-organise","tag-perspective","tag-pour","tag-poutine","tag-ski","tag-ski-de-fond","tag-ski-nordique","tag-sports-dhiver","tag-sports-de-glisse","tag-vladimir"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/57070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=57070"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/57070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/57071"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=57070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=57070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=57070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}