{"id":56927,"date":"2022-03-27T14:00:52","date_gmt":"2022-03-27T16:00:52","guid":{"rendered":"https:\/\/teknomers.com\/fr\/thw-kiel-coche-son-titre-malgre-le-gala-a-magdebourg\/"},"modified":"2022-03-27T14:00:56","modified_gmt":"2022-03-27T16:00:56","slug":"thw-kiel-coche-son-titre-malgre-le-gala-a-magdebourg","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/thw-kiel-coche-son-titre-malgre-le-gala-a-magdebourg\/","title":{"rendered":"THW Kiel coche son titre malgr\u00e9 le gala \u00e0 Magdebourg"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><b>Magdeburg (dpa) &#8211; Filip Jicha n&#8217;a pas voulu cr\u00e9er de tension artificielle dans la course au titre de la Bundesliga de handball malgr\u00e9 la performance magistrale de son THW Kiel face au leader SC Magdeburg.<\/b><\/p>\n<p>&#8220;La situation dans la ligue n&#8217;a pas chang\u00e9 du tout. Je pense que le SCM nage toujours dans ses propres eaux&#8221;, a d\u00e9clar\u00e9 l&#8217;entra\u00eeneur du champion en titre apr\u00e8s le clair 30:25 (17:15).<\/p>\n<p>Devant 5558 spectateurs dans la salle enti\u00e8rement occup\u00e9e pour la premi\u00e8re fois depuis des mois, et plus d&#8217;un million et demi devant les plateaux t\u00e9l\u00e9, le champion du record a d\u00e9montr\u00e9 sa classe dans un duel au top avec le club champion du monde. , qu&#8217;il n&#8217;a pas \u00e9t\u00e9 en mesure d&#8217;enregistrer r\u00e9guli\u00e8rement cette saison.<\/p>\n<p>Magdebourg d\u00e9tient les atouts<\/p>\n<p>Avec 44:4 points, Magdeburg est toujours largement devant le THW (40:10) et a encore tous les atouts en main pour d\u00e9crocher \u00e0 lui tout seul le premier titre de champion depuis 21 ans.  &#8220;Magdebourg joue peut-\u00eatre le plus beau handball de la ligue cette saison. Ils ont encore une grosse avance et doivent encore perdre trois matchs. S&#8217;ils continuent \u00e0 jouer comme ils l&#8217;ont fait, ce sera difficile&#8221;, a d\u00e9clar\u00e9 Patrick Wiencek, coureur du cercle THW. sur la constellation de table.<\/p>\n<p>L&#8217;entra\u00eeneur du SCM Bennet Wiegert a tenu son \u00e9quipe, pour qui ce n&#8217;\u00e9tait que la deuxi\u00e8me d\u00e9faite de la saison, responsable avant la fin de la saison.  &#8220;Maintenant, il est temps d&#8217;apprendre les bonnes le\u00e7ons et de continuer notre chemin. Nous ne devons pas nous laisser abattre&#8221;, a exig\u00e9 le joueur de 40 ans et a soulign\u00e9 en vue des prochains matchs : &#8220;Maintenant, nous pouvons voir \u00e0 quel point la stabilit\u00e9 et mentalement l&#8217;\u00e9quipe est forte. Nous devons faire face \u00e0 la d\u00e9faite. C&#8217;est difficile parce que nous n&#8217;y sommes pas habitu\u00e9s.&#8221;<\/p>\n<p>Le favori n&#8217;\u00e9tait pas \u00e0 la hauteur des habitants de Kiel.  Au final, toutes les statistiques parlaient pour les invit\u00e9s, qui avaient un tr\u00e8s fort soutien du gardien Niklas Landin dans la phase d\u00e9cisive.  Au milieu de la seconde mi-temps, Magdebourg n&#8217;a pas marqu\u00e9 pendant huit minutes.  Le THW, dans lequel Sander Sagosen a brill\u00e9 en attaque avec neuf buts, s&#8217;est \u00e9loign\u00e9.  &#8220;Nous avons montr\u00e9 une tr\u00e8s bonne performance&#8221;, a salu\u00e9 Jicha.  &#8220;Je tire mon chapeau \u00e0 mes gar\u00e7ons.&#8221;<\/p>\n<p>&#8220;C&#8217;\u00e9tait tr\u00e8s \u00e9mouvant&#8221;<\/p>\n<p>Ils ont c\u00e9l\u00e9br\u00e9 leur premi\u00e8re victoire \u00e0 Magdebourg en sept ans apr\u00e8s le coup de sifflet final avec une danse jubilatoire sur le sol.  &#8220;C&#8217;\u00e9tait important de survivre devant cette foule apr\u00e8s un long moment. Les gar\u00e7ons ont accept\u00e9 cela, c&#8217;\u00e9tait tr\u00e8s \u00e9mouvant&#8221;, a d\u00e9clar\u00e9 Jicha.  &#8220;Il est bien connu que ce n&#8217;est pas la t\u00e2che la plus facile de jouer ici devant ce grand public.&#8221;<\/p>\n<p>Le succ\u00e8s a \u00e9t\u00e9 extr\u00eamement important dans la lutte pour la participation \u00e0 la Ligue des champions, pour laquelle la deuxi\u00e8me place doit \u00eatre obtenue \u00e0 la fin de la saison.  Car les renards de Berlin (39:9 points) apr\u00e8s un 29:24 au Rhein-Neckar L\u00f6wen et du SG Flensburg-Handewitt (37:11), qui se sont affirm\u00e9s au MT Melsungen avec 32:26, \u200b\u200b\u200b\u200bsont proches.  &#8220;Nous avions besoin de points&#8221;, a d\u00e9clar\u00e9 Jicha, soulag\u00e9.<\/p>\n<p>Malgr\u00e9 les bonnes performances, personne chez THW ne pense s\u00e9rieusement \u00e0 d\u00e9fendre avec succ\u00e8s le titre.  &#8220;Je ne pense pas qu&#8217;il soit r\u00e9aliste que nous puissions encore rattraper Magdebourg. Ils ont encore trop de points devant nous&#8221;, a d\u00e9clar\u00e9 Landin.  Et Jicha a d\u00e9clar\u00e9: &#8220;L&#8217;espoir ne gagne pas les championnats, nous le savons.&#8221;<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.t-online.de\/sport\/handball\/id_91907394\/handball-bundesliga-thw-kiel-hakt-titel-trotz-gala-in-magdeburg-ab.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-10<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Magdeburg (dpa) &#8211; Filip Jicha n&#8217;a pas voulu cr\u00e9er de tension artificielle dans la course au titre de la Bundesliga de handball malgr\u00e9 la performance magistrale de son THW Kiel face au leader SC Magdeburg. &#8220;La situation dans la ligue n&#8217;a pas chang\u00e9 du tout. Je pense que le SCM nage toujours dans ses propres [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56078,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[108,37038,138,30846,97,7349,405,2959,3347,13604,2492,37036,37035,1779,1242,5303,37037,167,3440,1351],"class_list":["post-56927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-allemagne","tag-bennett-wiegert","tag-bundesliga","tag-coche","tag-des-sports","tag-gala","tag-handball","tag-hommes","tag-kiel","tag-magdebourg","tag-malgre","tag-philippe-jicha","tag-quille","tag-renards-berlin","tag-saxe-anhalt","tag-schleswig-holstein","tag-scm","tag-son","tag-thw","tag-titre"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/56927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=56927"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/56927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/56078"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=56927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=56927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=56927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}