{"id":56418,"date":"2022-03-27T07:00:03","date_gmt":"2022-03-27T09:00:03","guid":{"rendered":"https:\/\/teknomers.com\/fr\/storm-titube-jusquau-ko-en-carriere\/"},"modified":"2022-03-27T07:00:10","modified_gmt":"2022-03-27T09:00:10","slug":"storm-titube-jusquau-ko-en-carriere","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/storm-titube-jusquau-ko-en-carriere\/","title":{"rendered":"Storm titube jusqu&#8217;au KO en carri\u00e8re"},"content":{"rendered":"\n<div>\n<p>Au lieu de se battre \u00e0 nouveau pour le championnat du monde de boxe, apr\u00e8s avoir perdu contre Istvan Szili, Felix Sturm est confront\u00e9 \u00e0 la question : est-il toujours judicieux de poursuivre sa carri\u00e8re ?  L&#8217;homme de 43 ans veut consulter de mani\u00e8re intensive, tandis que l&#8217;expert de ntv Andreas von Thien a une opinion claire.<\/p>\n<p>De voir Felix Sturm si mal dessin\u00e9, si bless\u00e9, si sans aucune chance, l&#8217;expert en boxe Andreas von Thien a \u00e9t\u00e9 tr\u00e8s bless\u00e9.  En fait, Sturm, le quintuple champion du monde, voulait rendre compte \u00e0 l&#8217;\u00e9lite mondiale de la boxe dimanche soir, mais son combat contre le Hongrois Istvan Szili dans le Dortmund Westfalenhalle a \u00e9t\u00e9 perdu avec un crash et a n\u00e9cessairement conduit \u00e0 la question: est-ce tout a encore du sens \u00e0 43 ans ?  Lui-m\u00eame a \u00e9vit\u00e9 le sujet de la fin d\u00e9finitive de sa carri\u00e8re ce soir-l\u00e0 : &#8220;Je parle \u00e0 ma famille, je suis toujours en bonne sant\u00e9. Nous allons nous asseoir avec le promoteur et ensuite prendre la bonne d\u00e9cision.&#8221;<\/p>\n<p>Si Sturm rassemble tous les d\u00e9tails de ce combat de qualification pour la Coupe du monde de l&#8217;association IBO plut\u00f4t moins importante au niveau international dans son analyse, alors il devrait \u00eatre clair pour lui que la chance de s&#8217;attacher \u00e0 nouveau sa ceinture est tr\u00e8s faible.  Peut-\u00eatre m\u00eame impossible.  Il \u00e9tait inf\u00e9rieur \u00e0 son adversaire de quatre ans plus jeune.  &#8220;La victoire de Szili nous a surpris, mais c&#8217;\u00e9tait surtout tr\u00e8s, tr\u00e8s m\u00e9rit\u00e9&#8221;, a d\u00e9clar\u00e9 von Thien, qui a accompagn\u00e9 Felix Sturm en tant que journaliste du ring pendant des ann\u00e9es, dans une interview \u00e0 ntv.  &#8220;F\u00e9lix \u00e9tait bien trop loin de sa meilleure journ\u00e9e ce soir-l\u00e0. L&#8217;explosivit\u00e9, la puissance de combat, la volont\u00e9 absolue, tout ce qui manquait.&#8221;<\/p>\n<p>Pendant ce temps, le promoteur Ludger Inholte a donn\u00e9 une indication brutale de la fa\u00e7on de proc\u00e9der.  &#8220;Gravir du bas \u00e0 43 ans est difficile. Je pense que les t\u00e2ches qui l&#8217;attendent sont plut\u00f4t dans le domaine de la gestion sportive&#8221;, a d\u00e9clar\u00e9 l&#8217;entrepreneur immobilier.  &#8220;C&#8217;\u00e9tait la derni\u00e8re chance de F\u00e9lix.&#8221;  Inholte lui-m\u00eame a admis qu&#8217;il ne s&#8217;attendait pas \u00e0 ce que le combat se termine ainsi.<\/p>\n<h2>&#8220;Les notes des deux juges scandaleuses&#8221;<\/h2>\n<p>Aussi clair que le combat ait \u00e9t\u00e9, le verdict du deuxi\u00e8me juge \u00e9tait \u00e9troit.  Ferenc Budai (\u00e9galement hongrois) a marqu\u00e9 le duel 114:114, soit un match nul, Marco Morales d&#8217;Allemagne a vu Szili juste devant avec 115:113.  &#8220;Nous avons \u00e0 peine rat\u00e9 une disgr\u00e2ce pour la boxe ce soir-l\u00e0&#8221;, a d\u00e9clar\u00e9 von Thien, qui lui-m\u00eame n&#8217;aurait marqu\u00e9 que deux des douze rounds pour Sturm.  Et seulement avec &#8220;bonne volont\u00e9&#8221;.  Sur le ring, les forces \u00e9taient clairement r\u00e9parties.  Pourquoi les juges l&#8217;ont-ils vu diff\u00e9remment?  L&#8217;expert de &#8220;ntv&#8221; est d\u00e9sempar\u00e9 : &#8220;C&#8217;est un myst\u00e8re complet pour moi, je trouve scandaleux les notes des deux juges.&#8221;  Seul le troisi\u00e8me juge, Giulio Piras d&#8217;Italie, a pris une d\u00e9cision justifi\u00e9e avec 116:111, pense-t-il.<\/p>\n<p>\u00c0 la fin, cependant, les choses se sont pass\u00e9es comme elles avaient \u00e9t\u00e9 d\u00e9crites dans le ring.  Avec le vainqueur Szili.  Il est pass\u00e9 \u00e0 l&#8217;offensive avec le premier gong et a ainsi domin\u00e9 le combat.  &#8220;Cette boxe puissante \u00e9tait un r\u00e9gal pour les yeux&#8221;, s&#8217;est enthousiasm\u00e9 von Thien.  &#8220;Avec les crochets courts et rapides au corps et \u00e0 la t\u00eate, il a rapidement bris\u00e9 la volont\u00e9 de Sturm, l&#8217;\u00e9puisant.&#8221;  Sturm n&#8217;est jamais sorti de la d\u00e9fensive pendant longtemps et n&#8217;a pas pu d\u00e9velopper son plan de match.  La clart\u00e9 du duel \u00e9tait \u00e9galement visible sur les visages des combattants.  Alors que Szili avait presque l&#8217;air frais du lit de bronzage, Sturm \u00e9tait marqu\u00e9 par des blessures et des coupures.<\/p>\n<p>L&#8217;Allemand a \u00e9galement \u00e9t\u00e9 touch\u00e9 d\u00e8s le d\u00e9but par une puissante coupure apr\u00e8s un coup de t\u00eate du Hongrois, que l&#8217;arbitre a qualifi\u00e9 d&#8217;involontaire.  Cependant, les cons\u00e9quences de l&#8217;action ont \u00e9t\u00e9 immenses.  Le cutman de Sturm a eu du mal \u00e0 arr\u00eater le saignement de son \u0153il gauche, et le septi\u00e8me round a d\u00fb \u00eatre arr\u00eat\u00e9 \u00e0 38 secondes de la fin.  Ce n&#8217;est qu&#8217;avec le consentement du m\u00e9decin du ring que Sturm a \u00e9t\u00e9 autoris\u00e9 \u00e0 poursuivre le combat.  Von Thien ne veut pas laisser passer le fait que le joueur de 43 ans s&#8217;est plaint plus tard d&#8217;un combat d\u00e9sordonn\u00e9.  &#8220;Je n&#8217;ai pas du tout vu \u00e7a.&#8221;  Szili est pouss\u00e9 et frapp\u00e9 \u00e0 l&#8217;arri\u00e8re de la t\u00eate &#8211; c&#8217;est juste de la boxe professionnelle.<\/p>\n<h2>La d\u00e9faite rend Sturm mondialement c\u00e9l\u00e8bre<\/h2>\n<p>L&#8217;expert de ntv a une opinion claire sur la question de savoir si Sturm im Ring peut et doit continuer.  &#8220;Je suis loin de lui donner une recommandation, mais peut-\u00eatre que F\u00e9lix devrait se rendre compte que \u00e7a suffit avant que \u00e7a se termine mal. Il a d\u00e9j\u00e0 conc\u00e9d\u00e9 de nombreux coups durs et lourds, m\u00eame si le renversement n&#8217;en faisait pas partie.&#8221;  Sturm a livr\u00e9 tant de grands combats, s&#8217;est entra\u00een\u00e9 avec diligence toute sa vie et tout est en panne avec le sport.  Il pouvait partir fier et n&#8217;avoir plus rien \u00e0 prouver \u00e0 personne, comme von Thien, qui se souvient aussi du combat de sa vie (de Sturm), contre la superstar Oscar de la Hoya le 5 juin 2004. C&#8217;est le combat qui a fait l&#8217;Allemand mondialement connu, qu&#8217;il n&#8217;a perdu qu&#8217;\u00e0 cause d&#8217;un verdict scandaleux.<\/p>\n<p>La sixi\u00e8me d\u00e9faite dans le 52e combat professionnel aurait d\u00e9sormais pu \u00eatre la derni\u00e8re d&#8217;une longue et extr\u00eamement r\u00e9ussie carri\u00e8re.  En signe presque symbolique, le logo IBO s&#8217;est envol\u00e9 du pantalon de Sturm au onzi\u00e8me tour.  Apr\u00e8s huit mois de garde \u00e0 vue, il est revenu fin 2020 apr\u00e8s une rupture de ring de pr\u00e8s de cinq ans et a remport\u00e9 deux combats avant le duel avec Szili, qui peut d\u00e9sormais se pr\u00e9parer pour le combat pour le titre contre le Britannique Lerrone Richards, le super-moyen IBO en titre. champion.<\/p>\n<p>Tobias Nordmann<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne4858474\/boxen-sturms-karriere-k-o-boxsport-entgeht-blamage-nur-knapp\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-8<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au lieu de se battre \u00e0 nouveau pour le championnat du monde de boxe, apr\u00e8s avoir perdu contre Istvan Szili, Felix Sturm est confront\u00e9 \u00e0 la question : est-il toujours judicieux de poursuivre sa carri\u00e8re ? L&#8217;homme de 43 ans veut consulter de mani\u00e8re intensive, tandis que l&#8217;expert de ntv Andreas von Thien a une [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56419,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[9758,37178,37179,1327,1446,36978,37180,3352,9761,28910,14728,37181],"class_list":["post-56418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-boxe","tag-boxe-des-super-moyens","tag-boxe-poids-moyen","tag-carriere","tag-championnat-du-monde","tag-felix-tempete","tag-istvan-szili","tag-jusquau","tag-meilleurs-combats-de-boxe","tag-sport-general","tag-storm","tag-titube"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/56418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=56418"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/56418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/56419"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=56418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=56418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=56418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}