{"id":56299,"date":"2022-03-27T05:22:48","date_gmt":"2022-03-27T07:22:48","guid":{"rendered":"https:\/\/teknomers.com\/fr\/il-y-a-quatre-vingts-ans-a-kiev-le-vrai-echappez-vous-vers-la-victoire-mais-sans-fin-heureuse\/"},"modified":"2022-03-27T05:22:53","modified_gmt":"2022-03-27T07:22:53","slug":"il-y-a-quatre-vingts-ans-a-kiev-le-vrai-echappez-vous-vers-la-victoire-mais-sans-fin-heureuse","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/il-y-a-quatre-vingts-ans-a-kiev-le-vrai-echappez-vous-vers-la-victoire-mais-sans-fin-heureuse\/","title":{"rendered":"Il y a quatre-vingts ans \u00e0 Kiev le vrai &quot;\u00c9chappez-vous vers la victoire&quot;.  Mais sans fin heureuse&#8230;"},"content":{"rendered":"\n<p><h2 class=\"is-subtitle\">Une \u00e9quipe de boulangers ukrainiens a vaincu celle des SS.  &#8220;Vous ne pouvez pas gagner&#8221;, ont d\u00e9clar\u00e9 les Allemands \u00e0 leurs rivaux \u00e0 la mi-temps.  Qui les a plut\u00f4t battus 5-3.  Puis se retrouver dans des camps de concentration accus\u00e9s d&#8217;\u00eatre des espions russes<\/h2>\n<\/p>\n<div>\n<p>  Les SS sont entr\u00e9s dans les vestiaires \u00e0 la mi-temps.  &#8220;Nous sommes profond\u00e9ment impressionn\u00e9s. Mais vous devez comprendre que vous ne pouvez pas gagner.&#8221;  Devant eux, 11 serviteurs d&#8217;une fabrique de pain.  Mal nourri.  Pas en forme.  Avec des uniformes ab\u00eem\u00e9s.  Pourtant, ils humiliaient une \u00e9quipe invincible, du moins selon la propagande nazie.  Certainement la meilleure \u00e9quipe nationale possible en Allemagne \u00e0 cette \u00e9poque, appel\u00e9e par le r\u00e9gime pour \u00e9teindre l&#8217;espoir d&#8217;un peuple qui avait tout perdu, \u00e0 commencer par sa propre ville, Kiev, envahie et conquise par l&#8217;arm\u00e9e d&#8217;Adolf Hitler, certaine d&#8217;une reddition imm\u00e9diate. <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.gazzetta.it\/Calcio\/Estero\/27-03-2022\/ucraina-80-anni-fa-kiev-partita-morte-che-ispiro-fuga-la-vittoria-4302012608900.shtml\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-4<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une \u00e9quipe de boulangers ukrainiens a vaincu celle des SS. &#8220;Vous ne pouvez pas gagner&#8221;, ont d\u00e9clar\u00e9 les Allemands \u00e0 leurs rivaux \u00e0 la mi-temps. Qui les a plut\u00f4t battus 5-3. Puis se retrouver dans des camps de concentration accus\u00e9s d&#8217;\u00eatre des espions russes Les SS sont entr\u00e9s dans les vestiaires \u00e0 la mi-temps. &#8220;Nous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56300,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[277,2360,37134,1389,15680,5111,3810,286,37133,26405,37135,1181,847,1218,16890,41],"class_list":["post-56299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-ans","tag-demarrer","tag-echapper-a-la-victoire","tag-fin","tag-heureuse","tag-hitler","tag-kiev","tag-mais","tag-match-de-la-mort","tag-quatrevingts","tag-quotechappezvous","tag-sans","tag-ukraine","tag-vers","tag-victoirequot","tag-vrai"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/56299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=56299"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/56299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/56300"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=56299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=56299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=56299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}