{"id":56227,"date":"2022-03-27T04:18:22","date_gmt":"2022-03-27T06:18:22","guid":{"rendered":"https:\/\/teknomers.com\/fr\/lentraineur-turc-kuntz-se-querelle-avec-la-coupe-du-monde\/"},"modified":"2022-03-27T04:18:28","modified_gmt":"2022-03-27T06:18:28","slug":"lentraineur-turc-kuntz-se-querelle-avec-la-coupe-du-monde","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/lentraineur-turc-kuntz-se-querelle-avec-la-coupe-du-monde\/","title":{"rendered":"L&#8217;entra\u00eeneur turc Kuntz se querelle avec la Coupe du monde"},"content":{"rendered":"\n<div>\n<p>Stefan Kuntz pleure encore un peu le billet rat\u00e9 pour la Coupe du monde, m\u00eame si l&#8217;entra\u00eeneur national de football turc a depuis longtemps les yeux riv\u00e9s sur l&#8217;avenir avec l&#8217;objectif du Championnat d&#8217;Europe 2024.<\/p>\n<p>&#8220;Quand vous \u00eates si pr\u00e8s du chocolat et que vous avez l&#8217;opportunit\u00e9 de le saisir, il faut un peu de temps pour l&#8217;accepter&#8221;, a d\u00e9clar\u00e9 Kuntz, revenant sur la d\u00e9faite 3-1 en demi-finale des s\u00e9ries \u00e9liminatoires au Portugal. dans une interview &#8220;Sky&#8221;.<\/p>\n<p>Son \u00e9quipe s&#8217;est vendue ch\u00e8rement \u00e0 Porto, il ne peut donc pas bl\u00e2mer l&#8217;\u00e9quipe.  &#8220;Ce qui nous d\u00e9range le plus, c&#8217;est que nous avons jou\u00e9 un peu d\u00e9courag\u00e9s et que nous ne pensions pas vraiment pouvoir le faire&#8221;, s&#8217;est plaint l&#8217;ancien entra\u00eeneur de l&#8217;Allemagne des moins de 21 ans.  &#8220;Mais parfois, il faut prendre le football pour ce qu&#8217;il est.&#8221;<\/p>\n<p>Selon Kuntz, le match du 29 mars contre les Italiens, qui ont \u00e9chou\u00e9 de mani\u00e8re sensationnelle lors des \u00e9liminatoires de la Coupe du monde contre la Mac\u00e9doine du Nord, est d&#8217;une grande importance pour la Turquie.  &#8220;M\u00eame si vous ne pouvez pas tout \u00e0 fait compenser la perte, ils veulent au moins se racheter un peu&#8221;, a d\u00e9clar\u00e9 Kuntz, faisant r\u00e9f\u00e9rence \u00e0 la Squadra Azzurra, qui a rat\u00e9 une Coupe du monde pour la deuxi\u00e8me fois cons\u00e9cutive.<\/p>\n<p>Le prochain grand objectif des Turcs est d\u00e9sormais la qualification pour le Championnat d&#8217;Europe 2024 en Allemagne.  &#8220;D&#8217;un point de vue turc, nous ne sous-estimons pas non plus la Ligue des Nations. C&#8217;est aussi une fa\u00e7on de se qualifier pour le Championnat d&#8217;Europe 2024. Nous avons une \u00e9quipe tr\u00e8s jeune avec des joueurs jeunes et capables&#8221;, a soulign\u00e9 l&#8217;entra\u00eeneur.  &#8220;Et pour nous, il s&#8217;agit simplement de commencer une nouvelle voie.&#8221;<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne4858367\/tuerkei-coach-kuntz-hadert-mit-wm-aus\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-8<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stefan Kuntz pleure encore un peu le billet rat\u00e9 pour la Coupe du monde, m\u00eame si l&#8217;entra\u00eeneur national de football turc a depuis longtemps les yeux riv\u00e9s sur l&#8217;avenir avec l&#8217;objectif du Championnat d&#8217;Europe 2024. &#8220;Quand vous \u00eates si pr\u00e8s du chocolat et que vous avez l&#8217;opportunit\u00e9 de le saisir, il faut un peu de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56228,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[84,1008,91,28909,15340,3511,1126,1056,16552,8579,2506,5417],"class_list":["post-56227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-avec","tag-coupe","tag-football","tag-football-de-haut-niveau","tag-kuntz","tag-le-portugal","tag-lentraineur","tag-monde","tag-qualification-coupe-du-monde-leurope-","tag-querelle","tag-turc","tag-turquie"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/56227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=56227"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/56227\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/56228"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=56227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=56227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=56227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}