{"id":499877,"date":"2022-12-07T15:03:25","date_gmt":"2022-12-07T17:03:25","guid":{"rendered":"https:\/\/teknomers.com\/fr\/cest-la-serie-la-plus-recherchee-de-2022\/"},"modified":"2022-12-07T15:03:26","modified_gmt":"2022-12-07T17:03:26","slug":"cest-la-serie-la-plus-recherchee-de-2022","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/cest-la-serie-la-plus-recherchee-de-2022\/","title":{"rendered":"C&#8217;est la s\u00e9rie la plus recherch\u00e9e de 2022"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"article__meta\">\n\t\t\t\t\t<span class=\"byline\"><span class=\"author vcard\">Par Rita Deutschbein et Marlene Polywka<\/span><\/span>  | <span class=\"posted-on\">07 d\u00e9cembre 2022 15 h 36<\/span>\t\t\t\t<\/p>\n<p><!-- .entry-meta --><\/p>\n<p class=\"article__summary\"><strong>Netflix propose un assortiment color\u00e9 de toutes sortes de films et de s\u00e9ries.  De temps en temps, un titre en particulier suscite l&#8217;int\u00e9r\u00eat des utilisateurs.  C&#8217;est \u00e9galement le cas avec une nouvelle s\u00e9rie bas\u00e9e sur des \u00e9v\u00e9nements r\u00e9els.  Maintenant, il a m\u00eame atteint le num\u00e9ro 1 sur Google\u00a0!<\/strong><\/p>\n<div class=\"article-content__mrec-block\">\n<div class=\"article-content__mrec-paragraph\">\n<p>Si l&#8217;on repense aux succ\u00e8s des s\u00e9ries pass\u00e9es sur Netflix, on pense notamment \u00e0 des titres comme &#8220;Bridgerton&#8221;, &#8220;Inventing Anna&#8221; ou &#8220;Squid Game&#8221; qui attiraient au d\u00e9part des millions de spectateurs.  Depuis octobre 2022, il y a un nom de plus sur cette liste.  Nous parlons de la v\u00e9ritable s\u00e9rie polici\u00e8re &#8220;Dahmer&#8221;.<\/p>\n<\/div><\/div>\n<h2 id=\"h-geschichte-eines-serienmorders-wurde-zum-netflix-erfolg\">L&#8217;histoire d&#8217;un tueur en s\u00e9rie est devenue un succ\u00e8s sur Netflix<\/h2>\n<p>&#8220;Dahmer&#8221; met en lumi\u00e8re les meurtres du tueur en s\u00e9rie Jeffrey Dahmer dans un total de 10 \u00e9pisodes.  Entre 1978 et 1991, il a horriblement tu\u00e9 17 jeunes hommes aux \u00c9tats-Unis et a gard\u00e9 certaines de leurs parties du corps dans son appartement pendant des semaines.  Les m\u00e9dias l&#8217;ont \u00e9galement appel\u00e9 &#8220;The Milwaukee Cannibal&#8221; ou &#8220;The Milwaukee Monster&#8221;.  Apr\u00e8s qu&#8217;une de ses victimes potentielles ait r\u00e9ussi \u00e0 s&#8217;\u00e9chapper, Dahmer a \u00e9t\u00e9 attrap\u00e9.  Apr\u00e8s son arrestation en 1991, il a coop\u00e9r\u00e9 avec les autorit\u00e9s et la police, ce qui signifie que les cas et leurs ant\u00e9c\u00e9dents sont aujourd&#8217;hui tr\u00e8s bien document\u00e9s.  Il est \u00e9galement l&#8217;un des tueurs en s\u00e9rie les plus c\u00e9l\u00e8bres des \u00c9tats-Unis.  Dahmer a \u00e9t\u00e9 tu\u00e9 en prison par un cod\u00e9tenu \u00e0 l&#8217;\u00e2ge de 34 ans. <\/p>\n<figure class=\"wp-block-image size-large\"><figcaption class=\"wp-element-caption\">Le vrai Jeffrey Dahmer dans une photo de 1982.<span class=\"media__copyright\">Photo : Getty Images<\/span> <\/figcaption><\/figure>\n<p>L&#8217;histoire effrayante et macabre pla\u00eet apparemment \u00e0 de nombreux utilisateurs de Netflix.  Au cours de la premi\u00e8re semaine seulement apr\u00e8s le lancement de Netflix le 21 septembre 2022, la s\u00e9rie a \u00e9t\u00e9 diffus\u00e9e 196,2 millions d&#8217;heures.  Au cours de la deuxi\u00e8me semaine, le nombre d&#8217;heures de streaming a augment\u00e9 <a rel=\"nofollow noopener\" href=\"https:\/\/top10.netflix.com\/tv\" target=\"_blank\">selon Netflix <\/a>m\u00eame \u00e0 299,84 millions.  Aucune autre s\u00e9rie en anglais sur Netflix n&#8217;a connu un red\u00e9marrage aussi brutal.  Seul &#8220;Wednesday&#8221; a pu d\u00e9passer ce nombre impressionnant directement en novembre.<\/p>\n<h2 id=\"h-dahmer-auch-bei-google-erfolgreichste-serie\">&#8220;Dahmer&#8221; est aussi la s\u00e9rie la plus r\u00e9ussie sur Google<\/h2>\n<p>L&#8217;int\u00e9r\u00eat pour la s\u00e9rie Netflix est \u00e9galement \u00e9vident sur Google.  Dans le bilan annuel du moteur de recherche, &#8220;Dahmer&#8221; se classe en effet au premier rang des s\u00e9ries les plus recherch\u00e9es.  Les classements Google sont toujours un tr\u00e8s bon indicateur de succ\u00e8s et d&#8217;int\u00e9r\u00eat pour un sujet.  C&#8217;est particuli\u00e8rement impressionnant car &#8220;Dahmer&#8221; n&#8217;a commenc\u00e9 sur Netflix que relativement tard dans l&#8217;ann\u00e9e. <\/p>\n<p>Accessoirement, les s\u00e9ries Netflix tr\u00f4nent \u00e9galement en 2\u00e8me et 5\u00e8me place, \u00e0 savoir &#8220;Stranger Things&#8221; et &#8220;The Watcher&#8221;.  La 4e saison de &#8220;Stranger Things&#8221; a \u00e9t\u00e9 diffus\u00e9e sur le fournisseur de streaming cet \u00e9t\u00e9, et la saison 5 sera alors la finale de la s\u00e9rie \u00e0 succ\u00e8s.  Parmi les autres s\u00e9ries du top 5, citons le spin-off de Game of Thrones House of the Dragon et la s\u00e9rie HBO Euphoria.<\/p>\n<h2 id=\"h-kritik-an-serie-dahmer\">Critique de la s\u00e9rie &#8220;Dahmer&#8221;<\/h2>\n<p>Peut-\u00eatre que &#8220;Dahmer&#8221; a aussi un tel succ\u00e8s parce que la s\u00e9rie ne peut pas se passer de critiques.  Surtout, les proches des victimes sont tr\u00e8s critiques vis-\u00e0-vis du tournage des \u00e9v\u00e9nements de cette \u00e9poque.  Par exemple, Eric Thulhu, parent d&#8217;Errol Lindsey, qui a \u00e9t\u00e9 tu\u00e9 en 1991, a d\u00e9clar\u00e9 dans un post sur Twitter que sa famille (les Isbells) \u00e9tait furieuse contre cette \u00e9mission.  \u00ab Elle n&#8217;arr\u00eate pas de re-traumatiser, et pour quoi ?  De combien de films\/\u00e9missions\/documentaires avons-nous encore besoin ?&#8221; Rita Isbell, la s\u0153ur de l&#8217;homme assassin\u00e9, a \u00e9galement d\u00e9clar\u00e9 qu&#8217;elle n&#8217;avait jamais \u00e9t\u00e9 contact\u00e9e au sujet de la s\u00e9rie.<\/p>\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\">\n<div class=\"wp-block-embed__wrapper\">\n<div class=\"embed-placeholder__container\" data-purpose-id=\"5e8794bab31ef52cd96cde4d\" vendor=\"5e71760b69966540e4554f01\" data-nosnippet=\"true\">\n<p>C&#8217;est ici que vous trouverez le contenu de Twitter<\/p>\n<p>Afin d&#8217;interagir avec ou d&#8217;afficher le contenu des r\u00e9seaux sociaux, nous avons besoin de votre consentement.<\/p>\n<p>\t<button class=\"embed-placeholder__button social\">Activer les r\u00e9seaux sociaux<\/button><\/p>\n<\/div>\n<\/div>\n<\/figure>\n<p>L&#8217;accusation g\u00e9n\u00e9rale des personnes concern\u00e9es : Netflix s&#8217;enrichirait financi\u00e8rement de leurs souffrances.  Au cours des derniers mois et ann\u00e9es, le service de streaming a soit produit lui-m\u00eame un grand nombre d&#8217;histoires de crimes r\u00e9els, soit les a ajout\u00e9es \u00e0 sa gamme.  Le fournisseur montre \u00e9galement les histoires de Ted Bundy, John Wayne Gacy et d&#8217;autres tueurs en s\u00e9rie.  Il existe \u00e9galement de nombreux documentaires qui \u00e9clairent les histoires de crimes ou de leurs auteurs.  Apparemment, de telles histoires sont tr\u00e8s bien re\u00e7ues par les clients du streaming.  Mais l&#8217;histoire n&#8217;est pas finie avec &#8220;Dahmer&#8221;.  Le documentaire Jeffrey Dahmer : Autoportrait d&#8217;un tueur en s\u00e9rie est sur Netflix depuis le 7 octobre. <\/p>\n<p>Netflix a depuis r\u00e9pondu \u00e0 certaines critiques et supprim\u00e9 la cat\u00e9gorie LGBTQ.  La s\u00e9rie a \u00e9t\u00e9 initialement attribu\u00e9e \u00e0 cette cat\u00e9gorie parce que Dahmer a cherch\u00e9 et trouv\u00e9 ses victimes dans la communaut\u00e9 LGBTQ de Milwaukee.  Pourtant, la narration des \u00e9v\u00e9nements de l&#8217;\u00e9poque dans la s\u00e9rie Netflix a encore une fois \u00e9branl\u00e9 la communaut\u00e9 et r\u00e9veill\u00e9 de vieux r\u00eaves.  L&#8217;interpr\u00e8te de drag BJ Daniels a racont\u00e9 &#8220;<a rel=\"nofollow noopener\" href=\"https:\/\/www.wisn.com\/\" target=\"_blank\">WISN<\/a>&#8220;J&#8217;ai l&#8217;impression que la journ\u00e9e f\u00e9tichise tout cet horrible moment de l&#8217;histoire de Milwaukee.  Ce n&#8217;est pas cens\u00e9 \u00eatre vu de cette fa\u00e7on, c&#8217;est juste compl\u00e8tement faux.  Je sais que beaucoup de mes amis et de nombreuses personnes qui ont v\u00e9cu cette p\u00e9riode ne regarderont pas la s\u00e9rie.  Vous n&#8217;allez pas mettre de l&#8217;argent dans la poche de quelqu&#8217;un qui d\u00e9range litt\u00e9ralement les tombes des victimes.&#8221;<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.techbook.de\/streaming\/programm\/netflix-serie-dahmer-1\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-35<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Rita Deutschbein et Marlene Polywka | 07 d\u00e9cembre 2022 15 h 36 Netflix propose un assortiment color\u00e9 de toutes sortes de films et de s\u00e9ries. De temps en temps, un titre en particulier suscite l&#8217;int\u00e9r\u00eat des utilisateurs. C&#8217;est \u00e9galement le cas avec une nouvelle s\u00e9rie bas\u00e9e sur des \u00e9v\u00e9nements r\u00e9els. Maintenant, il a m\u00eame [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":408446,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[1820,30882,198],"class_list":["post-499877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-cest","tag-recherchee","tag-serie"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/499877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=499877"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/499877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/408446"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=499877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=499877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=499877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}