{"id":497651,"date":"2022-12-06T07:37:34","date_gmt":"2022-12-06T09:37:34","guid":{"rendered":"https:\/\/teknomers.com\/fr\/istat-estimation-du-pib-2022-a-39-ralentissement-en-2023-a-04\/"},"modified":"2022-12-06T07:37:35","modified_gmt":"2022-12-06T09:37:35","slug":"istat-estimation-du-pib-2022-a-39-ralentissement-en-2023-a-04","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/istat-estimation-du-pib-2022-a-39-ralentissement-en-2023-a-04\/","title":{"rendered":"Istat\u00a0: estimation du PIB 2022 \u00e0 +3,9\u00a0%, ralentissement en 2023 \u00e0 +0,4\u00a0%"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>\u00c9couter la version audio de l&#8217;article<\/button><\/p>\n<p class=\"atext\">Le PIB italien devrait cro\u00eetre \u00e0 un rythme toujours soutenu en 2022 (+3,9%) puis ralentir nettement en 2023 (+0,4%).  Istat le communique dans son rapport sur les perspectives de l&#8217;\u00e9conomie italienne en 2022-2023, pr\u00e9cisant que l&#8217;augmentation du PIB serait soutenue par la contribution de la demande int\u00e9rieure nette des stocks, tandis que la demande ext\u00e9rieure nette apporterait une contribution n\u00e9gative les deux ann\u00e9es.  Les investissements devraient repr\u00e9senter le moteur de l&#8217;\u00e9conomie italienne tant en 2022 (+10,0 %) que, dans une moindre mesure, en 2023 (+2,0 %).  En juin, Istat estimait +2,8% pour 2022 et +1,9% pour 2023.<\/p>\n<p><h2 id=\"U402021849226T2G\">Fitch revoit ses attentes pour l&#8217;Italie : en 2023 seulement -0,1% du PIB<br \/><\/h2>\n<\/p>\n<p class=\"atext\">Fitch r\u00e9vise les perspectives pour l&#8217;Italie et n&#8217;attend plus que -0,1% du PIB en 2023. &#8220;Nous maintenons notre pr\u00e9vision d&#8217;une contraction \u00e0 partir du quatri\u00e8me trimestre &#8211; expliquent les analystes &#8211; bas\u00e9e sur la forte exposition au choc du prix du gaz l&#8217;impact des hausses de prix sur la consommation priv\u00e9e, mais nous avons r\u00e9duit cet impact et estimons maintenant la croissance globale pour 2022 \u00e0 3,7\u00a0%.  Nous avons \u00e9galement r\u00e9duit nos pr\u00e9visions de contraction pour 2023 de 0,6 point de pourcentage \u00e0 -0,1 % gr\u00e2ce \u00e0 une am\u00e9lioration de la contribution du quatri\u00e8me trimestre et \u00e0 une l\u00e9g\u00e8re att\u00e9nuation de la crise du gaz.<\/p>\n<p><h2 id=\"U4020218492260RH\">L&#8217;emploi cro\u00eet plus vite que le PIB : +4,3% en 2022 <\/h2>\n<\/p>\n<p class=\"atext\">Cette ann\u00e9e et la suivante, l&#8217;emploi, mesur\u00e9 en termes d&#8217;unit\u00e9s de travail (UTA), marquera une croissance sup\u00e9rieure \u00e0 celle du PIB avec une hausse plus prononc\u00e9e en 2022 (+4,3%) par rapport \u00e0 celle de 2023 (+0,5%).  C&#8217;est ce qui ressort du rapport Istat sur les perspectives de l&#8217;\u00e9conomie italienne en 2022 et 2023. L&#8217;am\u00e9lioration de l&#8217;emploi ira de pair avec celle du taux de ch\u00f4mage, qui baissera sensiblement cette ann\u00e9e (8,1%) pour ensuite enregistrer une l\u00e9g\u00e8re hausse en 2023 (8,2%).<\/p>\n<p><h2 id=\"U402021849226TFB\">L&#8217;inflation ralentira, mais les temps sont encore incertains <\/h2>\n<\/p>\n<p class=\"atext\">L&#8217;inflation devrait ralentir au cours des prochains mois, bien qu&#8217;avec un calendrier et une intensit\u00e9 incertains.  C&#8217;est ce qu&#8217;a not\u00e9 Istat dans le Rapport sur les perspectives de l&#8217;\u00e9conomie italienne en 2022 et 2023. En moyenne pour 2022, le taux de variation du d\u00e9flateur des d\u00e9penses des m\u00e9nages devrait cro\u00eetre (+8,2 %, il \u00e9tait de +1,6 %). en 2021) tandis que le d\u00e9flateur du PIB marquera une hausse significative mais plus limit\u00e9e (+3,6%, il \u00e9tait de +0,5% en 2021).  En supposant que les pressions \u00e0 la hausse sur les prix des mati\u00e8res premi\u00e8res seront contenues dans les mois \u00e0 venir et en pr\u00e9sence d&#8217;une stabilisation des taux de p\u00e9trole et de change, ajoute Istat, l&#8217;inflation devrait d\u00e9c\u00e9l\u00e9rer partiellement l&#8217;ann\u00e9e prochaine.  L&#8217;Institut de la statistique explique en outre que la phase prolong\u00e9e de croissance des prix, soutenue par la hausse exceptionnelle de ceux des biens \u00e9nerg\u00e9tiques, devrait se refl\u00e9ter dans l&#8217;\u00e9volution du d\u00e9flateur des d\u00e9penses des m\u00e9nages r\u00e9sidents tant pour l&#8217;ann\u00e9e en cours (+8,2 %) que pour , dans une moindre mesure, en 2023 (+5,4 %).<\/p>\n<div class=\"acor acor--mkt\">\n<div class=\"\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--isq\" href=\"https:\/\/consigli24.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><\/figure>\n<p><\/a><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/istat-stima-pil-2022-39percento-frena-2023-04percento-AEYVdzMC\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9couter la version audio de l&#8217;article Le PIB italien devrait cro\u00eetre \u00e0 un rythme toujours soutenu en 2022 (+3,9%) puis ralentir nettement en 2023 (+0,4%). Istat le communique dans son rapport sur les perspectives de l&#8217;\u00e9conomie italienne en 2022-2023, pr\u00e9cisant que l&#8217;augmentation du PIB serait soutenue par la contribution de la demande int\u00e9rieure nette des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":497652,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[30470,13317,7141,5521],"class_list":["post-497651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-estimation","tag-istat","tag-pib","tag-ralentissement"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/497651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=497651"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/497651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/497652"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=497651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=497651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=497651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}