{"id":496564,"date":"2022-12-05T15:22:23","date_gmt":"2022-12-05T17:22:23","guid":{"rendered":"https:\/\/teknomers.com\/fr\/bonaccini-schlein-la-contestation-identitaire-qui-risque-de-faire-exploser-le-parti-democrate\/"},"modified":"2022-12-05T15:22:25","modified_gmt":"2022-12-05T17:22:25","slug":"bonaccini-schlein-la-contestation-identitaire-qui-risque-de-faire-exploser-le-parti-democrate","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/bonaccini-schlein-la-contestation-identitaire-qui-risque-de-faire-exploser-le-parti-democrate\/","title":{"rendered":"Bonaccini-Schlein, la contestation identitaire qui risque de faire exploser le Parti d\u00e9mocrate"},"content":{"rendered":"\n<div>\n<p><h2 id=\"U402018084264sCI\"> <b>La fente contre Matteo Renzi : des choix m\u00e9chants <\/b> <br \/><\/h2>\n<\/p>\n<p class=\"atext\">La fente contre Matteo Renzi va \u00e9galement dans ce sens, qui le jour o\u00f9 l&#8217;assembl\u00e9e d&#8217;Italia Viva donne le feu vert \u00e0 la f\u00e9d\u00e9ration avec l&#8217;Action calendienne rappelle que c&#8217;est lui, en tant que secr\u00e9taire du Parti d\u00e9mocrate, qui l&#8217;a nomm\u00e9 pour les \u00e9lections europ\u00e9ennes de 2014 et donc \u00ab sans moi Schlein ne serait personne \u00bb.  \u00ab J&#8217;ai \u00e9t\u00e9 \u00e9lu \u00e0 Strasbourg gr\u00e2ce aux 53 000 pr\u00e9f\u00e9rences prises lors d&#8217;une campagne de porte-\u00e0-porte &#8211; r\u00e9pond Schlein -.  Au lieu de cela, Renzi doit avoir le m\u00e9rite de m&#8217;avoir pouss\u00e9, ainsi que beaucoup d&#8217;autres, hors du Parti d\u00e9mocrate avec une gestion arrogante, incapable de synth\u00e9tiser la diversit\u00e9 \u00bb.  Et encore : &#8220;Apr\u00e8s avoir humili\u00e9 quiconque avait une id\u00e9e diff\u00e9rente, avec ses mauvais choix il a laiss\u00e9 un champ de d\u00e9combres&#8230; ceux qui filtrent avec la droite ne nous diront pas ce que nous devons faire pour reconstruire la gauche&#8221;.<\/p>\n<p><h2 id=\"U402018084264RtG\"> <b>Non au Jobs Act, oui au revenu de base : la vision de Schlein<\/b> <br \/><\/h2>\n<\/p>\n<p class=\"atext\">Et c&#8217;est ainsi que la r\u00e9forme du travail de Renzi, la loi Jobs, devient le symbole de tous les maux dans la chambre du Moine, \u00e0 r\u00e9primer.  Et c&#8217;est ainsi que r\u00e9sonnent avec force les mots d&#8217;ordre de la gauche : de la n\u00e9cessit\u00e9 d&#8217;une plus grande redistribution (le mot patrimonial ne se prononce pas mais est dans l&#8217;air) \u00e0 la d\u00e9fense du revenu de base avec un clin d&#8217;\u0153il clair au M5, alli\u00e9 d&#8217;hier et surtout de demain (&#8220;\u00e7a a emp\u00each\u00e9 un million de pauvres&#8221;);  de la mise en accusation du \u00ab mod\u00e8le n\u00e9olib\u00e9ral qui se nourrit des in\u00e9galit\u00e9s et est inadapt\u00e9 \u00e0 la plan\u00e8te \u00bb aux trois d\u00e9fis sur \u00ab les in\u00e9galit\u00e9s, le climat et la pr\u00e9carit\u00e9 \u00bb.<\/p>\n<p class=\"atext\"><b>Croissance et m\u00e9rite : les mots r\u00e9cup\u00e9r\u00e9s par Bonaccini<\/b> <br \/>Les mots qui manquent \u00e0 la vision de Schlein sont croissance et m\u00e9rite, tr\u00e8s pr\u00e9sents par contre dans le discours de Bonaccini sur le terrain le 20 novembre dernier.  Le gouverneur d&#8217;\u00c9milie-Romagne rappelle que le Parti d\u00e9mocrate doit \u00eatre le parti de la croissance car sans richesse il ne peut y avoir de redistribution et que le mot m\u00e9rite est de gauche car c&#8217;est le principal ascenseur social dont disposent les pauvres.  Bonaccini imagine un parti \u00ab des travaux \u00bb au lieu de \u00ab du travail \u00bb, car il n&#8217;y a pas que des salari\u00e9s et des ouvriers : il y a des jeunes travailleurs pr\u00e9caires auxquels il faut r\u00e9pondre, bien s\u00fbr, mais il y a aussi des millions d&#8217;ind\u00e9pendants et Num\u00e9ros de TVA que &#8220;nous ne pouvons pas laisser \u00e0 droite&#8221;.  Il est clair que le Parti d\u00e9mocrate que Schlein a en t\u00eate (&#8220;il faut un nouveau parti&#8221;, disent ceux qui n&#8217;ont pas encore adh\u00e9r\u00e9 \u00e0 ce parti par hasard) est un parti \u00e0 forte identit\u00e9 qui tourne compl\u00e8tement \u00e0 gauche alors que celui de Bonaccini imagine est toujours le parti veltronien \u00e0 vocation majoritaire, c&#8217;est-\u00e0-dire le parti qui a l&#8217;ambition de parler \u00e0 tout le pays et \u00e0 toutes les classes sociales et pas seulement \u00e0 une partie de celui-ci.<\/p>\n<p><h2 id=\"U4020180842648jE\"> <b>Le risque de se s\u00e9parer : celui qui perd la partie s&#8217;enfuira-t-il avec le ballon ?<\/b> <br \/><\/h2>\n<\/p>\n<p class=\"atext\">Si Schlein l&#8217;emportait, les r\u00e9formistes d&#8217;origine catholique et lib\u00e9rale-d\u00e9mocrate se sentiraient-ils toujours repr\u00e9sent\u00e9s ?  Et la gauche qui frappe avec force aux portes du Parti d\u00e9mocrate &#8211; en plus de l&#8217;interne, Schlein elle-m\u00eame et les Bersaniens de l&#8217;article 1 sur le point de rejoindre le parti avec leur chef Roberto Speranza &#8211; se sentiraient-elles chez elles si Bonaccini devait gagner \u00e0 la place ?  Beaucoup sont convaincus que de toute fa\u00e7on le congr\u00e8s dem mettra fin \u00e0 une nouvelle scission, apr\u00e8s celle de Bersani en 2017 et de Renzi en 2019, qu&#8217;il faudra prendre en compte.<\/p>\n<p><h2 id=\"U402018084264JcE\"> <b>L&#8217;ombre de Renzi sur le congr\u00e8s dem<\/b> <br \/><\/h2>\n<\/p>\n<p class=\"atext\">Certes, ce n&#8217;est pas un hasard si le leitmotiv de la discussion au Congr\u00e8s porte toujours le nom de Renzi, si durement attaqu\u00e9 par Schein dans son discours et utilis\u00e9 par les d\u00e9tracteurs de Bonaccini d\u00e9sormais en tandem avec Nardella au cri de &#8220;tu es Renziani&#8221; ou &#8220;tu es le cheval diTroia qui ram\u00e8nera Renzi au Parti d\u00e9mocrate&#8221;.  Renzi est en effet le leader qui a le plus tendu la corde du Parti d\u00e9mocrate du c\u00f4t\u00e9 du r\u00e9formisme gouvernemental au point de la rompre \u00e0 gauche.  Et maintenant, paradoxalement, elle pourrait b\u00e9n\u00e9ficier des effets de la corde raide de l&#8217;autre c\u00f4t\u00e9 jusqu&#8217;\u00e0 ce qu&#8217;elle casse du c\u00f4t\u00e9 du r\u00e9formisme.  Car force est de constater que si l&#8217;ancien Premier ministre se rapproche id\u00e9alement de Bonaccini et de Nardella, ses anciens bras droit et gauche au moment de la prise de pouvoir du Nazar\u00e9en et de la contestation gouvernementale, il esp\u00e8re en son for int\u00e9rieur que Schlein l&#8217;emportera pour le &#8221; prairies&#8221; qu&#8217;ils ouvriraient \u00e0 la nouvelle formation politique &#8211; la &#8220;maison des r\u00e9formistes&#8221;, en fait &#8211; qui se construit avec Carlo Calenda.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/bonaccini-schlein-sfida-identitaria-che-rischia-far-esplodere-pd-AEM4pjMC\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fente contre Matteo Renzi : des choix m\u00e9chants La fente contre Matteo Renzi va \u00e9galement dans ce sens, qui le jour o\u00f9 l&#8217;assembl\u00e9e d&#8217;Italia Viva donne le feu vert \u00e0 la f\u00e9d\u00e9ration avec l&#8217;Action calendienne rappelle que c&#8217;est lui, en tant que secr\u00e9taire du Parti d\u00e9mocrate, qui l&#8217;a nomm\u00e9 pour les \u00e9lections europ\u00e9ennes de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":496565,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[129882,43278,37,939,365,129883,35,364,326],"class_list":["post-496564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-bonaccinischlein","tag-contestation","tag-democrate","tag-exploser","tag-faire","tag-identitaire","tag-parti","tag-qui","tag-risque"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/496564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=496564"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/496564\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/496565"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=496564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=496564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=496564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}