{"id":496348,"date":"2022-12-05T12:21:30","date_gmt":"2022-12-05T14:21:30","guid":{"rendered":"https:\/\/teknomers.com\/fr\/pont-sur-le-detroit-ue-nous-sommes-disposes-a-financer-la-premiere-phase\/"},"modified":"2022-12-05T12:21:31","modified_gmt":"2022-12-05T14:21:31","slug":"pont-sur-le-detroit-ue-nous-sommes-disposes-a-financer-la-premiere-phase","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/pont-sur-le-detroit-ue-nous-sommes-disposes-a-financer-la-premiere-phase\/","title":{"rendered":"Pont sur le d\u00e9troit, UE : nous sommes dispos\u00e9s \u00e0 financer la premi\u00e8re phase"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>\u00c9couter la version audio de l&#8217;article<\/button><\/p>\n<p class=\"atext\">L&#8217;UE tend la main au projet du pont du d\u00e9troit de Messine et se d\u00e9clare pr\u00eate \u00e0 financer la premi\u00e8re partie du projet.  \u00ab Nous n&#8217;avons pas seulement discut\u00e9 de l&#8217;inclusion \u00bb du pont du d\u00e9troit de Messine dans le Ten-T, \u00ab qui existait d\u00e9j\u00e0, je sais que c&#8217;est tr\u00e8s important pour le gouvernement italien, nous avons discut\u00e9 des prochaines \u00e9tapes et nous nous sommes rendus disponibles.  Nous attendons un projet solide pour financer la premi\u00e8re phase de faisabilit\u00e9 et ensuite le projet d\u00e9marrera&#8221;.<\/p>\n<p class=\"atext\">C&#8217;est ce qu&#8217;a d\u00e9clar\u00e9 la commissaire europ\u00e9enne aux transports, Adina Valean, en r\u00e9ponse \u00e0 une question sur la rencontre avec le vice-Premier ministre Matteo Salvini.  &#8220;En plus d&#8217;avoir une intention, vous devez avoir une phase de pr\u00e9paration, puis \u00eatre pr\u00eat pour la construction proprement dite&#8221;, a-t-il soulign\u00e9.<\/p>\n<p class=\"atext\">La volont\u00e9 politique est donc d&#8217;acc\u00e9l\u00e9rer le projet qui relierait la Sicile au continent par le rail et la route.  &#8220;L&#8217;objectif est, si tout se passe comme je l&#8217;esp\u00e8re et comme l&#8217;esp\u00e8re l&#8217;Italie, de commencer les travaux &#8211; a ajout\u00e9 le ministre Salvini en marge du Conseil de l&#8217;UE &#8211; d&#8217;ici deux ans, unir Palerme \u00e0 Berlin et Amsterdam est quelque chose de pertinent.  J&#8217;esp\u00e8re qu&#8217;il n&#8217;y a pas de professionnels du non, en activit\u00e9 constante pour bloquer ces grands travaux&#8221;, conclut-il.<\/p>\n<div class=\"acor acor--mkt\">\n<div class=\"\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--isq\" href=\"https:\/\/consigli24.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><\/figure>\n<p><\/a><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/ponte-stretto-ue-siamo-disponibili-finanziare-prima-fase-AElbTkMC\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9couter la version audio de l&#8217;article L&#8217;UE tend la main au projet du pont du d\u00e9troit de Messine et se d\u00e9clare pr\u00eate \u00e0 financer la premi\u00e8re partie du projet. \u00ab Nous n&#8217;avons pas seulement discut\u00e9 de l&#8217;inclusion \u00bb du pont du d\u00e9troit de Messine dans le Ten-T, \u00ab qui existait d\u00e9j\u00e0, je sais que c&#8217;est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":496349,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[15110,19694,11666,1266,1694,17329,675,4634,60],"class_list":["post-496348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-detroit","tag-disposes","tag-financer","tag-nous","tag-phase","tag-pont","tag-premiere","tag-sommes","tag-sur"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/496348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=496348"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/496348\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/496349"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=496348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=496348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=496348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}