{"id":496044,"date":"2022-12-05T08:48:34","date_gmt":"2022-12-05T10:48:34","guid":{"rendered":"https:\/\/teknomers.com\/fr\/le-showrunner-de-witcher-comprend-parfaitement-les-inquietudes-des-fans-concernant-le-depart-dhenry-cavill\/"},"modified":"2022-12-05T08:48:36","modified_gmt":"2022-12-05T10:48:36","slug":"le-showrunner-de-witcher-comprend-parfaitement-les-inquietudes-des-fans-concernant-le-depart-dhenry-cavill","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/le-showrunner-de-witcher-comprend-parfaitement-les-inquietudes-des-fans-concernant-le-depart-dhenry-cavill\/","title":{"rendered":"Le showrunner de Witcher &#8220;comprend parfaitement&#8221; les inqui\u00e9tudes des fans concernant le d\u00e9part d&#8217;Henry Cavill"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"article-body\">\n<p>La showrunner de Witcher, Lauren Hissrich, dit qu&#8217;elle &#8220;comprend parfaitement&#8221; pourquoi les fans sont furieux du d\u00e9part prochain d&#8217;Henry Cavill.<\/p>\n<p>S&#8217;adressant exclusivement \u00e0 TechRadar lors du junket britannique de The Witcher: Blood Origin, Hissrich a d\u00e9clar\u00e9 qu&#8217;elle sympathisait avec les t\u00e9l\u00e9spectateurs au sujet de Cavill quittant l&#8217;\u00e9mission \u00e0 succ\u00e8s Netflix.  Cependant, Hissrich a simultan\u00e9ment appel\u00e9 les fans \u00e0 rester fid\u00e8les \u00e0 la s\u00e9rie t\u00e9l\u00e9vis\u00e9e, m\u00eame si Cavill ne fera pas partie de son casting plus longtemps.<\/p>\n<aside class=\"hawk-nest\" data-render-type=\"fte\" data-skip=\"dealsy\" data-widget-type=\"seasonal\"\/>\n<p>La r\u00e9ponse de Hissrich intervient cinq semaines apr\u00e8s qu&#8217;il a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 que l&#8217;acteur principal de la s\u00e9rie ne reviendrait pas en tant que Geralt de Riv apr\u00e8s la saison 3 de The Witcher. La s\u00e9rie fantastique, qui revient au deuxi\u00e8me trimestre 2023, mettra le rideau sur le r\u00e8gne de Cavill, avec Liam Hemsworth &#8211; fr\u00e8re de la star de cin\u00e9ma Marvel Chris Hemsworth \u2013 rempla\u00e7ant Cavill \u00e0 partir de la saison 4.<\/p>\n<p>Dans les jours qui ont suivi, la base de fans de The Witcher a exprim\u00e9 son choc et sa consternation que Cavill s&#8217;\u00e9loigne de l&#8217;un de ses r\u00f4les de r\u00eave.  UN <a rel=\"nofollow noopener\" href=\"https:\/\/www.change.org\/p\/netflix-you-must-keep-henry-cavill-as-the-witcher-and-replace-the-writers-instead\" target=\"_blank\" data-url=\"https:\/\/www.change.org\/p\/netflix-you-must-keep-henry-cavill-as-the-witcher-and-replace-the-writers-instead\">P\u00e9tition Change.org<\/a><span class=\"sr-only\">  (s&#8217;ouvre dans un nouvel onglet)<\/span> \u2013 qui compte actuellement plus de 275 000 signatures \u2013 a m\u00eame \u00e9t\u00e9 mis en place, appelant Netflix \u00e0 essayer de persuader Cavill de rester et de renvoyer l&#8217;\u00e9quipe de r\u00e9daction de l&#8217;\u00e9mission \u00e0 la place.<\/p>\n<p>Pour sa part, Hissrich dit qu&#8217;elle comprend parfaitement la col\u00e8re des fans envers elle et le reste des cr\u00e9ateurs de la s\u00e9rie.  Cependant, elle a \u00e9galement appel\u00e9 la base de fans de The Witcher \u00e0 continuer de soutenir ses acteurs et son \u00e9quipe, ajoutant que ne pas le faire serait au d\u00e9triment du prochain spin-off Blood Origin et des futures saisons de la s\u00e9rie principale de The Witcher.<\/p>\n<p>&#8220;C&#8217;est aussi un gros probl\u00e8me pour nous&#8221;, a admis Hissrich lorsque TechRadar a mentionn\u00e9 \u00e0 quel point les fans avaient r\u00e9agi n\u00e9gativement au d\u00e9part imminent de Cavill.  &#8220;Et c&#8217;est le probl\u00e8me &#8211; il y a beaucoup de discussions et de rumeurs \u00e0 ce sujet et nous comprenons parfaitement pourquoi les fans y vont. <\/p>\n<p>&#8220;Ce que je dirai, c&#8217;est s&#8217;il vous pla\u00eet, revenez pour la troisi\u00e8me saison de The Witcher afin que nous puissions continuer \u00e0 le faire. \u00c9videmment, cela [Cavill&#8217;s departure] est une \u00e9norme nouvelle.  Mais ce que je ne veux pas faire, c&#8217;est que \u00e7a doit rester \u00e0 propos de Blood Origin, Declan [de Barra, Blood Origin&#8217;s showrunner], les acteurs et l&#8217;\u00e9quipe.  C&#8217;est leur moment sous les projecteurs.&#8221;<\/p>\n<p>Cavill est un superfan de Witcher autoproclam\u00e9 et son interpr\u00e9tation de Geralt a \u00e9t\u00e9 un moment fort de l&#8217;une des meilleures \u00e9missions de Netflix au cours de ses deux premi\u00e8res saisons.  Sans lui, les fans craignent que la s\u00e9rie principale ne s&#8217;\u00e9carte davantage des sources de l&#8217;auteur Andrzej Sapkowski, une grande partie de la base de fans critiquant auparavant les d\u00e9viations bas\u00e9es sur l&#8217;intrigue prises par l&#8217;\u00e9quipe cr\u00e9ative de la s\u00e9rie dans The Witcher saison 2.<\/p>\n<p>En tant que grand fan de Witcher, Cavill a \u00e9t\u00e9 aussi vocal que sa base de fans sur son souhait que la s\u00e9rie colle plus \u00e9troitement aux romans fantastiques de Sapkowski.  En d\u00e9cembre 2021, il a d\u00e9clar\u00e9 \u00e0 Netflix <a rel=\"nofollow noopener\" href=\"https:\/\/www.youtube.com\/watch?v=_Mjhw6q7E80&amp;feature=emb_title\" target=\"_blank\" data-url=\"https:\/\/www.youtube.com\/watch?v=_Mjhw6q7E80&amp;feature=emb_title\">Aftershow d\u00e9bloqu\u00e9 de la saison 2 de The Witcher<\/a><span class=\"sr-only\">  (s&#8217;ouvre dans un nouvel onglet)<\/span>: &#8220;Je suis un grand fan des livres et je leur reste fid\u00e8le, et il s&#8217;agit de s&#8217;assurer que l&#8217;histoire se d\u00e9roule sans trop de d\u00e9tournements ou de choses secondaires qui viennent brouiller les pistes.&#8221;<\/p>\n<p>De multiples rumeurs ont circul\u00e9 en ligne depuis que la nouvelle du d\u00e9part de Cavill a \u00e9clat\u00e9, de nombreux fans sugg\u00e9rant qu&#8217;il s&#8217;\u00e9tait brouill\u00e9 avec les sc\u00e9naristes et les producteurs de la s\u00e9rie sur la direction de l&#8217;histoire de la s\u00e9rie.  Toujours gentleman, Cavill n&#8217;a pas exprim\u00e9 d&#8217;animosit\u00e9 envers l&#8217;\u00e9quipe cr\u00e9ative de la s\u00e9rie dans son propre <a rel=\"nofollow noopener\" href=\"https:\/\/www.instagram.com\/p\/CkTv9FyPnNz\/\" target=\"_blank\" data-url=\"https:\/\/www.instagram.com\/p\/CkTv9FyPnNz\/\">Publication Instagram<\/a><span class=\"sr-only\">  (s&#8217;ouvre dans un nouvel onglet)<\/span> \u00e0 propos de quitter l&#8217;\u00e9mission t\u00e9l\u00e9vis\u00e9e Witcher.  Au lieu de cela, il a choisi de demander \u00e0 Liam Hemsworth de poursuivre l&#8217;h\u00e9ritage de Geralt dans l&#8217;adaptation en direct.<\/p>\n<p>De toute \u00e9vidence, seules quelques personnes connaissent la v\u00e9rit\u00e9 derri\u00e8re le d\u00e9part de Cavill de la s\u00e9rie et il est tr\u00e8s peu probable que nous le sachions un jour.  Les commentaires de Hissrich, cependant, ne feront pas grand-chose pour apaiser les sp\u00e9culations des fans sur les raisons pour lesquelles il a pass\u00e9 du temps \u00e0 jouer \u00e0 Geralt \u2013 ou les convaincre de continuer \u00e0 regarder la s\u00e9rie principale de la s\u00e9rie et \/ ou de se transformer en ses retomb\u00e9es.<\/p>\n<p>TechRadar vous apportera plus de couverture de Blood Origin dans la perspective de sa sortie le 25 d\u00e9cembre.  Alors revenez avec nous au cours des deux prochaines semaines pour plus d&#8217;exclusivit\u00e9s et nos r\u00e9flexions compl\u00e8tes sur le deuxi\u00e8me projet d\u00e9riv\u00e9 de The Witcher.<\/p>\n<p>Pour plus de contenu Netflix et The Witcher, consultez les meilleurs films Netflix et les meilleurs documentaires Netflix.  Sinon, d\u00e9couvrez comment lire les livres de Witcher dans l&#8217;ordre ou regardez l&#8217;un de ces cinq fantasmes sanglants en attendant l&#8217;arriv\u00e9e de la saison 3.<\/p>\n<aside class=\"hawk-nest\" data-model-name=\"netflix\" data-widget-type=\"review\" data-render-type=\"editorial\">\n<div class=\"hawk-main-editorialized\">\n<div>\n<p>Les meilleures offres Netflix du jour<\/p>\n<div class=\"hawk-grid-items-review\" data-stacked=\"1\">\n<div class=\"hawk-grid-item-container hawk-grid-item-review\" data-expandable=\"0\" data-stacked=\"1\" aria-hidden=\"true\">\n<div class=\"hawk-grid-item-main-container hawk-grid-item-main-review\" data-product-type=\"2500\" data-button-type=\"\" data-stacked=\"1\" data-expanded=\"0\">\n<div class=\"hawk-grid-item-block-container hawk-grid-item-block-review\" data-name=\"image\" data-product-type=\"2500\" data-button-type=\"\" data-stacked=\"1\"><a rel=\"nofollow noopener\" data-google-interstitial=\"false\" aria-label=\"View Netflix on Netflix\" href=\"https:\/\/www.anrdoezrs.net\/links\/6361382\/type\/dlg\/sid\/trd-us-1518268972449490000\/https:\/\/www.netflix.com\/\" target=\"_blank\" referrerpolicy=\"no-referrer-when-downgrade\" class=\"hawk-affiliate-link-container\" data-product-key=\"55529-775999104\" data-url=\"https:\/\/www.anrdoezrs.net\/links\/6361382\/type\/dlg\/sid\/trd-us-1518268972449490000\/https:\/\/www.netflix.com\/\" data-model-id=\"2414\" data-match-id=\"142219953\" data-product-type=\"2500\" role=\"link\" tabindex=\"0\"><\/a><span class=\"sr-only\">  (s&#8217;ouvre dans un nouvel onglet)<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"hawk-grid-item-container hawk-grid-item-review\" data-expandable=\"0\" data-stacked=\"1\" aria-hidden=\"true\">\n<div class=\"hawk-grid-item-main-container hawk-grid-item-main-review\" data-product-type=\"2500\" data-button-type=\"\" data-stacked=\"1\" data-expanded=\"0\">\n<div class=\"hawk-grid-item-block-container hawk-grid-item-block-review\" data-name=\"image\" data-product-type=\"2500\" data-button-type=\"\" data-stacked=\"1\"><a rel=\"nofollow noopener\" data-google-interstitial=\"false\" aria-label=\"View Netflix on Netflix\" href=\"https:\/\/www.anrdoezrs.net\/links\/6361382\/type\/dlg\/sid\/trd-us-4958303980784718000\/https:\/\/www.netflix.com\/signup\/planform\" target=\"_blank\" referrerpolicy=\"no-referrer-when-downgrade\" class=\"hawk-affiliate-link-container\" data-product-key=\"55529-511345064\" data-url=\"https:\/\/www.anrdoezrs.net\/links\/6361382\/type\/dlg\/sid\/trd-us-4958303980784718000\/https:\/\/www.netflix.com\/signup\/planform\" data-model-id=\"2414\" data-match-id=\"607261\" data-product-type=\"2500\" role=\"link\" tabindex=\"0\"><img decoding=\"async\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2022\/09\/1662732624_438_7-nouveaux-films-et-emissions-de-television-sur-Netflix-Prime.png\" alt=\"Netflix\" title=\"Netflix\" class=\"hawk-lazy-image-image\" draggable=\"false\" loading=\"lazy\" width=\"80\" height=\"40\"\/><\/a><span class=\"sr-only\">  (s&#8217;ouvre dans un nouvel onglet)<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"hawk-grid-item-container hawk-grid-item-review\" data-expandable=\"0\" data-stacked=\"1\" aria-hidden=\"true\">\n<div class=\"hawk-grid-item-main-container hawk-grid-item-main-review\" data-product-type=\"2500\" data-button-type=\"\" data-stacked=\"1\" data-expanded=\"0\">\n<div class=\"hawk-grid-item-block-container hawk-grid-item-block-review\" data-name=\"image\" data-product-type=\"2500\" data-button-type=\"\" data-stacked=\"1\"><a rel=\"nofollow noopener\" data-google-interstitial=\"false\" aria-label=\"View Netflix on Netflix\" href=\"https:\/\/www.anrdoezrs.net\/links\/6361382\/type\/dlg\/sid\/trd-us-1276900606254786300\/https:\/\/www.netflix.com\/\" target=\"_blank\" referrerpolicy=\"no-referrer-when-downgrade\" class=\"hawk-affiliate-link-container\" data-product-key=\"55529-775999112\" data-url=\"https:\/\/www.anrdoezrs.net\/links\/6361382\/type\/dlg\/sid\/trd-us-1276900606254786300\/https:\/\/www.netflix.com\/\" data-model-id=\"2414\" data-match-id=\"142219961\" data-product-type=\"2500\" role=\"link\" tabindex=\"0\"><img decoding=\"async\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2022\/09\/1662732624_438_7-nouveaux-films-et-emissions-de-television-sur-Netflix-Prime.png\" alt=\"Netflix\" title=\"Netflix\" class=\"hawk-lazy-image-image\" draggable=\"false\" loading=\"lazy\" width=\"80\" height=\"40\"\/><\/a><span class=\"sr-only\">  (s&#8217;ouvre dans un nouvel onglet)<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/aside>\n<\/div>\n<p><script async defer src=\"https:\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.techradar.com\/news\/the-witcher-showrunner-fully-understands-fan-concerns-over-henry-cavills-departure\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-59<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La showrunner de Witcher, Lauren Hissrich, dit qu&#8217;elle &#8220;comprend parfaitement&#8221; pourquoi les fans sont furieux du d\u00e9part prochain d&#8217;Henry Cavill. S&#8217;adressant exclusivement \u00e0 TechRadar lors du junket britannique de The Witcher: Blood Origin, Hissrich a d\u00e9clar\u00e9 qu&#8217;elle sympathisait avec les t\u00e9l\u00e9spectateurs au sujet de Cavill quittant l&#8217;\u00e9mission \u00e0 succ\u00e8s Netflix. Cependant, Hissrich a simultan\u00e9ment appel\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":496045,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[21627,7956,5748,1675,133,21626,734,4816,65,1916,47596,7469],"class_list":["post-496044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-cavill","tag-comprend","tag-concernant","tag-depart","tag-des","tag-dhenry","tag-fans","tag-inquietudes","tag-les","tag-parfaitement","tag-showrunner","tag-witcher"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/496044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=496044"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/496044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/496045"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=496044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=496044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=496044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}