{"id":495247,"date":"2022-12-04T17:44:28","date_gmt":"2022-12-04T19:44:28","guid":{"rendered":"https:\/\/teknomers.com\/fr\/les-revenus-publicitaires-de-twitter-ont-chute\/"},"modified":"2022-12-04T17:44:29","modified_gmt":"2022-12-04T19:44:29","slug":"les-revenus-publicitaires-de-twitter-ont-chute","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/les-revenus-publicitaires-de-twitter-ont-chute\/","title":{"rendered":"Les revenus publicitaires de Twitter ont chut\u00e9"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>Les revenus publicitaires de Twitter pour la semaine en cours sont inf\u00e9rieurs de 80\u00a0% aux attentes internes. <\/p>\n<div itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\" role=\"button\" tabindex=\"0\">\n<div class=\"article-image-container\" style=\"height:;padding-bottom:66.66666666666666%\"><img decoding=\"async\" class=\"image image-show\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2022\/12\/1670183068_957_Les-revenus-publicitaires-de-Twitter-ont-chute.jpg\"  alt=\"Les revenus publicitaires de Twitter sont tomb\u00e9s en de\u00e7\u00e0 des attentes cette semaine.\"\/><\/div>\n<p><meta itemprop=\"url\" content=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2022\/12\/1670183068_957_Les-revenus-publicitaires-de-Twitter-ont-chute.jpg\"\/><meta itemprop=\"width\" content=\"3000\"\/><meta itemprop=\"height\" content=\"2000\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Twitterin mainostulot ovat romahtaneet kuluvalla viikolla alle odotusten.\"\/><span class=\"caption-text\" itemprop=\"description\">Les revenus publicitaires de Twitter sont tomb\u00e9s en de\u00e7\u00e0 des attentes cette semaine.<!-- --> <\/span><span class=\"media-source\">AOP<\/span><\/p>\n<\/div>\n<div itemprop=\"articleBody\">\n<p class=\"paragraph\">Les revenus publicitaires de Twitter se sont consid\u00e9rablement effondr\u00e9s cette semaine, rapporte <a rel=\"noopener nofollow\" href=\"https:\/\/www.nytimes.com\/2022\/12\/02\/technology\/twitter-advertising-targets-missed.html?partner=slack&amp;smid=sl-share\" target=\"_blank\">Le New York Times<\/a>.<\/p>\n<p class=\"paragraph\">Des sources qui ont parl\u00e9 au journal r\u00e9v\u00e8lent que les revenus publicitaires de Twitter cette semaine sont inf\u00e9rieurs de 80% aux attentes internes.<\/p>\n<p class=\"paragraph\">Dans le m\u00eame temps, Twitter a rapidement revu \u00e0 la baisse ses pr\u00e9visions de b\u00e9n\u00e9fices.  La soci\u00e9t\u00e9 avait pr\u00e9c\u00e9demment pr\u00e9dit qu&#8217;elle g\u00e9n\u00e9rerait 1,4 milliard de dollars au cours des trois derniers mois de l&#8217;ann\u00e9e, mais l&#8217;objectif a \u00e9t\u00e9 soudainement abaiss\u00e9 \u00e0 1,3 milliard de dollars, puis \u00e0 1,1 milliard de dollars, ont r\u00e9v\u00e9l\u00e9 des sources qui ont parl\u00e9 au NYT.<\/p>\n<p class=\"paragraph\">Le propri\u00e9taire actuel de Twitter <strong>Elon Musk<\/strong> n&#8217;a pas r\u00e9pondu \u00e0 la demande d&#8217;interview du NYT.<\/p>\n<h3 class=\"subheadline\">Plafond des annonceurs<\/h3>\n<p class=\"paragraph\">Musk a averti \u00e0 plusieurs reprises que sa soci\u00e9t\u00e9 de m\u00e9dias sociaux \u00e9tait confront\u00e9e \u00e0 de graves probl\u00e8mes financiers.  La raison en est que Twitter est menac\u00e9 d&#8217;une \u00e9norme perte de revenus publicitaires.<\/p>\n<p class=\"paragraph\">Selon les statistiques, les annonceurs de Twitter ont consid\u00e9rablement diminu\u00e9 depuis avril, lorsque Musk a annonc\u00e9 pour la premi\u00e8re fois qu&#8217;il rach\u00e8terait l&#8217;entreprise.  En mars, la soci\u00e9t\u00e9 comptait 3 900 annonceurs, ce qui \u00e9tait significatif.  En ao\u00fbt, il ne restait plus que 2 300 annonceurs et en septembre, il y avait 2 900 annonceurs.<\/p>\n<p class=\"paragraph\">Selon le NYT, jusqu&#8217;\u00e0 90 % des revenus de Twitter proviennent des revenus publicitaires.<\/p>\n<p class=\"paragraph\">La raison de la perte d&#8217;annonceurs n&#8217;est pas claire.  Les annonceurs ont pris en compte, entre autres, la s\u00e9curit\u00e9 et la mod\u00e9ration des informations de l&#8217;entreprise.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iltalehti.fi\/digiuutiset\/a\/b6111025-4761-4de6-ade6-8dbbb1bfca6e\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-54<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les revenus publicitaires de Twitter pour la semaine en cours sont inf\u00e9rieurs de 80\u00a0% aux attentes internes. Les revenus publicitaires de Twitter sont tomb\u00e9s en de\u00e7\u00e0 des attentes cette semaine. AOP Les revenus publicitaires de Twitter se sont consid\u00e9rablement effondr\u00e9s cette semaine, rapporte Le New York Times. Des sources qui ont parl\u00e9 au journal r\u00e9v\u00e8lent [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":495248,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[12884,2798,8459,65,89511,249,32513,3335,2209,12258,13393,4491],"class_list":["post-495247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-24-heures","tag-chute","tag-linternet","tag-les","tag-medias-numeriques","tag-ont","tag-publicitaires","tag-revenus","tag-services-internet","tag-technologie-general","tag-traitement-des-donnees-et-technologies-de-linformation","tag-twitter"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/495247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=495247"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/495247\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/495248"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=495247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=495247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=495247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}