{"id":493596,"date":"2022-12-03T12:34:23","date_gmt":"2022-12-03T14:34:23","guid":{"rendered":"https:\/\/teknomers.com\/fr\/bossi-et-les-debuts-du-comite-nord-une-ligue-sans-identite-ne-peut-exister-renouvelons-la\/"},"modified":"2022-12-03T12:34:24","modified_gmt":"2022-12-03T14:34:24","slug":"bossi-et-les-debuts-du-comite-nord-une-ligue-sans-identite-ne-peut-exister-renouvelons-la","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/bossi-et-les-debuts-du-comite-nord-une-ligue-sans-identite-ne-peut-exister-renouvelons-la\/","title":{"rendered":"Bossi et les d\u00e9buts du Comit\u00e9 Nord : une Ligue sans identit\u00e9 ne peut exister, renouvelons-la"},"content":{"rendered":"\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>\u00c9couter la version audio de l&#8217;article<\/button><\/p>\n<p class=\"atext\">\u00ab La Ligue ne peut exister sans une identit\u00e9 claire et forte.  Nous avons cr\u00e9\u00e9 le &#8216;Comit\u00e9 Nord pour renouveler la Ligue&#8217;.  Cela a \u00e9t\u00e9 r\u00e9it\u00e9r\u00e9 par le chef historique de la Lega Umberto Bossi lors de la premi\u00e8re sortie publique, au ch\u00e2teau de Giovenzano (Pavie), une organisation qu&#8217;il a lui-m\u00eame fond\u00e9e apr\u00e8s le r\u00e9sultat d\u00e9cevant de la Lega dirig\u00e9e par Matteo Salvini aux \u00e9lections g\u00e9n\u00e9rales de 25 septembre dernier.  &#8220;On craignait que beaucoup de gens quittent la Ligue, on ne peut pas l&#8217;accepter sans rien faire&#8221;, a ajout\u00e9 le s\u00e9nateur.  Qui a soulign\u00e9 : \u00ab Nous sommes ici pour renouveler la Ligue, pas pour la d\u00e9truire car sinon nous ne ferions que rendre service au centralisme romain.  Mais beaucoup de gens, nos militants, me demandent depuis un moment \u00ab Bossi, fais quelque chose ! \u00bb.  Et nous ne pouvions pas rester immobiles.&#8221;<\/p>\n<p class=\"atext\">\u00abLe Comit\u00e9 &#8211; ont rappel\u00e9 les coordinateurs Angelo Ciocca et Paolo Grimoldi &#8211; est n\u00e9 au sein de la Ligue et a pour objectif la d\u00e9fense des int\u00e9r\u00eats du Nord trop longtemps oubli\u00e9s.  Un projet avec un message clair qui veut donner des r\u00e9ponses aux personnes qui travaillent et produisent dans la v\u00e9ritable locomotive du pays.  Une grande importance sera accord\u00e9e \u00e0 l&#8217;\u00e9coute des cat\u00e9gories individuelles, avec lesquelles nous discuterons de l&#8217;\u00e9criture d&#8217;un programme qui place les territoires au centre de l&#8217;action politique et d\u00e9battrons de la valeur de l&#8217;autonomie aujourd&#8217;hui \u00bb.<\/p>\n<p class=\"atext\">Le premier rendez-vous \u00e9tait initialement pr\u00e9vu le 27 novembre mais a \u00e9t\u00e9 report\u00e9 d&#8217;une semaine car Bossi avait subi une op\u00e9ration pour un ulc\u00e8re gastrique.  Alors qu&#8217;il \u00e9tait encore hospitalis\u00e9, il avait assur\u00e9 sa pr\u00e9sence : \u00ab Je voulais le Comit\u00e9 et je veux \u00eatre l\u00e0 \u00e0 la premi\u00e8re r\u00e9union.  Rendez-vous le 3 d\u00e9cembre \u00e0 Giovenzano, ce sera une belle rencontre\u00bb.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/bossi-e-l-esordio-comitato-nord-lega-senza-identita-non-puo-esistere-rinnoviamola-AE3knKMC\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9couter la version audio de l&#8217;article \u00ab La Ligue ne peut exister sans une identit\u00e9 claire et forte. Nous avons cr\u00e9\u00e9 le &#8216;Comit\u00e9 Nord pour renouveler la Ligue&#8217;. Cela a \u00e9t\u00e9 r\u00e9it\u00e9r\u00e9 par le chef historique de la Lega Umberto Bossi lors de la premi\u00e8re sortie publique, au ch\u00e2teau de Giovenzano (Pavie), une organisation qu&#8217;il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":493597,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[113666,1856,719,1386,7368,65,720,1005,181,129380,1181,196],"class_list":["post-493596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-bossi","tag-comite","tag-debuts","tag-exister","tag-identite","tag-les","tag-ligue","tag-nord","tag-peut","tag-renouvelonsla","tag-sans","tag-une"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/493596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=493596"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/493596\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/493597"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=493596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=493596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=493596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}