{"id":493106,"date":"2022-12-03T05:31:26","date_gmt":"2022-12-03T07:31:26","guid":{"rendered":"https:\/\/teknomers.com\/fr\/covid-de-la-france-au-japon-voici-les-pays-qui-craignent-la-nouvelle-vague-avant-noel\/"},"modified":"2022-12-03T05:31:28","modified_gmt":"2022-12-03T07:31:28","slug":"covid-de-la-france-au-japon-voici-les-pays-qui-craignent-la-nouvelle-vague-avant-noel","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/covid-de-la-france-au-japon-voici-les-pays-qui-craignent-la-nouvelle-vague-avant-noel\/","title":{"rendered":"Covid : de la France au Japon, voici les pays qui craignent la nouvelle vague avant No\u00ebl"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>\u00c9couter la version audio de l&#8217;article<\/button><\/p>\n<p class=\"atext\">Le spectre d&#8217;une neuvi\u00e8me vague du Covid-19 s&#8217;\u00e9tend sur la France.  Et pas seulement.  Selon les donn\u00e9es de Sant\u00e9 Publique France, vendredi dernier, il y avait 48 629 nouveaux cas enregistr\u00e9s \u00e0 travers les Alpes contre 33 177 cas le vendredi pr\u00e9c\u00e9dent, soit une augmentation de 46 %.  Plus de 4 500 hospitalisations au cours des sept derniers jours.  &#8220;Le fameux Rt, le taux de reproduction du Covid, est sup\u00e9rieur \u00e0 1 depuis plusieurs jours, cela veut dire que l&#8217;incidence du nombre de cas augmente : nous sommes au d\u00e9but d&#8217;une courbe plus ou moins exponentielle&#8221;, a-t-il d\u00e9clar\u00e9 \u00e0 l&#8217;agence France Presse le virologue Pascal Cr\u00e9pey, de l&#8217;Ecole des hautes \u00e9tudes de sant\u00e9 publique.  La premi\u00e8re ministre fran\u00e7aise, Elisabeth Borne, a lanc\u00e9 un &#8220;appel solennel&#8221; au respect des mesures de protection (&#8220;on porte le masque d\u00e8s qu&#8217;on est avec des personnes vuln\u00e9rables ou dans des zones surpeupl\u00e9es comme les transports en commun&#8221;) pour faire face \u00e0 une &#8220;nouvelle vague&#8221; des coronavirus.  Plusieurs experts estiment qu'&#8221;une neuvi\u00e8me vague se forme en France et plus g\u00e9n\u00e9ralement en Europe, en Asie du Sud-Est et en Am\u00e9rique du Nord&#8221;<\/p>\n<p><h2 id=\"U401998348842QED\">Japon, la huiti\u00e8me vague arrive : les infections augmentent <\/h2>\n<\/p>\n<p class=\"atext\">Alors qu&#8217;en Chine, il y a des signes d&#8217;assouplissement des mesures anti-Covid \u00e0 Guangzhou, la capitale du riche Guangdong, o\u00f9 ces derniers jours, il y a eu de nouveaux affrontements entre habitants et police au sujet de restrictions draconiennes pour lutter contre une vague d&#8217;infections, les infections de Covid se multiplient \u00e0 nouveau au Japon avec le pays officiellement &#8211; selon ce qui a \u00e9t\u00e9 d\u00e9clar\u00e9 par l&#8217;Association nationale des m\u00e9decins &#8211; est confront\u00e9 \u00e0 la huiti\u00e8me vague du virus.  La recrudescence du coronavirus survient une fois de plus apr\u00e8s que le gouvernement japonais a lanc\u00e9 un programme de subventions aux r\u00e9sidents pour stimuler le tourisme int\u00e9rieur et a lev\u00e9 la limite des arriv\u00e9es de touristes \u00e9trangers aux fronti\u00e8res.  Selon une \u00e9tude de l&#8217;Institut de technologie de Nagoya, on s&#8217;attend \u00e0 ce qu&#8217;\u00e0 la mi-janvier les infections au Japon puissent d\u00e9passer le pic atteint en ao\u00fbt, lorsque plus de 260 000 cas ont \u00e9t\u00e9 enregistr\u00e9s quotidiennement.<\/p>\n<p><h2 id=\"U401998348842hYE\">Fauci : on est toujours en pand\u00e9mie, ce n&#8217;est pas fini<\/h2>\n<\/p>\n<p class=\"atext\">Le fait que nous soyons toujours au milieu d&#8217;une pand\u00e9mie, avec 300 \u00e0 400 d\u00e9c\u00e8s par jour aux \u00c9tats-Unis, est confirm\u00e9 par Anthony Fauci, le meilleur immunologiste qui quitte la direction de l&#8217;Institut national am\u00e9ricain des maladies infectieuses ces jours-ci.  &#8220;Nous pouvons oublier que c&#8217;est fini, en ce moment alors que nous nous dirigeons vers l&#8217;hiver&#8221;, a-t-il ajout\u00e9, lan\u00e7ant un appel fort \u00e0 &#8220;faire tout son possible pour att\u00e9nuer la flamb\u00e9e des cas de covid&#8221;.  &#8220;C&#8217;est terriblement frustrant &#8211; a-t-il expliqu\u00e9 &#8211; de voir \u00e0 quel point peu de gens vaccinent avec le nouveau rappel, nous ne sommes qu&#8217;entre 11-15% de la population&#8221;.<\/p>\n<p><h2 id=\"U401998348842BlB\">Fiaso, nouveau bond des hospitalisations en Italie : +19,5% en 7 jours <\/h2>\n<\/p>\n<p class=\"atext\">En Italie, il y a un nouveau bond dans les hospitalisations Covid : la semaine derni\u00e8re, elles ont augment\u00e9 de 19,5 %.  L&#8217;enqu\u00eate du 29 novembre a \u00e9t\u00e9 r\u00e9alis\u00e9e aupr\u00e8s des h\u00f4pitaux sentinelles du r\u00e9seau Fiaso.  Il s&#8217;agit de la deuxi\u00e8me semaine de croissance \u00e0 deux chiffres : une hausse de 24 % avait d\u00e9j\u00e0 \u00e9t\u00e9 enregistr\u00e9e dans le rapport du 23 novembre.  En particulier, les patients dans les services Covid ordinaires ont augment\u00e9 de 20 %, tandis que les unit\u00e9s de soins intensifs ont enregistr\u00e9 une augmentation plus faible de 9 %.<\/p>\n<div class=\"acor acor--mkt\">\n<div class=\"\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--isq\" href=\"https:\/\/consigli24.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><\/figure>\n<p><\/a><\/div>\n<\/div>\n<p><h2 id=\"U401998348842dfB\">Des signes d&#8217;optimisme aussi<\/h2>\n<\/p>\n<p class=\"atext\">Mais en Italie, il y a aussi des \u00e9l\u00e9ments optimistes.  Massimo Ciccozzi, responsable de l&#8217;unit\u00e9 de recherche en \u00e9pid\u00e9miologie mol\u00e9culaire du Campus Bio-medico de l&#8217;Universit\u00e9 de Rome, affirme que Covid &#8220;s&#8217;adapte de plus en plus \u00e0 nous&#8221;, la sous-variante Cerberus est moins contagieuse qu&#8217;Omicron 5, m\u00eame s&#8217;il faut \u00eatre toujours pr\u00eat en cas de nouvelles variantes plus redoutables d&#8217;Omicron.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/covid-francia-giappone-ecco-paesi-che-temono-nuova-ondata-prima-natale-AE6y1OLC\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9couter la version audio de l&#8217;article Le spectre d&#8217;une neuvi\u00e8me vague du Covid-19 s&#8217;\u00e9tend sur la France. Et pas seulement. Selon les donn\u00e9es de Sant\u00e9 Publique France, vendredi dernier, il y avait 48 629 nouveaux cas enregistr\u00e9s \u00e0 travers les Alpes contre 33 177 cas le vendredi pr\u00e9c\u00e9dent, soit une augmentation de 46 %. Plus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":493107,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[292,794,6786,2720,12067,65,1754,197,1480,364,2861,363],"class_list":["post-493106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-avant","tag-covid","tag-craignent","tag-france","tag-japon","tag-les","tag-noel","tag-nouvelle","tag-pays","tag-qui","tag-vague","tag-voici"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/493106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=493106"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/493106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/493107"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=493106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=493106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=493106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}