{"id":489887,"date":"2022-12-01T08:16:25","date_gmt":"2022-12-01T10:16:25","guid":{"rendered":"https:\/\/teknomers.com\/fr\/healthcare-summit-2022-schillaci-plus-de-ressources-pour-la-sante-renforcer-maintenant-le-maillage-territorial\/"},"modified":"2022-12-01T08:16:27","modified_gmt":"2022-12-01T10:16:27","slug":"healthcare-summit-2022-schillaci-plus-de-ressources-pour-la-sante-renforcer-maintenant-le-maillage-territorial","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/healthcare-summit-2022-schillaci-plus-de-ressources-pour-la-sante-renforcer-maintenant-le-maillage-territorial\/","title":{"rendered":"Healthcare Summit 2022, Schillaci : \u00ab Plus de ressources pour la sant\u00e9.  Renforcer maintenant le maillage territorial \u00bb"},"content":{"rendered":"\n<div>\n<p class=\"atext\">Pour le ministre, qui a soulign\u00e9 comment les &#8220;co\u00fbts ont augment\u00e9&#8221;, il faut &#8220;trouver des solutions pour faire fonctionner les structures locales et faire en sorte que les citoyens les voient comme des structures s\u00fbres&#8221;.  Nous travaillons sur ce dossier tout de suite car il ne suffit pas de construire, mais il faut que les maisons associatives entrent dans une m\u00e9decine territoriale et que ces structures soient harmonis\u00e9es : je pense aux r\u00e9seaux d&#8217;officines \u00bb.<\/p>\n<p><h2 id=\"U402002377602Bg\">Sp\u00e9cial supervis\u00e9 Covid<\/h2>\n<\/p>\n<p class=\"atext\">Sur le front de la pand\u00e9mie, le ministre a expliqu\u00e9 : &#8220;Regardons de pr\u00e8s le Covid : ce n&#8217;est plus comme il y a trois ans, mais on invite les personnes les plus fragiles \u00e0 se faire vacciner&#8221;.<\/p>\n<p class=\"atext\">Son discours au Sommet de la sant\u00e9 organis\u00e9 par Il Sole 24 Ore lui a donn\u00e9 l&#8217;occasion de revenir \u00e9galement sur les probl\u00e8mes du personnel de sant\u00e9.<\/p>\n<p class=\"atext\">\u00ab Le personnel soignant m\u00e9rite le respect.  Mon engagement est de r\u00e9\u00e9valuer le traitement \u00e9conomique de ceux qui travaillent dans le service national de sant\u00e9.  C&#8217;est la premi\u00e8re disposition que nous esp\u00e9rons pouvoir avancer \u00e0 2023. Il y a certainement un engagement avec les R\u00e9gions \u00e0 allouer plus de financements d\u00e8s que possible pour r\u00e9mun\u00e9rer tous les personnels de sant\u00e9 pour que le syst\u00e8me national de sant\u00e9 puisse redevenir attractif \u00bb.<\/p>\n<p><h2 id=\"U402002377602oSE\">Surco\u00fbts et r\u00f4le des r\u00e9gions<\/h2>\n<\/p>\n<p class=\"atext\">Selon le ministre de la Sant\u00e9 Orazio Schillaci, un accord avec les R\u00e9gions est n\u00e9cessaire sur la question des surco\u00fbts pour le syst\u00e8me de sant\u00e9.  &#8220;Il y a le Minist\u00e8re de la Sant\u00e9 &#8211; a-t-il pr\u00e9cis\u00e9 &#8211; mais il y a aussi les R\u00e9gions et il doit y avoir une collaboration vertueuse entre le Minist\u00e8re, le Gouvernement et les R\u00e9gions&#8221;.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/healthcare-summit-2022-schillaci-piu-risorse-sanita-ora-rafforzare-rete-territoriale-AE62vfLC\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour le ministre, qui a soulign\u00e9 comment les &#8220;co\u00fbts ont augment\u00e9&#8221;, il faut &#8220;trouver des solutions pour faire fonctionner les structures locales et faire en sorte que les citoyens les voient comme des structures s\u00fbres&#8221;. Nous travaillons sur ce dossier tout de suite car il ne suffit pas de construire, mais il faut que les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":489888,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[5018,92309,617,185,16250,6581,34,34953,28479,1070],"class_list":["post-489887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-healthcare","tag-maillage","tag-maintenant","tag-pour","tag-renforcer","tag-ressources","tag-sante","tag-schillaci","tag-summit","tag-territorial"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/489887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=489887"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/489887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/489888"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=489887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=489887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=489887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}