{"id":488801,"date":"2022-11-30T16:11:29","date_gmt":"2022-11-30T18:11:29","guid":{"rendered":"https:\/\/teknomers.com\/fr\/expulses-ukrainiens-dans-les-universites-du-schleswig-holstein\/"},"modified":"2022-11-30T16:11:31","modified_gmt":"2022-11-30T18:11:31","slug":"expulses-ukrainiens-dans-les-universites-du-schleswig-holstein","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/expulses-ukrainiens-dans-les-universites-du-schleswig-holstein\/","title":{"rendered":"Expuls\u00e9s ukrainiens dans les universit\u00e9s du Schleswig-Holstein"},"content":{"rendered":"\n<p>&#8220;Je n&#8217;ai jamais pens\u00e9 de ma vie que je vivais dans un pays en guerre.  Et ce pays est au milieu de l&#8217;Europe du 21e si\u00e8cle \u00bb, d\u00e9clare Serhij Lukanjuk, (Universit\u00e9 Yuriy Fedkovych, Chernivtsi).  Le chef du Bureau international rend compte de l&#8217;actualit\u00e9 de l&#8217;universit\u00e9 partenaire du TH L\u00fcbeck lors de la r\u00e9union d&#8217;\u00e9change num\u00e9rique sur la situation des personnes d\u00e9plac\u00e9es ukrainiennes dans les universit\u00e9s du Schleswig-Holstein le 29 novembre 2022.  Muriel Helbig, pr\u00e9sidente du TH L\u00fcbeck et vice-pr\u00e9sidente du Service allemand d&#8217;\u00e9changes universitaires (DAAD), a invit\u00e9 divers acteurs en coop\u00e9ration avec le minist\u00e8re de l&#8217;\u00c9ducation du Schleswig-Holstein.  Le but de l&#8217;\u00e9change est de coordonner les acteurs pour une aide efficace aux personnes d\u00e9plac\u00e9es par la guerre d&#8217;agression russe.<\/p>\n<h3><strong>Contrairement \u00e0 2015<\/strong><\/h3>\n<p>D\u00e8s le d\u00e9but de la r\u00e9union, Helbig a expliqu\u00e9 les diff\u00e9rences entre le mouvement des r\u00e9fugi\u00e9s en 2015 et la situation actuelle : alors que le DAAD avait pr\u00e9vu environ 100 000 \u00e9tudiants et scientifiques ukrainiens au printemps, beaucoup moins d&#8217;Ukrainiens sont en fait arriv\u00e9s dans les universit\u00e9s en novembre 2022.  &#8220;Les Ukrainiens sont beaucoup plus connect\u00e9s \u00e0 leurs institutions d&#8217;origine gr\u00e2ce aux offres num\u00e9riques que les r\u00e9fugi\u00e9s syriens ne l&#8217;\u00e9taient en 2015&#8221;, explique Helbig, expliquant les raisons.  De plus, la dur\u00e9e de s\u00e9jour en Allemagne est nettement plus courte car ils retournent plus souvent en Ukraine.<\/p>\n<p>Ceci est \u00e9galement confirm\u00e9 par Dirk G\u00e4rtner, directeur de l&#8217;Office d&#8217;\u00c9tat pour l&#8217;immigration et les r\u00e9fugi\u00e9s du Schleswig-Holstein.  L&#8217;immigration est actuellement g\u00e9rable.  Seuls environ 300 d\u00e9plac\u00e9s ukrainiens sont actuellement h\u00e9berg\u00e9s dans les \u00e9tablissements publics.  &#8220;En ao\u00fbt, il y avait beaucoup plus de d\u00e9plac\u00e9s ukrainiens, mais ils ne sont pas rest\u00e9s longtemps dans nos installations&#8221;, explique G\u00e4rtner.  Cependant, il existe de tr\u00e8s grandes diff\u00e9rences r\u00e9gionales dans la situation d&#8217;accueil.<\/p>\n<h3><strong>Plus de d\u00e9plac\u00e9s en hiver ?<\/strong><\/h3>\n<p>Cependant, cette situation pourrait bient\u00f4t changer : Lukanjuk rapporte des appels du gouvernement ukrainien pour que ceux qui peuvent le mettre en place quittent le pays pour l&#8217;hiver.  Le contexte est la destruction continue des infrastructures ukrainiennes par l&#8217;arm\u00e9e russe.  L&#8217;infrastructure num\u00e9rique d&#8217;enseignement et d&#8217;apprentissage est \u00e9galement affect\u00e9e.  &#8220;Sans \u00e9lectricit\u00e9, il n&#8217;y a pas de num\u00e9risation&#8221;, r\u00e9sume Lukanjuk.  Il aimerait que les universit\u00e9s allemandes acceptent des \u00e9tudiants ou des scientifiques ukrainiens pendant deux semaines \u00e0 six mois.<\/p>\n<p>Viviane Salzmann-El Bechri (DRK, Bad Segeberg) fait \u00e9galement \u00e9tat d&#8217;un changement ces derni\u00e8res semaines : &#8220;Au cours des premiers mois, les \u00e9tudiants utilisent souvent les offres num\u00e9riques de leur universit\u00e9 d&#8217;origine.  Ces derni\u00e8res semaines notamment, de nombreux \u00e9tudiants ukrainiens ont perdu le contact avec leur universit\u00e9 d&#8217;origine car personne n&#8217;est joignable sur place ou les infrastructures ont \u00e9t\u00e9 d\u00e9truites.<\/p>\n<h3><strong>soulager la souffrance<\/strong><\/h3>\n<p>&#8220;Les universit\u00e9s tentent d&#8217;all\u00e9ger les grandes souffrances li\u00e9es \u00e0 la guerre&#8221;, d\u00e9clare Karin Prien, ministre de l&#8217;\u00c9ducation du Schleswig-Holstein.  Les \u00e9tudiants ukrainiens Tetiana Halus, Gusev Oleksiy et Sofiia Samorodova de l&#8217;Universit\u00e9 des sciences appliqu\u00e9es de Kiel le confirment et signalent un bon d\u00e9part en Allemagne.  Vous avez trouv\u00e9 votre chemin vers l&#8217;Allemagne principalement gr\u00e2ce \u00e0 des relations personnelles.  L&#8217;un des principaux points d&#8217;achoppement reste la barri\u00e8re de la langue.  Leur \u00e9limination est \u00e9galement une priorit\u00e9 pour le minist\u00e8re de l&#8217;\u00c9ducation : une augmentation progressive des cr\u00e9dits budg\u00e9taires est ici pr\u00e9vue.<\/p>\n<p>Mais la s\u00e9rie de pourparlers montre \u00e9galement des points de d\u00e9part pour d&#8217;autres \u00e9tapes\u00a0: les p\u00e9nuries de logements, la garde des enfants et l&#8217;acc\u00e8s \u00e0 Internet sont \u00e9galement des sujets pertinents pour les personnes d\u00e9plac\u00e9es.  De plus, les expuls\u00e9s ont besoin de subventions et de conseils pour trouver leur chemin dans le syst\u00e8me allemand.<\/p>\n<p>&#8220;Le soutien est bon et en m\u00eame temps nous avons besoin de plus d&#8217;aide : en particulier, nous avons besoin du soutien diplomatique et des dons de l&#8217;Allemagne&#8221;, d\u00e9clare l&#8217;\u00e9tudiant Gusev Oleksiy.<\/p>\n<p>Si vous souhaitez aider, merci de faire un don \u00e0 :<\/p>\n<p><a rel=\"nofollow noopener\" href=\"https:\/\/www.dzi.de\/dzi-spenden-info-nothilfe-ukraine-2\/\" target=\"_blank\" class=\"link-external\">compte de don<\/a><\/p>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.th-luebeck.de\/hochschule\/aktuelles\/neuigkeiten\/beitrag\/2022-11-30-ukrainische-vertriebene-an-schleswig-holsteiner-hochschulen\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-37<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Je n&#8217;ai jamais pens\u00e9 de ma vie que je vivais dans un pays en guerre. Et ce pays est au milieu de l&#8217;Europe du 21e si\u00e8cle \u00bb, d\u00e9clare Serhij Lukanjuk, (Universit\u00e9 Yuriy Fedkovych, Chernivtsi). Le chef du Bureau international rend compte de l&#8217;actualit\u00e9 de l&#8217;universit\u00e9 partenaire du TH L\u00fcbeck lors de la r\u00e9union d&#8217;\u00e9change num\u00e9rique [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":488802,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[429,18474,65,29963,354,41700],"class_list":["post-488801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-dans","tag-expulses","tag-les","tag-schleswigholstein","tag-ukrainiens","tag-universites"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/488801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=488801"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/488801\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/488802"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=488801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=488801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=488801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}