{"id":480726,"date":"2022-11-25T10:36:27","date_gmt":"2022-11-25T12:36:27","guid":{"rendered":"https:\/\/teknomers.com\/fr\/decaro-anci-les-travaux-des-municipalites-sont-tous-realisables-en-simplifiant-le-processus\/"},"modified":"2022-11-25T10:36:28","modified_gmt":"2022-11-25T12:36:28","slug":"decaro-anci-les-travaux-des-municipalites-sont-tous-realisables-en-simplifiant-le-processus","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/decaro-anci-les-travaux-des-municipalites-sont-tous-realisables-en-simplifiant-le-processus\/","title":{"rendered":"Decaro (Anci): \u00abLes travaux des municipalit\u00e9s sont tous r\u00e9alisables en simplifiant le processus\u00bb"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>\u00c9couter la version audio de l&#8217;article<\/button><\/p>\n<p class=\"atext\">\u00ab Les travaux du Pnrr pr\u00e9vus dans les Communes peuvent tous \u00eatre r\u00e9alis\u00e9s dans les d\u00e9lais si les proc\u00e9dures sont simplifi\u00e9es.  Si vous ne simplifiez pas, ils deviennent tous irr\u00e9alisables\u00bb.  A peine descendu de la sc\u00e8ne o\u00f9 s&#8217;est cl\u00f4tur\u00e9e la 39e assembl\u00e9e nationale de l&#8217;Anci, le pr\u00e9sident Antonio Decaro, maire de Bari, semble \u00e0 la fois satisfait et inquiet.  Satisfait d&#8217;avoir v\u00e9cu l&#8217;une des \u00e9ditions les plus fr\u00e9quent\u00e9es (plus de 5 000 participants, plus de 2 000 administrateurs locaux et 20 membres du gouvernement) de l&#8217;histoire des assembl\u00e9es municipales.  Inquiets que le v\u00e9ritable enjeu du Pnrr pour les Communes commence maintenant, avec la grande majorit\u00e9 des appels d&#8217;offres \u00e0 cl\u00f4turer en 2023.<\/p>\n<p class=\"atext\"><b>Le gouvernement pr\u00e9tend qu&#8217;il faut r\u00e9cup\u00e9rer des ressources en coupant les projets qui ne peuvent \u00eatre achev\u00e9s \u00e0 temps \u00e0 partir du Pnrr.  Combien sont-ils ceux des Communes, parmi les 40 milliards dont les collectivit\u00e9s locales sont les organes d&#8217;ex\u00e9cution ?<\/b><\/p>\n<p class=\"atext\">Aucun.  A condition de tirer les le\u00e7ons de l&#8217;exp\u00e9rience de ces derniers mois et de simplifier les r\u00e8gles et surtout les proc\u00e9dures.  Si vous le faites, nous pouvons fermer \u00e0 temps.  Si vous ne le faites pas, tous les travaux sont vou\u00e9s \u00e0 \u00eatre retard\u00e9s.  Tout \u00e0 l&#8217;heure, la nouvelle est arriv\u00e9e qu&#8217;\u00e0 Bari, le Tar a bloqu\u00e9 les chemins de fer de l&#8217;\u00c9tat sur une variante de 500 millions, cofinanc\u00e9e par le Pnrr, en raison d&#8217;un appel de certains comit\u00e9s.  Appel l\u00e9gitime : mais cela ne passe pas.<\/p>\n<p class=\"atext\"><b>Vous lancez la balle au centre, mais de nombreux observateurs craignent que les autorit\u00e9s locales ne puissent y arriver faute de comp\u00e9tences et de personnel, comme vous l&#8217;avez souvent d\u00e9plor\u00e9 vous aussi.<\/b><\/p>\n<div class=\"acor acor--mkt\">\n<div class=\"\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--isq\" href=\"https:\/\/consigli24.ilsole24ore.com\/2022\/11\/18\/offerte-black-friday-2022\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><\/figure>\n<p><\/a><\/div>\n<\/div>\n<p class=\"atext\">Mais nous nous \u00e9tions engag\u00e9s \u00e0 pr\u00e9senter les projets et \u00e0 nous faire affecter les moyens d&#8217;ici juin, et ce m\u00eame si les effectifs sont au plus bas et que les nouveaux ne font que commencer \u00e0 arriver.  En effet, les projets que nous avons mis sur la table d\u00e9passent les ressources disponibles.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/decaro-anci-le-opere-comuni-sono-tutte-realizzabili-semplificando-l-iter-AEMNprJC\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9couter la version audio de l&#8217;article \u00ab Les travaux du Pnrr pr\u00e9vus dans les Communes peuvent tous \u00eatre r\u00e9alis\u00e9s dans les d\u00e9lais si les proc\u00e9dures sont simplifi\u00e9es. Si vous ne simplifiez pas, ils deviennent tous irr\u00e9alisables\u00bb. A peine descendu de la sc\u00e8ne o\u00f9 s&#8217;est cl\u00f4tur\u00e9e la 39e assembl\u00e9e nationale de l&#8217;Anci, le pr\u00e9sident Antonio Decaro, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":480727,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[127319,127318,133,65,6423,9630,55038,127320,317,378,4661],"class_list":["post-480726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-anci","tag-decaro","tag-des","tag-les","tag-municipalites","tag-processus","tag-realisables","tag-simplifiant","tag-sont","tag-tous","tag-travaux"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/480726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=480726"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/480726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/480727"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=480726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=480726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=480726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}