{"id":45976,"date":"2022-03-21T12:32:55","date_gmt":"2022-03-21T14:32:55","guid":{"rendered":"https:\/\/teknomers.com\/fr\/je-suis-jaloux-de-ma-petite-soeur\/"},"modified":"2022-03-21T12:32:59","modified_gmt":"2022-03-21T14:32:59","slug":"je-suis-jaloux-de-ma-petite-soeur","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/je-suis-jaloux-de-ma-petite-soeur\/","title":{"rendered":"&#8220;Je suis jaloux de ma petite soeur&#8221;"},"content":{"rendered":"\n<div data-element=\"articleBodyBlocks\">\n<p class=\"ArticleBodyBlocks__html ArticleBodyBlocks__html--vrouw\">Alors que tous les Pays-Bas \u00e9clataient de coupes de champagne et d&#8217;oliebollen, le feu vert avait sonn\u00e9 pour ma s\u0153ur le deuxi\u00e8me jour de la nouvelle ann\u00e9e.<\/p>\n<p class=\"ArticleBodyBlocks__html ArticleBodyBlocks__html--vrouw\">Pendant le d\u00eener de No\u00ebl, toute la famille a d\u00fb entendre qu&#8217;elle \u00e9tait plus que fatigu\u00e9e d&#8217;\u00eatre en surpoids et que la nouvelle ann\u00e9e serait \u00abl&#8217;ann\u00e9e du changement\u00bb.  Voir c&#8217;est croire, pensai-je, car ce n&#8217;\u00e9tait pas la premi\u00e8re fois qu&#8217;elle partageait ce plan avec ses proches.<\/p>\n<h3 class=\"ArticleBodyBlocks__subheader\">Des sacs entiers de chips<\/h3>\n<p class=\"ArticleBodyBlocks__html ArticleBodyBlocks__html--vrouw\">Ma relation avec ma s\u0153ur est bonne et je sais qu&#8217;elle aime la bonne nourriture.  Lorsque nous buvons un verre de vin ensemble, elle commande toujours une portion de collations et avoue r\u00e9guli\u00e8rement qu&#8217;elle mange des sacs entiers de chips lorsqu&#8217;elle est seule devant la t\u00e9l\u00e9.  Ce n&#8217;est pas grave, mais si vous conservez ce sch\u00e9ma pendant plusieurs ann\u00e9es, vous le verrez se refl\u00e9ter dans votre corps.<\/p>\n<p class=\"ArticleBodyBlocks__html ArticleBodyBlocks__html--vrouw\">L&#8217;horloge sonna midi et ma s\u0153ur prit une gorg\u00e9e.  Moins d&#8217;une demi-heure plus tard, elle avait termin\u00e9 trois beignets, et au moment o\u00f9 il \u00e9tait 2 heures du matin, le r\u00e9frig\u00e9rateur a \u00e9t\u00e9 ouvert et elle a fini quelques bouch\u00e9es de plus du dessert restant.<\/p>\n<h3 class=\"ArticleBodyBlocks__subheader\">\u00c0 la salle de sport<\/h3>\n<p class=\"ArticleBodyBlocks__html ArticleBodyBlocks__html--vrouw\">Lorsque mon mari et moi avons d\u00e9cid\u00e9 de rentrer \u00e0 la maison une heure plus tard, je lui ai sarcastiquement souhait\u00e9 bonne chance avec sa r\u00e9solution du Nouvel An.  En r\u00e9ponse, j&#8217;ai entendu un murmure \u00e0 moiti\u00e9 ivre qu&#8217;elle commencerait vraiment lundi.  &#8220;Elle tergiverse d\u00e9j\u00e0,&#8221; pensai-je.<\/p>\n<p class=\"ArticleBodyBlocks__html ArticleBodyBlocks__html--vrouw\">Mais rien ne pouvait \u00eatre plus \u00e9loign\u00e9 de la v\u00e9rit\u00e9.  Le 2 janvier, ma s\u0153ur \u00e9tait au gymnase.  Comme le 3 janvier, le 4 janvier et le reste de la semaine.  Les kilos se sont envol\u00e9s, et quand j&#8217;ai rencontr\u00e9 mes amis, je n&#8217;ai entendu que des histoires sur la beaut\u00e9 de ma s\u0153ur.  Elle travaille maintenant depuis pr\u00e8s de trois mois et est bien partie pour <span class=\"italic\">fille en forme <\/span> devenir.<\/p>\n<h3 class=\"ArticleBodyBlocks__subheader\">Cr\u00e8me \u00e0 travers sa nourriture<\/h3>\n<p class=\"ArticleBodyBlocks__html ArticleBodyBlocks__html--vrouw\">M\u00eame si je veux vraiment qu&#8217;elle perde quelques kilos, j&#8217;en ai marre de tous les compliments.  J&#8217;ai toujours \u00e9t\u00e9 &#8216;la plus mince&#8217; de nous deux, mais maintenant elle m&#8217;a rattrap\u00e9.  Lorsque nous nous promenons ensemble dans la ville, elle re\u00e7oit un clin d&#8217;\u0153il et les ouvriers du b\u00e2timent la sifflent \u00e9galement.<\/p>\n<p class=\"ArticleBodyBlocks__html ArticleBodyBlocks__html--vrouw\">Quand elle vient vers moi, je dois m&#8217;emp\u00eacher de mettre une cuiller\u00e9e de cr\u00e8me suppl\u00e9mentaire dans sa nourriture et je remarque que j&#8217;insiste vraiment pour qu&#8217;elle ait un biscuit avec le caf\u00e9.  Je ne le lui avouerai jamais, mais je suis tr\u00e8s jalouse et je n&#8217;esp\u00e8re rien de plus qu&#8217;elle jette l&#8217;\u00e9ponge bient\u00f4t&#8230;<\/p>\n<h3 class=\"ArticleBodyBlocks__subheader\">Vous sur VROUW.nl<\/h3>\n<p class=\"ArticleBodyBlocks__html ArticleBodyBlocks__html--vrouw\">Voulez-vous aussi avouer quelque chose, de mani\u00e8re anonyme\u00a0?<\/p>\n<p class=\"ArticleBodyBlocks__html ArticleBodyBlocks__html--vrouw\"><a rel=\"nofollow noopener\" href=\"https:\/\/vrouw.nl\/artikel\/lezerscolumn\/32402\/jij-op-vrouwnl-lezerscolumn\" target=\"_blank\">Alors vous pouvez le faire ici !<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.telegraaf.nl\/vrouw\/793626201\/ik-ben-stikjaloers-op-mijn-slanke-zus\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-2<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que tous les Pays-Bas \u00e9clataient de coupes de champagne et d&#8217;oliebollen, le feu vert avait sonn\u00e9 pour ma s\u0153ur le deuxi\u00e8me jour de la nouvelle ann\u00e9e. Pendant le d\u00eener de No\u00ebl, toute la famille a d\u00fb entendre qu&#8217;elle \u00e9tait plus que fatigu\u00e9e d&#8217;\u00eatre en surpoids et que la nouvelle ann\u00e9e serait \u00abl&#8217;ann\u00e9e du changement\u00bb. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45977,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[19107,2215,5501,3181],"class_list":["post-45976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-jaloux","tag-petite","tag-soeur","tag-suis"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=45976"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45976\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/45977"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=45976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=45976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=45976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}