{"id":45967,"date":"2022-03-21T12:29:52","date_gmt":"2022-03-21T14:29:52","guid":{"rendered":"https:\/\/teknomers.com\/fr\/la-politique-zero-covid-a-hong-kong-ne-fonctionne-plus-a-cause-domikron-le-gouvernement-se-detend-sous-la-pression-des-expatries-qui-partent\/"},"modified":"2022-03-21T12:29:57","modified_gmt":"2022-03-21T14:29:57","slug":"la-politique-zero-covid-a-hong-kong-ne-fonctionne-plus-a-cause-domikron-le-gouvernement-se-detend-sous-la-pression-des-expatries-qui-partent","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/la-politique-zero-covid-a-hong-kong-ne-fonctionne-plus-a-cause-domikron-le-gouvernement-se-detend-sous-la-pression-des-expatries-qui-partent\/","title":{"rendered":"La politique &#8220;z\u00e9ro covid&#8221; \u00e0 Hong Kong ne fonctionne plus \u00e0 cause d&#8217;omikron\u00a0: le gouvernement se d\u00e9tend sous la pression des expatri\u00e9s qui partent"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<p class=\"artstyle__paragraph \" data-element-id=\"2561-5c81-db92-26f9-0272-ad01-ee16-e71b\">\n<p>      La dirigeante de Hong Kong, Carrie Lam, qui a \u00e9t\u00e9 la cible de tirs nourris pour sa r\u00e9ponse d\u00e9faillante au covid, a annonc\u00e9 l&#8217;assouplissement lundi.  Elle a \u00e9galement annonc\u00e9 qu&#8217;elle annulerait le test de masse pr\u00e9vu pour l&#8217;ensemble de la population.  Selon Lam, l&#8217;ajustement fait suite \u00e0 une diminution du nombre d&#8217;infections \u00e0 Hong Kong, mais selon d&#8217;autres membres du gouvernement, les critiques du monde des affaires ont surtout jou\u00e9 un r\u00f4le.  Les r\u00e8gles strictes de Covid menacent le statut de Hong Kong en tant que centre financier international.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"951d-4640-21dc-dbe2-7f08-57d3-18af-dd09\">\n<p>      Hong Kong a men\u00e9 avec succ\u00e8s une politique z\u00e9ro covid pendant pr\u00e8s de deux ans, mais au d\u00e9but de cette ann\u00e9e, il s&#8217;est av\u00e9r\u00e9 qu&#8217;elle n&#8217;\u00e9tait pas \u00e0 la hauteur d&#8217;une \u00e9pid\u00e9mie de la variante omikron.  Apr\u00e8s \u00e0 peine 200 morts de covid au cours des deux premi\u00e8res ann\u00e9es de la pand\u00e9mie, Hong Kong a vu le bilan s&#8217;\u00e9lever \u00e0 plus de 5 000 en un mois.  Les morgues de Hong Kong sont surpeupl\u00e9es et dans les h\u00f4pitaux, des sacs mortuaires sont laiss\u00e9s entre les lits pendant des heures.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"5864-d7f2-125e-6cf4-8a89-1bd1-97a1-e28c\">\n<p>      Selon les experts, la d\u00e9b\u00e2cle actuelle \u00e0 Hong Kong est principalement due \u00e0 la faible couverture vaccinale des personnes \u00e2g\u00e9es : sur l&#8217;ensemble des personnes de plus de 80 ans, seuls 55 % ont \u00e9t\u00e9 doublement vaccin\u00e9s, dont les trois quarts avec le vaccin chinois Sinovac, moins efficace. contre l&#8217;omikron que les vaccins \u00e0 ARNm.  De nombreux Hongkongais \u00e2g\u00e9s ne se sont pas fait vacciner par peur des effets secondaires.  De tous les d\u00e9c\u00e8s r\u00e9cents de covid \u00e0 Hong Kong, 90% n&#8217;\u00e9taient pas compl\u00e8tement vaccin\u00e9s, selon les donn\u00e9es officielles.\n    <\/p>\n<h3 class=\"artstyle__title \" data-element-id=\"26e6-fd77-6756-9431-3cfa-8e61-a168-a059\">\n<p>      crise sanitaire<br \/>\n    <\/h3>\n<p class=\"artstyle__paragraph \" data-element-id=\"d881-2299-527b-0a63-e2cd-d5a8-9c7f-c00e\">\n<p>      La crise sanitaire a \u00e9t\u00e9 exacerb\u00e9e par la politique de Hong Kong exigeant initialement que tous les patients (y compris ceux pr\u00e9sentant des sympt\u00f4mes l\u00e9gers) soient hospitalis\u00e9s.  En cons\u00e9quence, les h\u00f4pitaux ont \u00e9t\u00e9 d\u00e9bord\u00e9s, obligeant les patients pr\u00e9sentant des sympt\u00f4mes graves \u00e0 attendre plus longtemps pour des soins m\u00e9dicaux.  D\u00e9but mars, le gouvernement, avec l&#8217;aide de P\u00e9kin, a fait construire huit centres de quarantaine temporaires, avec 10 000 lits pour les patients pr\u00e9sentant des sympt\u00f4mes b\u00e9nins.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"00c5-7e3d-d07b-b67e-5e87-db42-d6b4-d6ed\">\n<p>      Le gouvernement de Hong Kong a \u00e9galement ferm\u00e9 les \u00e9coles, restaurants et autres lieux de rencontre, et annonc\u00e9 un test de masse de l&#8217;ensemble de la population (7,5 millions d&#8217;habitants).  Les mesures s&#8217;inscrivent dans une politique z\u00e9ro covid, destin\u00e9e \u00e0 contenir le virus corona, bien que Hong Kong n&#8217;ait pas atteint l&#8217;arme ultime : le confinement.  Selon les critiques, la politique de Hong Kong a peu de fondement scientifique et est principalement motiv\u00e9e par des consid\u00e9rations politiques : destin\u00e9e \u00e0 plaire \u00e0 P\u00e9kin, o\u00f9 le Parti communiste chinois a fait de la politique z\u00e9ro-covid sa banni\u00e8re.\n    <\/p>\n<h3 class=\"artstyle__title \" data-element-id=\"4dcd-6e31-7c98-0649-cbd7-ecd2-41cf-a08c\">\n<p>      Expatri\u00e9s<br \/>\n    <\/h3>\n<p class=\"artstyle__paragraph \" data-element-id=\"fd2e-a61e-559f-d6e3-162b-b105-b5f9-bdce\">\n<p>      Les mesures extr\u00eamement strictes, mais non cibl\u00e9es, ont \u00e9t\u00e9 pour de nombreux habitants de Hong Kong &#8211; et en particulier pour de nombreux expatri\u00e9s &#8211; une raison de dire au revoir \u00e0 la ville.  Plus de 71 000 r\u00e9sidents sont partis en f\u00e9vrier, selon les responsables de l&#8217;immigration, et plus de 43 000 dans la premi\u00e8re quinzaine de mars.  La d\u00e9l\u00e9gation de l&#8217;Union europ\u00e9enne a d\u00e9clar\u00e9 le mois dernier que 10 % des expatri\u00e9s europ\u00e9ens avaient quitt\u00e9 Hong Kong.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"59c8-9dd8-39db-e44e-ffe1-c153-849f-8bd9\">\n<p>      Selon l&#8217;agence de presse Bloomberg, de nombreuses institutions financi\u00e8res de Hong Kong transf\u00e8rent progressivement leurs employ\u00e9s \u00e0 Singapour, bien que la plupart du temps tacitement par crainte d&#8217;offenser P\u00e9kin.  Un mouvement ouvert de Hong Kong serait consid\u00e9r\u00e9 comme &#8220;un mouvement agressif vers la Chine&#8221;, a d\u00e9clar\u00e9 le PDG de la banque d&#8217;investissement Soci\u00e9t\u00e9 G\u00e9n\u00e9rale, selon Bloomberg.  &#8220;Cela pourrait ne pas nous aider \u00e0 nous d\u00e9velopper en Chine comme nous le souhaitons.&#8221;\n    <\/p>\n<figure class=\"artstyle__figure  artstyle__figure-landscape\" data-element-id=\"afb81392-5392-4a76-8d1e-06bc659356eb\">\n<p><figcaption class=\"artstyle__figcaption\"><cite class=\"artstyle__figcaption__caption\">Les voyageurs arrivent \u00e0 l&#8217;a\u00e9roport de Hong Kong et doivent imm\u00e9diatement prendre une navette vers un h\u00f4tel de quarantaine.<\/cite><span class=\"artstyle__figcaption__credit\">Image ANP\/EPA<\/span><\/figcaption><\/p>\n<\/figure>\n<p class=\"artstyle__paragraph \" data-element-id=\"f970-5663-5b39-2b43-c08a-0c6b-26e1-2080\">\n<p>      Les membres du cabinet de Hong Kong ont \u00e9galement d\u00e9clar\u00e9 avoir protest\u00e9 aupr\u00e8s de Carrie Lam.  &#8220;Les mesures strictes de quarantaine pour les personnes venant \u00e0 Hong Kong et les craintes d&#8217;un verrouillage majeur pendant le test de masse pr\u00e9vu ont entra\u00een\u00e9 la relocalisation de nombreux expatri\u00e9s du secteur financier \u00e0 Singapour&#8221;, a d\u00e9clar\u00e9 le membre du cabinet Ronny Tong Ka-wah au journal. <i>Poste du matin de la Chine du Sud<\/i>\u2020\n    <\/p>\n<h3 class=\"artstyle__title \" data-element-id=\"304e-de59-4b99-5d12-7a32-abd4-da51-f740\">\n<p>      Restrictions d&#8217;entr\u00e9e strictes<br \/>\n    <\/h3>\n<p class=\"artstyle__paragraph \" data-element-id=\"83e0-dcda-bc16-923c-0f22-3954-13af-8c7b\">\n<p>      De nombreux expatri\u00e9s \u00e9taient particuli\u00e8rement pr\u00e9occup\u00e9s par une interdiction d&#8217;entr\u00e9e introduite en janvier dans neuf pays, dont les \u00c9tats-Unis et la Grande-Bretagne, et la quarantaine obligatoire de deux \u00e0 trois semaines dans les h\u00f4tels.  Ces restrictions d&#8217;entr\u00e9e strictes, qui n&#8217;ont gu\u00e8re de sens \u00e9tant donn\u00e9 que le virus est d\u00e9j\u00e0 enti\u00e8rement \u00e0 Hong Kong, sont en cours d&#8217;ajustement.  Les \u00e9coles, la restauration et d&#8217;autres lieux de rencontre de Hong Kong rouvriront \u00e9galement \u00e0 partir de la mi-avril, dans certains cas progressivement.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"933f-fcf1-5a36-a5d1-a134-9740-c5e1-a097\">\n<p>      Apr\u00e8s avoir culmin\u00e9 d\u00e9but mars avec plus de 50 000 cas par jour, l&#8217;\u00e9pid\u00e9mie d&#8217;omikron \u00e0 Hong Kong s&#8217;\u00e9teint : 13 000 infections ont \u00e9t\u00e9 signal\u00e9es lundi.  Officiellement, Hong Kong reste attach\u00e9 \u00e0 la politique z\u00e9ro covid, bien que celle-ci soit d\u00e9sormais att\u00e9nu\u00e9e dans la pratique.  La ville semi-autonome continue d&#8217;\u00eatre coinc\u00e9e dans sa politique covid entre la Chine continentale, qui applique une politique z\u00e9ro covid beaucoup plus stricte, et le reste du monde, o\u00f9 la plupart des restrictions ont \u00e9t\u00e9 lev\u00e9es.\n    <\/p>\n<\/p>\n<aside class=\"artstyle__editorial-tips \" data-element-id=\"article-element-editorialtips\">\n<h3 class=\"editorial-tips__title\">Lire aussi<\/h3>\n<\/aside>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.demorgen.be\/nieuws\/zero-covid-beleid-in-hongkong-werkt-niet-meer-door-omikron-overheid-versoepelt-onder-druk-van-vertrekkende-expats~b5c3b0a6\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-31<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La dirigeante de Hong Kong, Carrie Lam, qui a \u00e9t\u00e9 la cible de tirs nourris pour sa r\u00e9ponse d\u00e9faillante au covid, a annonc\u00e9 l&#8217;assouplissement lundi. Elle a \u00e9galement annonc\u00e9 qu&#8217;elle annulerait le test de masse pr\u00e9vu pour l&#8217;ensemble de la population. Selon Lam, l&#8217;ajustement fait suite \u00e0 une diminution du nombre d&#8217;infections \u00e0 Hong Kong, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45968,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[794,133,32711,32710,12722,219,583,4479,4480,1413,1060,5606,364,367,7318],"class_list":["post-45967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-covid","tag-des","tag-detend","tag-domikron","tag-expatries","tag-fonctionne","tag-gouvernement","tag-hong","tag-kong","tag-partent","tag-politique","tag-pression","tag-qui","tag-sous","tag-zero"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=45967"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/45968"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=45967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=45967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=45967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}