{"id":45595,"date":"2022-03-21T08:16:51","date_gmt":"2022-03-21T10:16:51","guid":{"rendered":"https:\/\/teknomers.com\/fr\/avec-ce-coupe-sportif-skoda-jette-les-lettres-rs-dans-les-egouts\/"},"modified":"2022-03-21T08:16:57","modified_gmt":"2022-03-21T10:16:57","slug":"avec-ce-coupe-sportif-skoda-jette-les-lettres-rs-dans-les-egouts","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/avec-ce-coupe-sportif-skoda-jette-les-lettres-rs-dans-les-egouts\/","title":{"rendered":"Avec ce coup\u00e9 sportif, Skoda jette les lettres RS dans les \u00e9gouts"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<p class=\"article__intro\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"tag has-theme-background\">Test automatique<\/span>Avec le nouveau coup\u00e9 Enyaq, Skoda renoue avec les coup\u00e9s sportifs du pass\u00e9, mais bouscule en m\u00eame temps une autre tradition avec ce mod\u00e8le enti\u00e8rement \u00e9lectrique : celle des mod\u00e8les RS.<\/p>\n<\/p><\/div>\n<div>\n<p>\t\t\t\t\t\t\t\t\t\t<!-- includes\/advertising\/fixed-slot.html --><\/p>\n<p><!-- \/ includes\/advertising\/fixed-slot.html --><\/p>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">Les fans de Skoda les connaissent encore et m\u00eame parmi les passionn\u00e9s de voitures, ils peuvent encore sonner une cloche : les mod\u00e8les RS de la marque tch\u00e8que.  Le suffixe RS a \u00e9t\u00e9 utilis\u00e9 pour la premi\u00e8re fois en 1974 sur deux prototypes de rallye : les Skoda 180 RS et 200 RS.  En 1975, cela a abouti \u00e0 la Skoda 130 RS, \u00e9galement connue sous le nom de &#8220;Porsche de l&#8217;Est&#8221;.  Avec ce coup\u00e9 sport, Skoda a remport\u00e9 deux victoires de classe en 1977 au mythique Rallye de Monte Carlo et au Rallye de l&#8217;Acropole. <\/p>\n<\/div>\n<p><!-- article\/components\/subheader.html --><\/p>\n<h2 class=\"article__subheader\">Octavia RS<\/h2>\n<p><!-- \/ article\/components\/subheader.html -->\n<\/p>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">En 2000, Skoda a pr\u00e9sent\u00e9 l&#8217;Octavia RS, le premier mod\u00e8le de production de la s\u00e9rie RS.  Une voiture familiale sportive, qui dans sa version la plus r\u00e9cente \u00e9tait forte de 245 ch.  C&#8217;est pourquoi on peut imaginer que Skoda a pens\u00e9 pouvoir \u00e0 nouveau retirer les lettres RS pour le nouveau coup\u00e9 Enyaq enti\u00e8rement \u00e9lectrique.  Apr\u00e8s tout : ce mod\u00e8le \u00e9lectrique d\u00e9veloppe 300 ch et avec ses passages de roue prononc\u00e9s, ses vitres relativement basses et ses grandes roues sportives, il ressemble \u00e0 un coureur accompli. <\/p>\n<\/div>\n<div class=\"article__component article__component--picture\"><!-- includes\/article\/components\/picture.html --><\/p>\n<figure class=\"article__figure\"><figcaption class=\"figcaption\">Skoda Enyaq Coup\u00e9 RS<span class=\"figcaption__credit\"> \u00a9Skoda<\/span><br \/>\n\t<\/figcaption><\/figure>\n<p><!-- \/ includes\/article\/components\/picture.html -->\n<\/div>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">Malheureusement pour Skoda, cependant, la concurrence propose des mod\u00e8les plus rapides et plus sportifs dans la gamme, sans avoir \u00e0 utiliser un ajout de type RS.  Des mod\u00e8les tels que la Kia EV6 et la Tesla Model 3 ne sont peut-\u00eatre pas connus comme des coureurs pur-sang, mais ils ont plus de 100 ch de plus dans leur version la plus puissante et, en raison de leur bas de caisse, ils se penchent moins dans les virages, ce qui les rend plus sportifs.  La Skoda ne fait pas cela &#8211; malgr\u00e9 son badge RS.  Et avec une vitesse de pointe de 180 kilom\u00e8tres \u00e0 l&#8217;heure, vous ne m\u00e9ritez pas non plus les lettres RS \u00e0 nos yeux.  Parce que vous \u00eates un peu farceur si vous conduisez 180 en Allemagne avec votre RS et que vous \u00eates ensuite d\u00e9pass\u00e9 par une Tesla Model 3 \u00e0 233 km\/h.<\/p>\n<\/div>\n<p><!-- article\/components\/subheader.html --><\/p>\n<h2 class=\"article__subheader\">Mod\u00e8le de base<\/h2>\n<p><!-- \/ article\/components\/subheader.html -->\n<\/p>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">Retour au mod\u00e8le de base : le coup\u00e9 Enyaq est la version sportive de l&#8217;Enyaq.  Les diff\u00e9rences avec le <a rel=\"nofollow noopener\" href=\"https:\/\/www.ad.nl\/auto\/test-skoda-enyaq-iv-ruime-gezinsauto-laat-nog-te-wensen-over~ad0e8d7a\/\" target=\"_blank\">Enyaq &#8220;ordinaire&#8221; <\/a>sont petites, car en fait les deux voitures sont compl\u00e8tement identiques jusqu&#8217;\u00e0 la porte arri\u00e8re.  \u00c0 partir de l\u00e0, la ligne de toit du coup\u00e9 commence \u00e0 s&#8217;abaisser pour une apparence plus \u00e9l\u00e9gante et sportive.  La hauteur libre \u00e0 l&#8217;arri\u00e8re n&#8217;en souffre gu\u00e8re, car les passagers d&#8217;une hauteur allant jusqu&#8217;\u00e0 1,90 m\u00e8tre peuvent s&#8217;y asseoir sans se cogner la t\u00eate.  On peut se demander dans quelle mesure l&#8217;Enyaq est un vrai coup\u00e9.  En fait, c&#8217;est un <a rel=\"nofollow noopener\" href=\"https:\/\/www.autoweek.nl\/nieuweauto\/welke-types-auto-noem-je-een-liftback\/\" target=\"_blank\">remont\u00e9e <\/a>avec son hayon qui s&#8217;ouvre vers le haut.  Un coup\u00e9 n&#8217;a \u00e9galement formellement que deux portes, mais personne d&#8217;autre ne tombera pour cela.<\/p>\n<\/div>\n<div class=\"article__component article__component--picture\"><!-- includes\/article\/components\/picture.html --><\/p>\n<figure class=\"article__figure\">\n<p>\t\t\t<img decoding=\"async\" alt=\"Skoda Enyaq Coup\u00e9 RS\" loading=\"lazy\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2022\/03\/1647857811_248_Avec-ce-coupe-sportif-Skoda-jette-les-lettres-RS-dans.8.jpeg\" height=\"462\" width=\"694\" class=\"webfeedsFeaturedVisual\" \/><figcaption class=\"figcaption\">Skoda Enyaq Coup\u00e9 RS<span class=\"figcaption__credit\"> \u00a9Skoda<\/span><br \/>\n\t<\/figcaption><\/figure>\n<p><!-- \/ includes\/article\/components\/picture.html -->\n<\/div>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">C&#8217;est peut-\u00eatre une autre histoire avec le pare-soleil en trois parties.  Si vous souhaitez vous prot\u00e9ger d&#8217;un ensoleillement excessif qui p\u00e9n\u00e8tre par le toit en verre, vous devez sortir, ouvrir le hayon et tirer un \u00e9cran sous la plage arri\u00e8re.  Il faut ensuite le d\u00e9plier et t\u00e2tonner manuellement entre la garniture de toit et le toit en verre \u00e0 l&#8217;avant et \u00e0 l&#8217;arri\u00e8re.  Avec la concurrence, vous le faites en appuyant sur un bouton, mais avec Skoda, vous devez d&#8217;abord vous agenouiller sur votre si\u00e8ge avant pour faire glisser l&#8217;avant, puis vous faites la m\u00eame chose \u00e0 l&#8217;arri\u00e8re.  Ce n&#8217;est pas exactement un exemple de &#8220;Simply Clever&#8221;. <\/p>\n<\/div>\n<p><!-- article\/components\/subheader.html --><\/p>\n<h2 class=\"article__subheader\">visage de cristal<\/h2>\n<p><!-- \/ article\/components\/subheader.html -->\n<\/p>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">La version de base, l&#8217;Enyaq Coup\u00e9 iV 60, dispose d&#8217;une batterie de 62 kWh en combinaison avec un moteur \u00e9lectrique de 132 kW et une propulsion arri\u00e8re.  Ensuite, il y a l&#8217;iV 80 avec une batterie de 82 kWh et un moteur \u00e9lectrique de 150 kW qui entra\u00eene les roues arri\u00e8re.  L&#8217;iV 80x a le m\u00eame bloc-batterie, mais gr\u00e2ce \u00e0 un moteur \u00e9lectrique suppl\u00e9mentaire sur l&#8217;essieu avant, cette version d\u00e9veloppe 195 kW et dispose de quatre roues motrices.  La vitesse de pointe de toutes ces versions est limit\u00e9e \u00e0 160 km\/h et tous les mod\u00e8les sont adapt\u00e9s \u00e0 la recharge rapide : 120 kW maximum pour les versions \u00e0 propulsion et 135 kW pour les versions \u00e0 traction int\u00e9grale.  Par exemple, la batterie de 82 kWh du coup\u00e9 Enyaq iV 80 peut \u00eatre charg\u00e9e de 10 \u00e0 80 % en seulement 29 minutes.<\/p>\n<\/div>\n<div class=\"article__component article__component--picture\"><!-- includes\/article\/components\/picture.html --><\/p>\n<figure class=\"article__figure\">\n<p>\t\t\t<img decoding=\"async\" alt=\"Skoda Enyaq Coup\u00e9 RS\" loading=\"lazy\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2022\/03\/1647857811_168_Avec-ce-coupe-sportif-Skoda-jette-les-lettres-RS-dans.8.jpeg\" height=\"462\" width=\"694\" class=\"webfeedsFeaturedVisual\" \/><figcaption class=\"figcaption\">Skoda Enyaq Coup\u00e9 RS<span class=\"figcaption__credit\"> \u00a9Skoda<\/span><br \/>\n\t<\/figcaption><\/figure>\n<p><!-- \/ includes\/article\/components\/picture.html -->\n<\/div>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">La caract\u00e9ristique la plus frappante du coup\u00e9 est son &#8220;Crystal Face&#8221; en option, qui donne \u00e0 l&#8217;avant un look high-tech.  L&#8217;apparence de la voiture est \u00e9galement parfaitement soign\u00e9e et vous ne manquez pas non plus d&#8217;espace pour les bagages dans ce coup\u00e9.  Avec les si\u00e8ges arri\u00e8re utilis\u00e9s, le coffre \u00e0 bagages a d\u00e9j\u00e0 une capacit\u00e9 de 570 litres.  En rabattant le canap\u00e9, cela peut \u00eatre augment\u00e9 \u00e0 1 610 litres.  Avec la \u00ab\u00a0p\u00e9dale virtuelle\u00a0\u00bb en option, le hayon s&#8217;ouvre automatiquement apr\u00e8s un mouvement du pied.  Les versions \u00e0 propulsion arri\u00e8re du coup\u00e9 sont autoris\u00e9es \u00e0 tracter des remorques pesant jusqu&#8217;\u00e0 1 000 kilogrammes.  Les versions \u00e0 quatre roues motrices peuvent m\u00eame supporter 1 200 kilogrammes.  Nous connaissons l&#8217;int\u00e9rieur de l&#8217;Enyaq standard.  Il est spacieux, moderne, digital et connect\u00e9. <\/p>\n<\/div>\n<p><!-- article\/components\/subheader.html --><\/p>\n<h2 class=\"article__subheader\">Mamba Vert<\/h2>\n<p><!-- \/ article\/components\/subheader.html -->\n<\/p>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">L&#8217;Enyaq Coup\u00e9 RS iV est tr\u00e8s sportif gr\u00e2ce \u00e0 une puissance syst\u00e8me de 220 kW, un couple maximal de 460 Nm, une transmission int\u00e9grale et un ch\u00e2ssis abaiss\u00e9.  Il acc\u00e9l\u00e8re de 0 \u00e0 100 km\/h en seulement 6,5 secondes et la vitesse de pointe est limit\u00e9e \u00e0 180 km\/h.  La batterie de 82 kWh est bonne pour une autonomie de plus de 500 kilom\u00e8tres.  Gr\u00e2ce \u00e0 l&#8217;option de charge de 135 kW, il ne faut que 36 minutes pour charger la batterie de 10 \u00e0 80 %.  L&#8217;avant Crystal Face est standard ici et le RS est le seul Enyaq Coup\u00e9 iV disponible dans la couleur spectaculaire Mamba Green.<\/p>\n<\/div>\n<div class=\"article__component article__component--picture\"><!-- includes\/article\/components\/picture.html --><\/p>\n<figure class=\"article__figure\">\n<p>\t\t\t<img decoding=\"async\" alt=\"Skoda Enyaq Coup\u00e9 RS\" loading=\"lazy\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2022\/03\/1647857811_8_Avec-ce-coupe-sportif-Skoda-jette-les-lettres-RS-dans.8.jpeg\" height=\"462\" width=\"694\" class=\"webfeedsFeaturedVisual\" \/><figcaption class=\"figcaption\">Skoda Enyaq Coup\u00e9 RS<span class=\"figcaption__credit\"> \u00a9Skoda<\/span><br \/>\n\t<\/figcaption><\/figure>\n<p><!-- \/ includes\/article\/components\/picture.html -->\n<\/div>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">L&#8217;int\u00e9rieur RS Lounge respire \u00e9galement la sportivit\u00e9 avec un rev\u00eatement en tissu et Alcantara, des surpiq\u00fbres vert citron et une garniture de toit noire.  Le volant sport \u00e0 trois branches gain\u00e9 de cuir est multifonctionnel et comporte des palettes de r\u00e9cup\u00e9ration d&#8217;\u00e9nergie.  Vous pouvez \u00e9galement choisir l&#8217;un des cinq programmes de conduite Driving Mode Select sur le volant.  Malheureusement, l&#8217;exp\u00e9rience de conduite de la RS n&#8217;est gu\u00e8re diff\u00e9rente de celle du mod\u00e8le standard.  Et avec cela, la RS se sent \u00e9galement trop lourde pour parler d&#8217;un comportement de conduite sportif.  Ce qui semble \u00e9galement bizarre \u00e0 premi\u00e8re vue, c&#8217;est l&#8217;utilisation de freins \u00e0 tambour \u00e0 l&#8217;arri\u00e8re.  Ce n&#8217;est pas quelque chose que vous attendez imm\u00e9diatement d&#8217;une RS.  Mais parce que vous utilisez \u00e0 peine les freins sur un VE et les freins arri\u00e8re presque pas du tout, les disques de frein rouillent rapidement dans la pratique.  Au fil du temps, cela entra\u00eene beaucoup d&#8217;entretien suppl\u00e9mentaire, nous comprenons donc ce choix. <\/p>\n<\/div>\n<p><!-- article\/components\/subheader.html --><\/p>\n<h2 class=\"article__subheader\">\u00c0 partir de 58 990 \u20ac<\/h2>\n<p><!-- \/ article\/components\/subheader.html -->\n<\/p>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">L\u00e0 o\u00f9 d&#8217;autres v\u00e9hicules \u00e9lectriques se sentent souvent beaucoup moins lourds que ce \u00e0 quoi on pourrait s&#8217;attendre sur la base de leur poids en raison d&#8217;un ch\u00e2ssis sophistiqu\u00e9, les kilos de cette RS se sentent malheureusement bien.  Non seulement dans les virages, mais aussi sur les routes dont la surface est inf\u00e9rieure \u00e0 celle d&#8217;une toile de billard.  Le ch\u00e2ssis semble trop \u00e9lastique, malgr\u00e9 de l\u00e9gers ajustements par rapport au mod\u00e8le standard.  De plus, les freins ne sont pas trop mordants et n&#8217;inspirent pas confiance.  En mode sport, la direction offre un peu plus de sensations, mais c&#8217;est tout.  Le groupe VW a probablement dit \u00e0 Skoda qu&#8217;ils n&#8217;\u00e9taient pas autoris\u00e9s \u00e0 faire une version vraiment rapide et sportive de l&#8217;Enyaq, sinon ils n&#8217;auraient probablement jamais jet\u00e9 le badge RS avec cette version la plus rapide quelque peu d\u00e9cevante de l&#8217;Enyaq Coup\u00e9. <\/p>\n<\/div>\n<div class=\"article__component article__component--paragraph\">\n<p class=\"article__paragraph\">L&#8217;ENYAQ COUP\u00c9 RS iV est disponible \u00e0 l&#8217;achat \u00e0 partir de 58 990 \u20ac.  La livraison des autres mod\u00e8les d\u00e9butera \u00e9galement au milieu de cette ann\u00e9e.  Le prix de l&#8217;Enyaq Coup\u00e9 RS n&#8217;est pas encore connu.<\/p>\n<\/div>\n<div class=\"article__component article__component--snippet\"><!-- article\/components\/snippet.html --><br \/>\n<!-- htmllint attr-req-value=\"false\" attr-no-unsafe-char=\"false\" indent-style=\"false\" --><\/p>\n<p><!-- htmllint attr-req-value=\"$previous\" attr-no-unsafe-char=\"$previous\" indent-style=\"$previous\" --><\/p>\n<div class=\"snippet fjs-snippet\" data-privacy-category=\"socialmedia\" style=\"min-height: 330px\">\n<p>\t\t<!-- includes\/article\/social-content-placeholder.html --><\/p>\n<div class=\"no-consent-placeholder fjs-no-consent-placeholder\">\n<div class=\"no-consent-placeholder__content\">\n<header class=\"no-consent-placeholder__header\">Nos excuses<\/header>\n<p>Malheureusement, nous ne pouvons pas afficher cette publication sociale, blog en direct ou autre, car elle contient un ou plusieurs \u00e9l\u00e9ments de m\u00e9dias sociaux.  Acceptez les cookies des r\u00e9seaux sociaux pour continuer \u00e0 afficher ce contenu.<\/p>\n<\/p><\/div>\n<footer class=\"no-consent-placeholder__footer\">\n\t\t<a rel=\"nofollow\" class=\"no-consent-placeholder__footer--link button--list-block\" href=\"#\">Modifier les param\u00e8tres des cookies<\/a><br \/>\n\t<\/footer>\n<\/div>\n<p><!-- \/ includes\/article\/social-content-placeholder.html --><\/p><\/div>\n<p><!-- \/ article\/components\/snippet.html -->\n<\/div>\n<div class=\"article-login-gate fjs-article-login-gate\">\n<p class=\"article-login-gate__title fjs-article-login-gate__title\">\n<p>\t\tAcc\u00e8s gratuit et illimit\u00e9 \u00e0 Showbytes\u00a0?  Qui peut!\n\t<\/p>\n<p>\t<span class=\"article-login-gate__info fjs-article-login-gate__info\"><\/p>\n<p>\t\tConnectez-vous ou cr\u00e9ez un compte et ne manquez rien des \u00e9toiles.<br \/>\n\t<\/span><\/p>\n<p class=\"article-login-gate__buttonholder\">\n<p>\t\t\t<span class=\"button__text fjs-article-login-gate__button\">Oui, je veux un acc\u00e8s gratuit et illimit\u00e9<\/span><\/p>\n<\/div><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.destentor.nl\/auto\/met-deze-sportief-bedoelde-coupe-spoelt-skoda-de-letters-rs-door-het-afvoerputje~a313fbf9\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-42<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Test automatiqueAvec le nouveau coup\u00e9 Enyaq, Skoda renoue avec les coup\u00e9s sportifs du pass\u00e9, mais bouscule en m\u00eame temps une autre tradition avec ce mod\u00e8le enti\u00e8rement \u00e9lectrique : celle des mod\u00e8les RS. Les fans de Skoda les connaissent encore et m\u00eame parmi les passionn\u00e9s de voitures, ils peuvent encore sonner une cloche : les mod\u00e8les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45596,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[84,1008,429,30821,9009,65,9571,32533,2920],"class_list":["post-45595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-avec","tag-coupe","tag-dans","tag-egouts","tag-jette","tag-les","tag-lettres","tag-skoda","tag-sportif"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=45595"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45595\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/45596"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=45595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=45595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=45595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}