{"id":45410,"date":"2022-03-21T05:44:01","date_gmt":"2022-03-21T07:44:01","guid":{"rendered":"https:\/\/teknomers.com\/fr\/succes-unique-du-relais-orange-remporte-des-prix-pour-les-hommes-et-les-femmes\/"},"modified":"2022-03-21T05:44:10","modified_gmt":"2022-03-21T07:44:10","slug":"succes-unique-du-relais-orange-remporte-des-prix-pour-les-hommes-et-les-femmes","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/succes-unique-du-relais-orange-remporte-des-prix-pour-les-hommes-et-les-femmes\/","title":{"rendered":"Succ\u00e8s unique du relais : Orange remporte des prix pour les hommes et les femmes"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<div class=\"PremiumLabelWithLine TextArticlePage__premiumLabel\">\n<p class=\"PremiumLabelWithLine__label\">Prime<\/p>\n<p class=\"PremiumLabelWithLine__bestOf\">Le meilleur de De Telegraaf<\/p>\n<\/div>\n<div class=\"TextArticlePage__socialWrapper\">\n<div class=\"ArticleAuthorBlock\" data-element=\"articleAuthor\">\n<div class=\"ArticleAuthorBlock__contentWrapper\">\n<p class=\"ArticleAuthorBlock__paragraph\">Par <strong class=\"ArticleAuthorBlock__paragraphStrong\">Willem a tenu<\/strong><\/p>\n<p>il y a 14 minutes<span class=\"ArticleAuthorBlock__sectionBlock\"> dans <span class=\"ArticleAuthorBlock__sectionName ArticleAuthorBlock__sectionName--sport\">SPORT<\/span><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"TextArticlePage__imageWrapper TextArticlePage__imageWrapper--mobile\">\n<div class=\"ArticleImage\">\n<div class=\"FluidImage__placeholder\"><img data-desking=\"image\" class=\"Image__img FluidImage__image\" alt=\"Les femmes apr\u00e8s avoir gagn\u00e9 l'argent.\" \/><\/div>\n<div class=\"ArticleImage__descriptionWrapper\" data-element=\"articleImage\">\n<p class=\"ArticleImage__paragraph\" data-element=\"articleImageDescription\">Les femmes apr\u00e8s avoir gagn\u00e9 l&#8217;argent.<\/p>\n<p class=\"ArticleImage__paragraph ArticleImage__paragraph--copyright\" data-element=\"articleImageCopyright\">\u24b8 <!-- -->ANP\/HH<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p class=\"ArticleIntro__paragraph ArticleIntro__paragraph--sport\"><span class=\"ArticleIntro__location\">BELGRADE- <\/span><span id=\"articleIntro156407468\">Les hommes avaient secr\u00e8tement esp\u00e9r\u00e9 plus, mais les deux m\u00e9dailles en Coupe du monde des \u00e9quipes de relais n\u00e9erlandaises sont vraiment uniques.  Les Pays-Bas n&#8217;avaient jamais particip\u00e9 \u00e0 cette partie des Championnats du monde en salle et \u00e0 Belgrade, la nation d\u00e9butante s&#8217;est av\u00e9r\u00e9e \u00eatre le seul pays \u00e0 avoir remport\u00e9 des prix \u00e0 la fois chez les hommes (bronze) et chez les femmes (argent).<\/span><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.telegraaf.nl\/sport\/156407468\/uniek-estafettesucces-oranje-valt-zowel-bij-mannen-als-vrouwen-in-de-prijzen\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-2<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prime Le meilleur de De Telegraaf Par Willem a tenu il y a 14 minutes dans SPORT Les femmes apr\u00e8s avoir gagn\u00e9 l&#8217;argent. \u24b8 ANP\/HH BELGRADE- Les hommes avaient secr\u00e8tement esp\u00e9r\u00e9 plus, mais les deux m\u00e9dailles en Coupe du monde des \u00e9quipes de relais n\u00e9erlandaises sont vraiment uniques. Les Pays-Bas n&#8217;avaient jamais particip\u00e9 \u00e0 cette [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45411,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[133,315,2959,65,8053,185,646,2876,3945,1864,12378],"class_list":["post-45410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-des","tag-femmes","tag-hommes","tag-les","tag-orange","tag-pour","tag-prix","tag-relais","tag-remporte","tag-succes","tag-unique"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=45410"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/45411"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=45410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=45410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=45410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}