{"id":45339,"date":"2022-03-21T04:51:19","date_gmt":"2022-03-21T06:51:19","guid":{"rendered":"https:\/\/teknomers.com\/fr\/plusieurs-voitures-senflamment-a-berlin-fennpfuhl\/"},"modified":"2022-03-21T04:51:24","modified_gmt":"2022-03-21T06:51:24","slug":"plusieurs-voitures-senflamment-a-berlin-fennpfuhl","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/plusieurs-voitures-senflamment-a-berlin-fennpfuhl\/","title":{"rendered":"Plusieurs voitures s&#8217;enflamment \u00e0 Berlin-Fennpfuhl"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"post-4300275\">\n<header class=\"article-header row\">\n<p><h2>Incendie criminel suspect\u00e9<\/h2>\n<\/p>\n<\/header>\n<div class=\"row\">\n<p>            <!-- Content --><\/p>\n<div class=\"col-xs-12 col-md-8\">\n<section class=\"article-content\">\n<div class=\"article-text\">\n<header class=\"article-meta\">\n<div class=\"article-meta-box-left pull-left\">\n<p>                            <span class=\"avatar\"><\/p>\n<p>                                    <\/span><br \/>\n                <span class=\"author-name\"><\/p>\n<p>                    BZ<br \/>\n                <\/span><\/p><\/div>\n<div class=\"article-meta-box-right pull-right\">\n        <span>21 mars 2022 07:38<\/span><br \/>\n                                    <span class=\"post-updated brand-primary\">Mis \u00e0 jour 07:40<br \/>\n                                    <\/span><\/p><\/div>\n<\/header>\n<p class=\"excerpt\">\n<p>                    Plusieurs voitures ont br\u00fbl\u00e9 \u00e0 Berlin-Fennpfuhl lundi soir.\n                <\/p>\n<p>Vers 01h20, plusieurs v\u00e9hicules ont pris feu sur la Franz-Jacob-Strasse \u00e0 Berlin-Fennpfuhl, dont au moins une voiture de soci\u00e9t\u00e9.  Selon les informations de BZ, un employ\u00e9 de la s\u00e9curit\u00e9 d&#8217;un centre commercial a remarqu\u00e9 les voitures en feu et a appel\u00e9 les pompiers.<\/p>\n<p>Les pompiers ont \u00e9teint les trois v\u00e9hicules, qui ont compl\u00e8tement br\u00fbl\u00e9.  Deux autres voitures ont \u00e9t\u00e9 endommag\u00e9es par la chaleur intense.  Personne n&#8217;a \u00e9t\u00e9 bless\u00e9, ont indiqu\u00e9 les pompiers.  Les pompiers ont \u00e9teint le feu apr\u00e8s plus d&#8217;une heure.<\/p>\n<p><strong>La police enqu\u00eate sur la cause de l&#8217;incendie et un incendie criminel est actuellement suspect\u00e9.<\/strong><\/p>\n<\/p><\/div>\n<\/section>\n<\/div>\n<p>            <!-- Sidebar --><\/p><\/div>\n<p>        <!-- below article sidebar --><\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.bz-berlin.de\/berlin\/lichtenberg\/mehrere-autos-gehen-in-berlin-fennpfuhl-in-flammen-auf\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-27<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incendie criminel suspect\u00e9 BZ 21 mars 2022 07:38 Mis \u00e0 jour 07:40 Plusieurs voitures ont br\u00fbl\u00e9 \u00e0 Berlin-Fennpfuhl lundi soir. Vers 01h20, plusieurs v\u00e9hicules ont pris feu sur la Franz-Jacob-Strasse \u00e0 Berlin-Fennpfuhl, dont au moins une voiture de soci\u00e9t\u00e9. Selon les informations de BZ, un employ\u00e9 de la s\u00e9curit\u00e9 d&#8217;un centre commercial a remarqu\u00e9 les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45340,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1657,32438,1656,32437,32436,701,5576,5575,28784,830],"class_list":["post-45339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-actualites-berlinoises","tag-berlinfennpfuhl","tag-courant-de-berlin","tag-fenfoul","tag-feu-de-voiture","tag-plusieurs","tag-police-berlinoise","tag-pompiers-de-berlin","tag-senflamment","tag-voitures"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=45339"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45339\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/45340"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=45339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=45339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=45339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}