{"id":45146,"date":"2022-03-21T01:41:55","date_gmt":"2022-03-21T03:41:55","guid":{"rendered":"https:\/\/teknomers.com\/fr\/quatre-maisons-inhabitables-apres-lincendie-damsterdam-ouest-je-pensais-que-je-devais-sortir-dici\/"},"modified":"2022-03-21T01:42:07","modified_gmt":"2022-03-21T03:42:07","slug":"quatre-maisons-inhabitables-apres-lincendie-damsterdam-ouest-je-pensais-que-je-devais-sortir-dici","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/quatre-maisons-inhabitables-apres-lincendie-damsterdam-ouest-je-pensais-que-je-devais-sortir-dici\/","title":{"rendered":"Quatre maisons inhabitables apr\u00e8s l&#8217;incendie d&#8217;Amsterdam-Ouest\u00a0: &quot;Je pensais que je devais sortir d&#8217;ici&quot;"},"content":{"rendered":"\n<div>\n<div class=\"container--detail intro__text\">\n<p><strong>En raison de l&#8217;incendie de la maison de la nuit derni\u00e8re dans la Marco Polostraat \u00e0 West, quatre maisons seront probablement inhabitables pendant une p\u00e9riode plus longue.  Lors de l&#8217;important incendie, qui s&#8217;est d\u00e9clar\u00e9 sur un balcon \u00e0 l&#8217;arri\u00e8re de la maison porche, une vingtaine d&#8217;habitations ont \u00e9t\u00e9 \u00e9vacu\u00e9es par pr\u00e9caution.<\/strong><\/p>\n<\/div>\n<div class=\"container--detail detail-text\">\n<p>L&#8217;incendie de la maison s&#8217;est d\u00e9clar\u00e9 au deuxi\u00e8me \u00e9tage vers 19 heures hier.  Puis il s&#8217;est rapidement propag\u00e9 au troisi\u00e8me \u00e9tage.  Un certain nombre de b\u00e2timents adjacents ont \u00e9galement pris feu \u00e0 travers le toit de la chambre haute.  Vers 21 heures, les pompiers signalent que le feu est ma\u00eetris\u00e9.  Les pompiers sont occup\u00e9s \u00e0 \u00e9teindre les incendies depuis un certain temps.<\/p>\n<p>Certains r\u00e9sidents locaux ont pu regagner leur domicile pendant la nuit.  Au total, huit maisons \u00e9taient inhabitables la nuit derni\u00e8re, en partie \u00e0 cause des d\u00e9g\u00e2ts des eaux caus\u00e9s par les activit\u00e9s d&#8217;extinction.  Aujourd&#8217;hui, il s&#8217;est av\u00e9r\u00e9 que quatre maisons sont probablement inhabitables pendant longtemps.<\/p>\n<\/div>\n<section class=\"media-item-container\">\n<figure class=\"figure\" \/><\/section>\n<div class=\"container--detail detail-text\">\n<p>Un jour apr\u00e8s l&#8217;incendie, de nombreux riverains sont encore tr\u00e8s effray\u00e9s.  Un habitant du quartier dont la maison a \u00e9t\u00e9 \u00e9vacu\u00e9e la nuit derni\u00e8re raconte : &#8220;C&#8217;\u00e9tait la panique chez tout le monde. Les pompiers ont aussi fait un excellent travail et sont intervenus tr\u00e8s rapidement.&#8221;<\/p>\n<p>Les pompiers ont pu monter sur le toit via la maison du voisin pour \u00e9teindre le feu.  Quelques instants plus tard, elle a d\u00fb quitter son domicile par pr\u00e9caution.  &#8220;Je n&#8217;arrivais plus \u00e0 penser clairement. Qu&#8217;est-ce que tu emm\u00e8nes avec toi ? J&#8217;ai juste pens\u00e9 : je dois sortir d&#8217;ici.&#8221;<\/p>\n<\/div>\n<blockquote class=\"quote\">\n<div class=\"quote__body\">\n<p class=\"quote__text\">&#8220;Tout le monde paniquait&#8221;<\/p>\n<\/div>\n<footer class=\"author\">INCENDIE R\u00c9SIDENTIEL MARCO POLOSTRAAT <\/footer>\n<\/blockquote>\n<section class=\"media-item-container\">\n<figure class=\"figure\" \/><\/section>\n<div class=\"container--detail detail-text\">\n<p>Les services d&#8217;urgence sont rest\u00e9s plus longtemps pour surveiller les maisons.  Les riverains en \u00e9taient ravis : &#8220;Tout ce qu&#8217;on a vu toute la soir\u00e9e, ce sont des lampes de poche et des pompiers assez h\u00e9ro\u00efques au travail. On a m\u00eame point\u00e9 du doigt et cri\u00e9 o\u00f9 ils devaient aller. Ils se sont occup\u00e9s jusque tard dans la nuit. \u00e0 retirer des pi\u00e8ces pour voir si c&#8217;\u00e9tait toujours en feu \u00bb, raconte un habitant. <\/p>\n<p>L&#8217;incendie de la maison est toujours le sujet de conversation de la ville dans la r\u00e9gion.  &#8220;Les gens passent et se parlent. Hier, nous avons appris \u00e0 bien conna\u00eetre tous les voisins, car tout le monde s&#8217;est r\u00e9uni. C&#8217;\u00e9tait bien.&#8221;<\/p>\n<\/div>\n<div class=\"info \" style=\"background:#dcf8c6\">\n<p><strong>? Vous ne voulez rien manquer d&#8217;Amsterdam ?<\/strong><\/p>\n<p>Vous avez vu une faute de frappe\u00a0?  Faites-nous savoir \u00e0 <strong><span class=\"__cf_email__\" data-cfemail=\"f3879a98959c8687b39d9b9e96979a92dd9d9f\">[email\u00a0protected]<\/span><\/strong><\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nhnieuws.nl\/nieuws\/301490\/vier-woningen-onbewoonbaar-na-brand-amsterdam-west-ik-dacht-ik-moet-hier-weg\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-55<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En raison de l&#8217;incendie de la maison de la nuit derni\u00e8re dans la Marco Polostraat \u00e0 West, quatre maisons seront probablement inhabitables pendant une p\u00e9riode plus longue. Lors de l&#8217;important incendie, qui s&#8217;est d\u00e9clar\u00e9 sur un balcon \u00e0 l&#8217;arri\u00e8re de la maison porche, une vingtaine d&#8217;habitations ont \u00e9t\u00e9 \u00e9vacu\u00e9es par pr\u00e9caution. L&#8217;incendie de la maison [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45147,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[271,32355,23353,32356,32354,165,5782,17142,313,283,2112],"class_list":["post-45146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-apres","tag-damsterdamouest","tag-devais","tag-diciquot","tag-inhabitables","tag-lincendie","tag-maisons","tag-pensais","tag-quatre","tag-quotje","tag-sortir"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=45146"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/45147"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=45146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=45146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=45146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}