{"id":45020,"date":"2022-03-20T23:10:04","date_gmt":"2022-03-21T01:10:04","guid":{"rendered":"https:\/\/teknomers.com\/fr\/laz-chute-a-la-cinquieme-place-apres-un-match-nul-contre-willem-ii\/"},"modified":"2022-03-20T23:10:14","modified_gmt":"2022-03-21T01:10:14","slug":"laz-chute-a-la-cinquieme-place-apres-un-match-nul-contre-willem-ii","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/laz-chute-a-la-cinquieme-place-apres-un-match-nul-contre-willem-ii\/","title":{"rendered":"L&#8217;AZ chute \u00e0 la cinqui\u00e8me place apr\u00e8s un match nul contre Willem II"},"content":{"rendered":"\n<div>\n<p><strong>AZ a rencontr\u00e9 un savon lors d&#8217;une visite \u00e0 Willem II.  A Tilburg, c&#8217;\u00e9tait 2-2.  Du coup, le FC Twente d\u00e9passe l&#8217;AZ et l&#8217;\u00e9quipe de Pascal Jansen chute \u00e0 la cinqui\u00e8me place de l&#8217;Eredivisie. <\/strong><\/p>\n<\/div>\n<div>\n<h2>D\u00e9but dramatique AZ<\/h2>\n<p>Tr\u00e8s t\u00f4t dans le match, l&#8217;AZ \u00e9tait men\u00e9 2-0.  A la septi\u00e8me minute, c&#8217;est Ch\u00e9 Nunnely qui marque de la t\u00eate le 1-0 et dix minutes plus tard c&#8217;est Elton Kabangu qui inscrit le deuxi\u00e8me but de la soir\u00e9e face \u00e0 face avec le gardien de l&#8217;AZ Peter Vindahl.<\/p>\n<p>L&#8217;AZ est revenu dans le match \u00e0 la 35e minute.  Bruno Martins Indi a simplement tap\u00e9 dans un coin.  Les Alkmaarders ont pouss\u00e9 dans le reste de la premi\u00e8re mi-temps, mais ils n&#8217;ont pas marqu\u00e9.<\/p>\n<p>Dans le temps additionnel de la premi\u00e8re mi-temps, l&#8217;AZ semblait conc\u00e9der un penalty, mais gr\u00e2ce au VAR, l&#8217;arbitre Rob Dieperink a d\u00fb revenir sur sa d\u00e9cision.<\/p>\n<\/div>\n<div>\n<h2>AZ avec opportunit\u00e9s<\/h2>\n<p>La deuxi\u00e8me mi-temps \u00e0 Tilburg a commenc\u00e9 sans trop de d\u00e9tails.  \u00ddukinari Sugawara \u00e9tait proche de l&#8217;\u00e9galisation, mais son tir est pass\u00e9 au-dessus de la barre transversale.  Dani de Wit n&#8217;a pas eu de chance non plus.  Apr\u00e8s une superbe attaque AZ, il a \u00e9br\u00e9ch\u00e9 le ballon sur le poteau.<\/p>\n<p>C&#8217;\u00e9tait AZ avec la possession du ballon, mais dans la phase finale, il n&#8217;\u00e9tait presque plus dangereux.  Dans les arr\u00eats de jeu, c&#8217;\u00e9tait quand m\u00eame un succ\u00e8s pour AZ.  Le rempla\u00e7ant Zakaria Aboukhlal est entr\u00e9 de la t\u00eate sur corner.  Plus aucun but n&#8217;a \u00e9t\u00e9 marqu\u00e9 dans le reste du temps d&#8217;arr\u00eat.<\/p>\n<p><strong>Configuration AZ\u00a0:<\/strong> Vindahl\u00a0;  Witry (Aboukhlal\/68), Hatzidiakos (Beukema\/87), Martins Indi, Wijndal\u00a0;  Reijnders (Evjen\/68), De Wit, Clasie\u00a0;  Sugawara, Pavlidis, Karlsson<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nhnieuws.nl\/nieuws\/301491\/az-zakt-naar-plek-vijf-na-gelijkspel-tegen-willem-ii\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-55<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AZ a rencontr\u00e9 un savon lors d&#8217;une visite \u00e0 Willem II. A Tilburg, c&#8217;\u00e9tait 2-2. Du coup, le FC Twente d\u00e9passe l&#8217;AZ et l&#8217;\u00e9quipe de Pascal Jansen chute \u00e0 la cinqui\u00e8me place de l&#8217;Eredivisie. D\u00e9but dramatique AZ Tr\u00e8s t\u00f4t dans le match, l&#8217;AZ \u00e9tait men\u00e9 2-0. A la septi\u00e8me minute, c&#8217;est Ch\u00e9 Nunnely qui marque [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45021,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[271,2798,4755,841,14427,69,1502,1814,8937],"class_list":["post-45020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-apres","tag-chute","tag-cinquieme","tag-contre","tag-laz","tag-match","tag-nul","tag-place","tag-willem"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=45020"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/45020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/45021"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=45020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=45020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=45020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}