{"id":448141,"date":"2022-11-05T06:02:29","date_gmt":"2022-11-05T08:02:29","guid":{"rendered":"https:\/\/teknomers.com\/fr\/milan-sommet-fixe-avec-lagent-dadli-les-deux-scenarios-pour-janvier\/"},"modified":"2022-11-05T06:02:30","modified_gmt":"2022-11-05T08:02:30","slug":"milan-sommet-fixe-avec-lagent-dadli-les-deux-scenarios-pour-janvier","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/milan-sommet-fixe-avec-lagent-dadli-les-deux-scenarios-pour-janvier\/","title":{"rendered":"Milan, sommet fix\u00e9 avec l&#8217;agent d&#8217;Adli : les deux sc\u00e9narios pour janvier"},"content":{"rendered":"\n<div id=\"article-body\">\n<p>                        <strong>Talent pur<\/strong>.  Autour de Milanello, ces deux mots sont utilis\u00e9s pour d\u00e9crire <strong>Yacine Adli<\/strong>.  Des pieds qui savent dessiner le football auxquels il faut ajouter la bonne connaissance des rythmes du football italien.  Pour l&#8217;instant un seul match en tant que titulaire \u00e0 V\u00e9rone et quelques morceaux de jeu pour l&#8217;ancien Bordelais qui rencontre plus d&#8217;une difficult\u00e9 \u00e0 se tailler une place importante dans les rotations de <strong>Stefano Pioli<\/strong>.<\/p>\n<p><a rel=\"nofollow noopener\" class=\"spreaker-player\" data-chapters-image=\"true\" data-episode-image-position=\"right\" data-height=\"200px\" data-hide-comments=\"false\" data-hide-download=\"true\" data-hide-likes=\"false\" data-hide-logo=\"false\" data-hide-sharing=\"false\" data-playlist=\"false\" data-playlist-continuous=\"false\" data-resource=\"episode_id=51786038\" data-theme=\"dark\" data-width=\"100%\" href=\"https:\/\/www.spreaker.com\/episode\/51786038\" target=\"_blank\">\u00c9coutez &#8220;Milan, sommet fix\u00e9 avec l&#8217;agent d&#8217;Adli\u00a0: les deux sc\u00e9narios pour janvier&#8221; sur Spreaker.<\/a><\/p>\n<p><strong>CE QUI CHANGE EN JANVIER <\/strong>&#8211; <strong>L&#8217;id\u00e9e de Milan est de poursuivre le chemin de l&#8217;acclimatation avec les Rossoneri \u00e9galement dans les mois \u00e0 venir<\/strong>.  Adli est un joueur en qui Maldini et Massara croient fortement surtout pour l&#8217;avenir. <strong>Mais en janvier, diff\u00e9rentes solutions ne sont pas \u00e0 exclure, surtout si c&#8217;est le gar\u00e7on qui demande \u00e0 sortir jouer en pr\u00eat<\/strong>.  En ce sens, le voisin sera fondamental <strong>sommet avec l&#8217;agent Sissoko<\/strong>: sur la table de discussion il y aura \u00e0 la fois la situation d&#8217;Adli et le renouvellement du contrat de Bennacer.  Deux joueurs que Milan consid\u00e8re comme centraux dans le projet.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.calciomercato.com\/news\/milan-summit-fissato-con-l-agente-di-adli-i-due-scenari-per-genn-60439\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-4<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Talent pur. Autour de Milanello, ces deux mots sont utilis\u00e9s pour d\u00e9crire Yacine Adli. Des pieds qui savent dessiner le football auxquels il faut ajouter la bonne connaissance des rythmes du football italien. Pour l&#8217;instant un seul match en tant que titulaire \u00e0 V\u00e9rone et quelques morceaux de jeu pour l&#8217;ancien Bordelais qui rencontre plus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":448142,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[84,28628,245,17720,12243,15011,65,628,185,14227,6946],"class_list":["post-448141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-avec","tag-dadli","tag-deux","tag-fixe","tag-janvier","tag-lagent","tag-les","tag-milan","tag-pour","tag-scenarios","tag-sommet"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/448141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=448141"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/448141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/448142"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=448141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=448141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=448141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}