{"id":444916,"date":"2022-11-03T08:46:25","date_gmt":"2022-11-03T10:46:25","guid":{"rendered":"https:\/\/teknomers.com\/fr\/lhistoire-dune-rancon-dune-femme-pleine-de-force\/"},"modified":"2022-11-03T08:46:27","modified_gmt":"2022-11-03T10:46:27","slug":"lhistoire-dune-rancon-dune-femme-pleine-de-force","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/lhistoire-dune-rancon-dune-femme-pleine-de-force\/","title":{"rendered":"L&#8217;histoire d&#8217;une ran\u00e7on, d&#8217;une femme pleine de force"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"p1\"><span class=\"first-letter\">\u00c0<\/span>il n&#8217;avait que 15 ans <strong>Ema Stokholma<\/strong> (vrai nom <strong>Morwenn Mogu\u00e9rou<\/strong>) \u00e0 son arriv\u00e9e en Italie.  Il avait quitt\u00e9 la France pour \u00e9chapper \u00e0 une vie de violence et d&#8217;insultes.  Aujourd&#8217;hui on la conna\u00eet tous : DJ, animatrice radio et t\u00e9l\u00e9 et concurrente de la derni\u00e8re \u00e9dition de <em>danser avec les \u00e9toiles<\/em>.  Mais derri\u00e8re le personnage bien connu, il y a <strong>une enfance difficile qu&#8217;Ema raconte dans son livre<\/strong> <em>Pour mon bien.<\/em> Sorti il \u200b\u200by a deux ans, c&#8217;est un r\u00e9cit \u00e0 c\u0153ur ouvert de tout ce qu&#8217;elle a travers\u00e9 quand elle n&#8217;\u00e9tait qu&#8217;une enfant.<\/p>\n<h2 class=\"p1\">Ema Stokholma et son enfance difficile<\/h2>\n<p class=\"p1\"><strong>Violences, coups et insultes :<\/strong> la pr\u00e9sentatrice a v\u00e9cu tout cela dans sa maison.  Le monstre dont il avait peur \u00e9tait sa m\u00e8re.  Il l&#8217;a battue et l&#8217;a bless\u00e9e, dans son c\u0153ur et dans son \u00e2me, au point de souhaiter sa mort.<\/p>\n<article class=\"id-vda-article box_ed_hp_02-article eltdf-item-space hentry-pos-i hentry-home_section-i post-iiiii post type-post status-publish format-standard hentry\" \/>\n<p class=\"p1\">&#8220;<strong>Vous n&#8217;\u00eates jamais en s\u00e9curit\u00e9 nulle part<\/strong>L&#8217;enseignement qu&#8217;il a appris des ann\u00e9es pass\u00e9es en France avec sa m\u00e8re et son fr\u00e8re Gwendal est-il un peu plus<span class=\"Apple-converted-space\">  <\/span>grande d&#8217;elle et, comme elle, victime d&#8217;une m\u00e8re ogre. <strong>Une femme psychologiquement instable,<\/strong> incapable d&#8217;amour, ce qui a d\u00e9vers\u00e9 sur ses enfants la col\u00e8re et la douleur d&#8217;avoir \u00e9t\u00e9 abandonn\u00e9e par son mari alors qu&#8217;elle \u00e9tait enceinte de Morwenn.  &#8220;<strong>Je rentrais \u00e0 la maison et nous frappais<\/strong>\u00bb dit-il dans le livre.<\/p>\n<h2 class=\"p1\">La r\u00e9demption en Italie<\/h2>\n<p class=\"p1\">Du c\u00f4t\u00e9 de sa m\u00e8re, la DJ ne se souvient pas d&#8217;un c\u00e2lin ou d&#8217;un sourire, mais seulement d&#8217;ecchymoses et d&#8217;humiliations.  Pour \u00e9chapper \u00e0 toute cette violence, Morwenn se r\u00e9fugie dans son amour de la musique.<\/p>\n<\/p>\n<p class=\"p1\">Et, \u00e0 15 ans, <strong>apr\u00e8s plusieurs tentatives infructueuses, il parvient \u00e0 s&#8217;\u00e9chapper de chez lui<\/strong>.  Il arrive en Italie o\u00f9 commence sa r\u00e9demption.  Il retrouve son p\u00e8re mais une relation ne s&#8217;est jamais cr\u00e9\u00e9e entre eux.  Elle commence \u00e0 travailler comme mannequin pour de grandes marques de mode.  Puis l&#8217;amour de la musique prend le dessus.<\/p>\n<p class=\"p1\">Devenez DJ d&#8217;abord, puis h\u00f4te. <strong>Son nom change \u00e9galement : Morwenn Moguerou est parti.  Devenir Ema Stokholma<\/strong>.  Et avec ce nom, il laisse \u00e9galement son pass\u00e9 derri\u00e8re lui.  Mais ne l&#8217;oubliez pas.  Au point qu&#8217;il a voulu tout raconter dans un livre, \u00e0 la fois pour aider ceux qui vivent des situations similaires et pour d\u00e9montrer que la sienne est une histoire de r\u00e9demption et de vengeance.<span class=\"Apple-converted-space\"> <\/span><\/p>\n<div class=\"player_single_video_component\">\n                <img decoding=\"async\" id=\"imgVideoPlayer\" class=\"\" alt=\"Danse avec les stars : la valse de Cesare Bocci avec sa femme \u00e9meut tout le monde\" title=\"Danse avec les stars : la valse de Cesare Bocci avec sa femme \u00e9meut tout le monde\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2022\/11\/1667472385_20_Lhistoire-dune-rancon-dune-femme-pleine-de-force.jpg\" \/><\/p>\n<div id=\"divVideoPlayer\" class=\"video-sticky-box privacyAccettata\">\n<div class=\"video-sticky-box-inner\">\n<div class=\"video-sticky-box-frame-cont\">\n<div class=\"player player_video_rcs player_shortcode custom-video-sticky\" data-config=\"&quot;newspaper&quot;:&quot;corriere&quot;,&quot;uuid&quot;:&quot;52c777f2-5c12-11e8-82e5-88fb275b03b8&quot;,&quot;muted&quot;:true,&quot;blockAdv&quot;:false,&quot;ovlLogo&quot;:false,&quot;autoplay&quot;:true,&quot;watermark&quot;:false,&quot;sticky&quot;:&quot;targetClass&quot;:&quot;sticky-video&quot;,&quot;times&quot;:1,&quot;viewport&quot;:50,&quot;relocation&quot;:true,&quot;endlessSticky&quot;:true,&quot;initStickyNoAutoplay&quot;:true,&quot;tipo_video&quot;:&quot;pagina_video&quot;\">\n<div class=\"player_preview\">\n                                    <img decoding=\"async\" class=\"\" alt=\"Danse avec les stars : la valse de Cesare Bocci avec sa femme \u00e9meut tout le monde\" title=\"Danse avec les stars : la valse de Cesare Bocci avec sa femme \u00e9meut tout le monde\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2022\/11\/1667472385_20_Lhistoire-dune-rancon-dune-femme-pleine-de-force.jpg\" \/>                                    <span class=\"player_button play\" \/>\n                                <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<h2 class=\"p1\">Danseur pour <em>danser avec les \u00e9toiles<\/em><\/h2>\n<p class=\"p1\">De la mode \u00e0 la musique, puis le management et la passion de la peinture.  Jusqu&#8217;\u00e0 la danse.  Aujourd&#8217;hui, en effet, Ema Stokholma est au casting de l&#8217;\u00e9mission Rai men\u00e9e par Milly Carlucci.  Et l&#8217;histoire du DJ franco-italien revient faire la une des journaux.  Mais le pass\u00e9 est pass\u00e9.\n<\/p>\n<div class=\"runa-integration-newsletter-box\">\n<p>\n        <span>Recevez des nouvelles et des mises \u00e0 jour<\/span><br \/>\n        <span>au dernier<\/span><br \/>\n        <span>tendances beaut\u00e9<\/span><br \/>\n        <span>directement dans votre courrier<\/span>\n    <\/p>\n<\/div>\n<p class=\"p1\">E, interview\u00e9 par <a rel=\"nofollow noopener\" href=\"https:\/\/www.instagram.com\/p\/Ckd4lWrDOCn\/?hl=it\" target=\"_blank\" data-wpel-link=\"external\">hebdomadaire<em> Aujourd&#8217;hui<\/em>d\u00e9crit ainsi son pr\u00e9sent : \u00ab \u00catre c\u00e9libataire est la seule fa\u00e7on d&#8217;\u00eatre heureuse. <strong>Je n&#8217;ai besoin de rien, je suis ind\u00e9pendant,<\/strong> il m&#8217;est difficile de faire entrer quelqu&#8217;un dans ce paradis que je me suis construit, qui est ma vie \u00bb.<\/p>\n<p class=\"all-rights-reserved\">iO Donna \u00a9 REPRODUCTION R\u00c9SERV\u00c9E<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iodonna.it\/personaggi\/star-italiane\/2022\/11\/03\/ema-stokholma-infanzia-difficile-riscatto-italia-storia-dj-conduttrice\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-13<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0il n&#8217;avait que 15 ans Ema Stokholma (vrai nom Morwenn Mogu\u00e9rou) \u00e0 son arriv\u00e9e en Italie. Il avait quitt\u00e9 la France pour \u00e9chapper \u00e0 une vie de violence et d&#8217;insultes. Aujourd&#8217;hui on la conna\u00eet tous : DJ, animatrice radio et t\u00e9l\u00e9 et concurrente de la derni\u00e8re \u00e9dition de danser avec les \u00e9toiles. Mais derri\u00e8re le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":444917,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[1326,1711,1209,922,5180,18254],"class_list":["post-444916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-dune","tag-femme","tag-force","tag-lhistoire","tag-pleine","tag-rancon"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/444916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=444916"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/444916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/444917"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=444916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=444916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=444916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}