{"id":264353,"date":"2022-07-18T14:21:24","date_gmt":"2022-07-18T16:21:24","guid":{"rendered":"https:\/\/teknomers.com\/fr\/la-star-de-glee-a-pris-le-volant\/"},"modified":"2022-07-18T14:21:25","modified_gmt":"2022-07-18T16:21:25","slug":"la-star-de-glee-a-pris-le-volant","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/la-star-de-glee-a-pris-le-volant\/","title":{"rendered":"La star de Glee a pris le volant"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>L&#8217;acteur connu de la s\u00e9rie jeunesse est soup\u00e7onn\u00e9 de conduite en \u00e9tat d&#8217;\u00e9bri\u00e9t\u00e9.<\/p>\n<div role=\"button\">\n<div class=\"article-image-container\" style=\"height:;padding-bottom:60.9375%\"><img decoding=\"async\" class=\"image image-show\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2022\/07\/1658161284_571_La-star-de-Glee-a-pris-le-volant.jpg\" alt=\"Blake Jenner fait carri\u00e8re \u00e0 Hollywood depuis son plus jeune \u00e2ge.\" \/><\/div>\n<p><span class=\"caption-text\">Blake Jenner fait carri\u00e8re \u00e0 Hollywood depuis son plus jeune \u00e2ge.<!-- --> <\/span><span class=\"media-source\">AOP<\/span><\/p>\n<\/div>\n<div>\n<p class=\"paragraph\">Acteur de cin\u00e9ma <strong>Blake Jenner<\/strong>29 ans, a \u00e9t\u00e9 arr\u00eat\u00e9 dans le sud de la Californie, rapporte <a rel=\"nofollow noopener\" href=\"https:\/\/www.tmz.com\/2022\/07\/17\/glee-actor-blake-jenner-arrested-dui\/\" target=\"_blank\">TMZ<\/a>.  Jenner est soup\u00e7onn\u00e9 de conduite en \u00e9tat d&#8217;\u00e9bri\u00e9t\u00e9.<\/p>\n<p class=\"paragraph\">Selon le journal, l&#8217;acteur a \u00e9t\u00e9 arr\u00eat\u00e9 le 9 juillet.  La police a arr\u00eat\u00e9 Jenner pour ne pas s&#8217;\u00eatre arr\u00eat\u00e9 \u00e0 un feu rouge.  L&#8217;alcool\u00e9mie de Jenner a d\u00e9pass\u00e9 la limite l\u00e9gale.<\/p>\n<p class=\"paragraph\">L&#8217;incident s&#8217;est produit un peu apr\u00e8s minuit, mais Jenner a d\u00e9j\u00e0 \u00e9t\u00e9 lib\u00e9r\u00e9 dimanche matin contre une caution d&#8217;environ 5 000 euros.<\/p>\n<div class=\"article-image gallery center\" role=\"button\">\n<p><span class=\"caption-text\">Blake Jenner a pris le volant en Californie du Sud.<!-- --> <\/span><span class=\"media-source\">AOP<\/span><\/p>\n<\/div>\n<h3 class=\"subheadline\">Une grosse diff\u00e9rence<\/h3>\n<p class=\"paragraph\">Jenner s&#8217;est fait conna\u00eetre du grand public gr\u00e2ce \u00e0 la s\u00e9rie \u00e0 succ\u00e8s Glee.  Plus tard, il a \u00e9galement jou\u00e9 dans la s\u00e9rie Netflix What\/If.<\/p>\n<p class=\"paragraph\">En 2015, l&#8217;acteur a \u00e9pous\u00e9 sa co-star dans la s\u00e9rie Glee <strong>M\u00e9lissa Benoist<\/strong> avec.  Cependant, le couple a divorc\u00e9 l&#8217;ann\u00e9e suivante.<\/p>\n<p class=\"paragraph\">Quatre ans apr\u00e8s le mariage, Benoist a r\u00e9v\u00e9l\u00e9 sur Instagram avoir \u00e9t\u00e9 victime de violences conjugales.  L&#8217;actrice a racont\u00e9 comment son ex-amant avait \u00e9t\u00e9 jaloux.<\/p>\n<p class=\"paragraph\">&#8211; Il ne voulait pas que je fasse des sc\u00e8nes de baisers ou des sc\u00e8nes de flirt avec des hommes et c&#8217;\u00e9tait vraiment difficile.  &#8220;J&#8217;ai commenc\u00e9 \u00e0 refuser des auditions, des emplois et des amiti\u00e9s parce que je ne voulais pas lui faire de mal&#8221;, a d\u00e9clar\u00e9 Benoist dans la vid\u00e9o.<\/p>\n<p class=\"paragraph\">Si l&#8217;image n&#8217;est pas visible, vous pouvez la visualiser<a rel=\"nofollow noopener\" href=\"https:\/\/www.instagram.com\/p\/B5YXu8oHkzn\/?utm_source=ig_embed&amp;ig_rid=824cf45e-db99-4261-a838-424be74b80d2\" target=\"_blank\"> d&#8217;ici<\/a>.<\/p>\n<p class=\"paragraph\">Cependant, Benoist n&#8217;a pas mentionn\u00e9 directement Jenner par son nom.<\/p>\n<p class=\"paragraph\">En 2020, Jenner a admis avoir abus\u00e9 physiquement de son ex-femme et s&#8217;est excus\u00e9.<\/p>\n<p class=\"paragraph\">&#8211; Je n&#8217;arr\u00eaterai jamais de faire le travail n\u00e9cessaire pour devenir une meilleure personne dans tous les domaines de la vie.  Je vous souhaite, \u00e0 vous et \u00e0 votre famille, une bonne sant\u00e9, de la joie et de l&#8217;amour.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iltalehti.fi\/viihdeuutiset\/a\/3db34282-8a2b-47f2-8423-d556b591d503\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-50<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;acteur connu de la s\u00e9rie jeunesse est soup\u00e7onn\u00e9 de conduite en \u00e9tat d&#8217;\u00e9bri\u00e9t\u00e9. Blake Jenner fait carri\u00e8re \u00e0 Hollywood depuis son plus jeune \u00e2ge. AOP Acteur de cin\u00e9ma Blake Jenner29 ans, a \u00e9t\u00e9 arr\u00eat\u00e9 dans le sud de la Californie, rapporte TMZ. Jenner est soup\u00e7onn\u00e9 de conduite en \u00e9tat d&#8217;\u00e9bri\u00e9t\u00e9. Selon le journal, l&#8217;acteur a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":264354,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[12884,3248,11832,672,71062,885,3246,84739,5506,3564,888,12579],"class_list":["post-264353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-24-heures","tag-acteurs-theatre","tag-acteurs-de-cinema-et-de-television","tag-films","tag-glee","tag-la-tele","tag-medias-audiovisuels","tag-operations-cinematographiques-et-cinematographiques-et-video","tag-pris","tag-star","tag-television-et-films","tag-volant"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/264353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=264353"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/264353\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/264354"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=264353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=264353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=264353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}