{"id":188947,"date":"2022-06-07T19:46:01","date_gmt":"2022-06-07T21:46:01","guid":{"rendered":"https:\/\/teknomers.com\/fr\/litalie-celebre-sa-victoire-a-domicile-face-a-la-hongrie\/"},"modified":"2022-06-07T19:46:02","modified_gmt":"2022-06-07T21:46:02","slug":"litalie-celebre-sa-victoire-a-domicile-face-a-la-hongrie","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/litalie-celebre-sa-victoire-a-domicile-face-a-la-hongrie\/","title":{"rendered":"L&#8217;Italie c\u00e9l\u00e8bre sa victoire \u00e0 domicile face \u00e0 la Hongrie"},"content":{"rendered":"\n<div>\n<p>L&#8217;Italie, championne d&#8217;Europe de football, a remport\u00e9 sa premi\u00e8re Ligue des Nations et a pris la t\u00eate du Groupe 3.<\/p>\n<p>Apr\u00e8s le nul d&#8217;ouverture face \u00e0 l&#8217;Allemagne, la Squadra Azzurra a battu l&#8217;h\u00f4te hongrois 2-1 (2-0) \u00e0 Cesena.  Giacomo Raspadori (30&#8242;) a pris l&#8217;avantage m\u00e9rit\u00e9 d&#8217;une belle frappe du pied droit, Lorenzo Pellegrini (45&#8242;) a augment\u00e9 juste avant le coup de sifflet de la mi-temps.  Un but contre son camp de Gianluca Mancini (61e) a de nouveau provoqu\u00e9 la tension.<\/p>\n<p>Les Hongrois, qui avaient quatre joueurs de Bundesliga dans le onze de d\u00e9part \u00e0 Willi Orban, Dominik Szoboszlai (tous deux RB Leipzig), Roland Sallai (SC Freiburg) et Andras Sch\u00e4fer (Union Berlin), n&#8217;ont pas pu le faire apr\u00e8s leur premi\u00e8re victoire contre l&#8217;Angleterre ( 1-0) mettre un autre point d&#8217;exclamation.<\/p>\n<p>L&#8217;entra\u00eeneur italien Roberto Mancini s&#8217;est appuy\u00e9 sur des jeunes \u00e0 l&#8217;avant en Wilfried Gnonto, 18 ans, et Raspadori, 22 ans &#8211; et son \u00e9quipe est entr\u00e9e dans le match de mani\u00e8re houleuse.<\/p>\n<p>Mais ce n&#8217;est qu&#8217;\u00e0 la 21e minute que le gardien hongrois Denes Dibusz a \u00e9t\u00e9 s\u00e9rieusement mis \u00e0 l&#8217;\u00e9preuve par le d\u00e9fenseur central Mancini apr\u00e8s un corner.  A l&#8217;autre bout, le gardien italien Gianluigi Donnarumma a d\u00e9gag\u00e9 un tir bas dangereux de Sallai (26e) en corner.  Apr\u00e8s cela, Raspadori et Pellegrini ont donn\u00e9 \u00e0 l&#8217;\u00e9quipe italienne une avance rassurante \u00e0 la mi-temps.<\/p>\n<p>Apr\u00e8s la pause, l&#8217;\u00e9quipe italienne n&#8217;a pas r\u00e9ussi \u00e0 remonter t\u00f4t &#8211; un tir de Matteo Politano (55e) a touch\u00e9 la barre transversale.  Un peu plus tard, Mancini dirigeait malencontreusement un centre hongrois dans son propre but depuis la droite.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne4938813\/nations-league--italien-feiert-knappen-heimsieg-gegen-ungarn\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-8<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Italie, championne d&#8217;Europe de football, a remport\u00e9 sa premi\u00e8re Ligue des Nations et a pris la t\u00eate du Groupe 3. Apr\u00e8s le nul d&#8217;ouverture face \u00e0 l&#8217;Allemagne, la Squadra Azzurra a battu l&#8217;h\u00f4te hongrois 2-1 (2-0) \u00e0 Cesena. Giacomo Raspadori (30&#8242;) a pris l&#8217;avantage m\u00e9rit\u00e9 d&#8217;une belle frappe du pied droit, Lorenzo Pellegrini (45&#8242;) a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":188948,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[93,171,1006,91,28909,15825,360,38942,58203,2319,28910,2559],"class_list":["post-188947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-celebre","tag-domicile","tag-face","tag-football","tag-football-de-haut-niveau","tag-hongrie","tag-italie","tag-ligue-des-nations","tag-ligue-des-nations-a","tag-litalie","tag-sport-general","tag-victoire"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/188947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=188947"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/188947\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/188948"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=188947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=188947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=188947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}