{"id":181677,"date":"2022-06-03T21:28:59","date_gmt":"2022-06-03T23:28:59","guid":{"rendered":"https:\/\/teknomers.com\/fr\/hanovre-96-obtient-toni-stahl-comme-gardien-remplacant-vient-denergie-cottbus\/"},"modified":"2022-06-03T21:29:00","modified_gmt":"2022-06-03T23:29:00","slug":"hanovre-96-obtient-toni-stahl-comme-gardien-remplacant-vient-denergie-cottbus","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/hanovre-96-obtient-toni-stahl-comme-gardien-remplacant-vient-denergie-cottbus\/","title":{"rendered":"Hanovre 96 obtient Toni Stahl comme gardien rempla\u00e7ant: vient d&#8217;Energie Cottbus"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Le gardien vient d&#8217;Energie Cottbus <\/p>\n<p>Hanovre 96 poursuit la planification de l&#8217;\u00e9quipe pour la saison \u00e0 venir et a pr\u00e9sent\u00e9 la huiti\u00e8me signature externe vendredi soir, dont trois au cours des derni\u00e8res 24 heures.  Le gardien Toni Stahl arrive \u00e0 Maschsee gr\u00e2ce \u00e0 un transfert gratuit d&#8217;Energie Cottbus et a un contrat jusqu&#8217;au 30 juin 2024.<\/p>\n<p><\/p>\n<p>Le joueur de 22 ans vient de la jeunesse du RB Leipzig et a trouv\u00e9 son chemin vers Lausitz via le FC Fulham 2020.  La saison derni\u00e8re, il \u00e9tait un gardien r\u00e9gulier \u00e0 Cottbus et a gard\u00e9 13 draps propres en 34 matchs de championnat r\u00e9gional.  &#8220;Avec Toni Stahl, nous avons gagn\u00e9 un jeune gardien de but talentueux.  Il devrait grandir et m\u00fbrir aux c\u00f4t\u00e9s des gardiens les plus exp\u00e9riment\u00e9s.  Il a la t\u00eate claire et fera sa part chaque jour pour maintenir l&#8217;intensit\u00e9 et la qualit\u00e9 de l&#8217;entra\u00eenement des gardiens de but \u00e0 un niveau \u00e9lev\u00e9.  De plus, il aura certainement des entra\u00eenements de match chez les U23&#8221;, a d\u00e9clar\u00e9 le directeur sportif de 96, Marcus Mann.<\/p>\n<p><\/p>\n<p>Stahl est d\u00e9sormais le quatri\u00e8me gardien de l&#8217;\u00e9quipe de Basse-Saxe aux c\u00f4t\u00e9s de Ron-Robert Zieler (33 ans), Martin Hansen (32 ans) et Leo Weinkauf (25 ans), qui est revenu en pr\u00eat.  \u00ab Au cours des discussions, le concept souhait\u00e9 m&#8217;a \u00e9t\u00e9 expliqu\u00e9 de mani\u00e8re tr\u00e8s pr\u00e9cise et convaincante.  De plus, on m&#8217;a montr\u00e9 un r\u00f4le que je peux assumer, de sorte que la d\u00e9cision pour 96 n&#8217;a pas \u00e9t\u00e9 difficile pour moi.  Pour moi personnellement, d\u00e9m\u00e9nager \u00e0 Hanovre est la prochaine \u00e9tape logique.  Maintenant, il s&#8217;agit d&#8217;arriver le plus vite possible en ville et au club&#8221;, a d\u00e9clar\u00e9 le gardien.<\/p>\n<p><\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">Hanovre 96 a sign\u00e9 le gardien de but Toni <a rel=\"nofollow noopener\" href=\"https:\/\/twitter.com\/hashtag\/Stahl?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\">#Acier<\/a>.  Le joueur de 22 ans passe du FC Energie Cottbus \u00e0 Maschsee sur un transfert gratuit.  Accueil chaleureux! <a rel=\"nofollow noopener\" href=\"https:\/\/twitter.com\/hashtag\/H96?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\">#H96<\/a> <a rel=\"nofollow noopener\" href=\"https:\/\/twitter.com\/hashtag\/NiemalsAllein?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\">#Jamais seul<\/a> <a rel=\"nofollow\" href=\"https:\/\/t.co\/kTgpdVqSJ2\">https:\/\/t.co\/kTgpdVqSJ2<\/a><\/p>\n<p>\u2014 Hanovre 96 (@ Hanovre96) <a rel=\"nofollow noopener\" href=\"https:\/\/twitter.com\/Hannover96\/status\/1532777085135118343?ref_src=twsrc%5Etfw\" target=\"_blank\">3 juin 2022<\/a><\/p><\/blockquote>\n<p>\t\t\t\t\t\t\t<span><\/p>\n<p>\t\t\t\t\t\t\t\tVers la page d&#8217;accueil\t\t\t\t\t\t\t<\/span><br \/>\n                            <span class=\"icon-doppelpfeil-weiss\"> <\/span><\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.transfermarkt.de\/hannover-verpflichtet-stahl-8-neuzugang-soll-an-der-seite-von-zieler-amp-co-bdquo-wachsen-und-reifen-ldquo-\/view\/news\/405414\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-38<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le gardien vient d&#8217;Energie Cottbus Hanovre 96 poursuit la planification de l&#8217;\u00e9quipe pour la saison \u00e0 venir et a pr\u00e9sent\u00e9 la huiti\u00e8me signature externe vendredi soir, dont trois au cours des derni\u00e8res 24 heures. Le gardien Toni Stahl arrive \u00e0 Maschsee gr\u00e2ce \u00e0 un transfert gratuit d&#8217;Energie Cottbus et a un contrat jusqu&#8217;au 30 juin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":181678,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1622,1756,25375,4665,73635,1890,6512,7153,3537,8864,20909,17248,73636,9265],"class_list":["post-181677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-2e-bundesliga","tag-comme","tag-cottbus","tag-denergie","tag-fc-energie-cottbus","tag-gardien","tag-hanovre","tag-hanovre-96","tag-obtient","tag-remplacant","tag-stahl","tag-toni","tag-tony-steel","tag-vient"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/181677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=181677"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/181677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/181678"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=181677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=181677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=181677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}