{"id":1722836,"date":"2025-10-01T12:00:25","date_gmt":"2025-10-01T09:00:25","guid":{"rendered":"https:\/\/teknomers.com\/fr\/offraient-des-opportunites-dinvestissement-dans-des-actifs-inexistants-demantelement-dun-reseau-criminel-international-ayant-escroque-plus-de-102-millions-deuros\/"},"modified":"2025-10-01T12:00:31","modified_gmt":"2025-10-01T09:00:31","slug":"offraient-des-opportunites-dinvestissement-dans-des-actifs-inexistants-demantelement-dun-reseau-criminel-international-ayant-escroque-plus-de-102-millions-deuros","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/offraient-des-opportunites-dinvestissement-dans-des-actifs-inexistants-demantelement-dun-reseau-criminel-international-ayant-escroque-plus-de-102-millions-deuros\/","title":{"rendered":"Offraient des opportunit\u00e9s d&#8217;investissement dans des actifs inexistants : d\u00e9mant\u00e8lement d&#8217;un r\u00e9seau criminel international ayant escroqu\u00e9 plus de 102 millions d&#8217;euros."},"content":{"rendered":"\n<h2>D\u00e9mant\u00e8lement d&#8217;un r\u00e9seau criminel international<\/h2>\n<p>Agentes de la <strong>Polic\u00eda Nacional<\/strong> ont r\u00e9cemment dirig\u00e9 une op\u00e9ration majeure, coordonn\u00e9e par <strong>EUROJUST<\/strong>, avec le soutien d&#8217;<strong>EUROPOL<\/strong> et la participation des autorit\u00e9s de <strong>Portugal<\/strong>, <strong>Italie<\/strong>, <strong>Ruman\u00eda<\/strong> et <strong>Bulgarie<\/strong>. Cette op\u00e9ration a permis de d\u00e9manteler une <strong>r\u00e9seau criminel international<\/strong> ayant blanchi plus de <strong>102 millions d&#8217;euros<\/strong> issus d&#8217;escroqueries d&#8217;investissement en ligne. Parmi cette somme colossale, <strong>12,2 millions d&#8217;euros<\/strong> proviennent de victimes r\u00e9sidant en Espagne.<\/p>\n<h2>Origine de l&#8217;enqu\u00eate<\/h2>\n<p>L&#8217;enqu\u00eate a d\u00e9but\u00e9 en octobre 2022 suite \u00e0 une alerte des <strong>autorit\u00e9s lituaniennes<\/strong>, qui signal\u00e8rent l&#8217;utilisation d&#8217;une plateforme financi\u00e8re pour canaliser des fonds obtenus par le biais d&#8217;escroqueries. Cela a conduit \u00e0 la formation d&#8217;un <strong>\u00c9quipe Conjointe d&#8217;Investigation<\/strong> dirig\u00e9e par l&#8217;Espagne, avec l&#8217;appui de la Lituanie, et la participation ult\u00e9rieure du Portugal, de l&#8217;Italie, de la Roumanie et de la Bulgarie, le tout sous la coordination d&#8217;<strong>EUROJUST<\/strong> et le soutien analytique d&#8217;<strong>EUROPOL<\/strong>.<\/p>\n<h2>Fonctionnement de la escroquerie<\/h2>\n<p>Les investigations ont r\u00e9v\u00e9l\u00e9 que le r\u00e9seau criminel op\u00e9rait depuis 2019 \u00e0 travers des plateformes frauduleuses d&#8217;investissement, souvent appel\u00e9es des <strong>\u201cchiringuitos financiers\u201d<\/strong>. Selon la <strong>Polic\u00eda Nacional<\/strong>, ces op\u00e9rations ont caus\u00e9 de graves pr\u00e9judices \u00e0 des milliers de victimes dans plus de <strong>trente pays europ\u00e9ens<\/strong>.<\/p>\n<p>Leur modus operandi \u00e9tait relativement simple : attirer des investisseurs avec des sites web professionnels et des gestionnaires d&#8217;investissement fictifs en leur promettant des rendements <strong>irr\u00e9els<\/strong> en <strong>cryptomonnaies<\/strong>, devises ou produits technologiques.<\/p>\n<p>Pour ce faire, l&#8217;organisation employait des t\u00e9l\u00e9op\u00e9rateurs qui, <strong>sous une apparence de professionnalisme<\/strong>, gagnaient la confiance des victimes pour les inciter \u00e0 effectuer des transferts bancaires vers des comptes au nom de soci\u00e9t\u00e9s <strong>\u00e9cran<\/strong>. Ces soci\u00e9t\u00e9s, en r\u00e9alit\u00e9, n&#8217;avaient aucune activit\u00e9 \u00e9conomique r\u00e9elle et servaient uniquement d&#8217;interm\u00e9diaires pour recevoir des fonds de mani\u00e8re frauduleuse.<\/p>\n<h2>Transformation des fonds et arrestations<\/h2>\n<p>Une fois que l&#8217;organisation criminelle avait re\u00e7u les fonds, ceux-ci \u00e9taient imm\u00e9diatement fragment\u00e9s et envoy\u00e9s \u00e0 des <strong>\u00e9changes de cryptomonnaies<\/strong> o\u00f9 ils \u00e9taient convertis en actifs cryptographiques tels que le <strong>BTC<\/strong> et le <strong>USDT<\/strong>, puis transf\u00e9r\u00e9s vers des adresses opaques contr\u00f4l\u00e9es par le groupe lui-m\u00eame.<\/p>\n<p>L&#8217;affaire a atteint son paroxysme le 17 septembre 2025, lors d&#8217;une op\u00e9ration d&#8217;exploitation coordonn\u00e9e \u00e0 travers cinq pays. Cette action a abouti \u00e0 l&#8217;arrestation de <strong>six individus<\/strong> (trois en Espagne, un au Portugal, un en Bulgarie et un en Roumanie), ainsi qu&#8217;\u00e0 la r\u00e9alisation de cinq perquisitions r\u00e9sidentielle et soci\u00e9taires. Un des principaux suspects, r\u00e9sidant au Portugal, a \u00e9t\u00e9 localis\u00e9 \u00e0 <strong>Barcelone<\/strong> par les agents espagnols.<\/p>\n<div class=\"visual__image\">\n<picture><source  media=\"(min-width: 1000px)\"\/><source  media=\"(min-width: 768px)\"\/><source  media=\"(min-width: 580px)\"\/><source  media=\"(min-width: 350px)\"\/><source  media=\"(min-width: 80px)\"\/><\/picture><figcaption class=\"article-figcaption-img\">Les agents lors des perquisitions (Polic\u00eda Nacional)<\/figcaption><\/div>\n<p>En outre, une <strong>ordre international<\/strong> de d\u00e9tention a \u00e9t\u00e9 \u00e9mise contre un autre enqu\u00eateur qui n&#8217;a pas pu \u00eatre appr\u00e9hend\u00e9 en <strong>Italie<\/strong>. Lors des perquisitions, les forces de l&#8217;ordre ont saisi 10.700 euros en esp\u00e8ces, des cryptomonnaies d&#8217;une valeur approximative de <strong>80.000 euros<\/strong> et <strong>20.000 dollars<\/strong>, six lingots d&#8217;or, des pi\u00e8ces en argent et divers bijoux. De plus, 83 comptes bancaires ont \u00e9t\u00e9 gel\u00e9s en Espagne et dans d&#8217;autres pays europ\u00e9ens.<\/p>\n<h2>Impact \u00e9conomique des escroqueries<\/h2>\n<p>Le montant total des fonds fraud\u00e9s s&#8217;\u00e9l\u00e8ve \u00e0 <strong>102.908.705 euros<\/strong>, dont plus de <strong>12,2 millions d&#8217;euros<\/strong> proviennent de <strong>victimes r\u00e9sidant en Espagne<\/strong>. Ce chiffre est bas\u00e9 sur des mouvements bancaires v\u00e9rifi\u00e9s ainsi que sur la tra\u00e7abilit\u00e9 des <strong>criptoactifs<\/strong>. Cependant, il est estim\u00e9 que les pertes r\u00e9elles pourraient \u00eatre encore plus \u00e9lev\u00e9es, en raison des victimes qui n&#8217;ont pas signal\u00e9 ces escroqueries.<\/p>\n<p>La lutte contre ces op\u00e9rations criminelles met en lumi\u00e8re la n\u00e9cessit\u00e9 d&#8217;une coop\u00e9ration internationale et d&#8217;une vigilance accrue de la part des investisseurs. Les autorit\u00e9s encouragent toute personne soup\u00e7onnant une fraude d\u2019agir rapidement et de signaler les incidents aux forces de l&#8217;ordre.<\/p>\n<p><br \/>\n<br \/><a href=\"https:\/\/teknomers.com\/fr\/category\/finance\/\" rel=\"dofollow\">F1-ES<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9mant\u00e8lement d&#8217;un r\u00e9seau criminel international Agentes de la Polic\u00eda Nacional ont r\u00e9cemment dirig\u00e9 une op\u00e9ration majeure, coordonn\u00e9e par EUROJUST, avec le soutien d&#8217;EUROPOL et la participation des autorit\u00e9s de Portugal, Italie, Ruman\u00eda et Bulgarie. Cette op\u00e9ration a permis de d\u00e9manteler une r\u00e9seau criminel international ayant blanchi plus de 102 millions d&#8217;euros issus d&#8217;escroqueries d&#8217;investissement en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1722837,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[10224,13712,3222,429,15484,133,1559,23868,74,66006,14849,1838,1610,319067,7868,4810],"class_list":["post-1722836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-actifs","tag-ayant","tag-criminel","tag-dans","tag-demantelement","tag-des","tag-deuros","tag-dinvestissement","tag-dun","tag-escroque","tag-inexistants","tag-international","tag-millions","tag-offraient","tag-opportunites","tag-reseau"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1722836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1722836"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1722836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1722837"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1722836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1722836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1722836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}